{"id":11057,"date":"2023-11-09T13:43:59","date_gmt":"2023-11-09T16:43:59","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2023\/11\/09\/prefeitura-de-cuiab-cultura-parceira-da-9-edio-do-cuiab-open-2023\/"},"modified":"2023-11-09T13:43:59","modified_gmt":"2023-11-09T16:43:59","slug":"prefeitura-de-cuiab-cultura-parceira-da-9-edio-do-cuiab-open-2023","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2023\/11\/09\/prefeitura-de-cuiab-cultura-parceira-da-9-edio-do-cuiab-open-2023\/","title":{"rendered":"Prefeitura de Cuiab | Cultura parceira da 9 Edio do Cuiab Open 2023"},"content":{"rendered":"<p><\/p>\n<div id=\"texto\" style=\" width:100%\">\n<div itemprop=\"articleBody\" class=\"textBody\">\n<p>A 9\u00aa edi\u00e7\u00e3o do Cuiab\u00e1 Open 2023 \u00e9 um dos eventos mais aguardados pelos amantes do taekwondo e est\u00e1 marcada para os dias 18 e 19 de novembro. O Gin\u00e1sio Verdinho ser\u00e1 o palco deste encontro esportivo de alto n\u00edvel, proporcionando um ambiente prop\u00edcio para a exibi\u00e7\u00e3o de talento e determina\u00e7\u00e3o dos participantes.<\/p>\n<p>\u201cA Secretaria Municipal de Cultura, Esporte e Lazer se une como parceira nesta celebra\u00e7\u00e3o esportiva, promovendo o encontro entre a tradi\u00e7\u00e3o do esporte marcial e a riqueza cultural da regi\u00e3o. Ser\u00e1 uma grande competi\u00e7\u00e3o, com atletas renomados e promete intensa disputa no mundo do Taekwondo\u201d, disse o secret\u00e1rio municipal de Cultura, Esporte e Lazer, Alu\u00edzio Leite.<\/p>\n<p>O torneio contar\u00e1 com tr\u00eas categorias distintas: kyorug individual, poomsae e kyopa, prometendo um espet\u00e1culo de habilidade e t\u00e9cnica. Os atletas competir\u00e3o n\u00e3o apenas pela honra da vit\u00f3ria, mas tamb\u00e9m pela generosa premia\u00e7\u00e3o de R$ 1.000,00 para as duplas masculinas e femininas.<\/p>\n<p>\u201cO Cuiab\u00e1 Open 2023 representa n\u00e3o apenas uma oportunidade para os praticantes do taekwondo demonstrarem sua destreza no esporte, mas tamb\u00e9m uma celebra\u00e7\u00e3o da uni\u00e3o entre cultura e esporte, enriquecendo a experi\u00eancia para todos os envolvidos\u201d, declarou o respons\u00e1vel pelo o evento, Gr\u00e3o-Mestre Jefferson Souza, 7\u00b0 Dan de Taekwondo.<\/p>\n<p class=\"MsoNormal\">\u00a0\u201cN\u00e3o perca a chance de testemunhar a excel\u00eancia atl\u00e9tica e a riqueza cultural que o Cuiab\u00e1 Open 2023 tem a oferecer. Marque em seu calend\u00e1rio os dias 18 e 19 de novembro e junte-se a n\u00f3s nesta emocionante jornada esportiva\u201d, completou Jeferson Souza.<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A 9\u00aa edi\u00e7\u00e3o do Cuiab\u00e1 Open 2023 \u00e9 um dos eventos mais aguardados pelos amantes do taekwondo e est\u00e1 marcada para os dias 18 e 19 de novembro. O Gin\u00e1sio Verdinho ser\u00e1 o palco deste encontro esportivo de alto n\u00edvel, proporcionando um ambiente prop\u00edcio para a exibi\u00e7\u00e3o de talento e determina\u00e7\u00e3o dos participantes. \u201cA Secretaria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11057","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11057"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11057\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}