{"id":13850,"date":"2023-12-23T08:34:42","date_gmt":"2023-12-23T11:34:42","guid":{"rendered":"https:\/\/novasdodia.com.br\/?p=13850"},"modified":"2023-12-23T08:34:42","modified_gmt":"2023-12-23T11:34:42","slug":"vasco-vem-honrando-os-pagamentos-das-parcelas-da-compra-de-jair-netvasco-bola-rolando","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2023\/12\/23\/vasco-vem-honrando-os-pagamentos-das-parcelas-da-compra-de-jair-netvasco-bola-rolando\/","title":{"rendered":"Vasco vem honrando os pagamentos das parcelas da compra de Jair | NETVASCO &#8211; BOLA ROLANDO"},"content":{"rendered":"\n<p>Vasco vem honrando os pagamentos das parcelas da compra de Jair  \t\t\t\t\t\t                        S\u00e1bado, 23\/12\/2023  &#8211; 04:41                              \t\t\t\t\tLucas Tanaka @LucasTanaka  Alguns vasca\u00ednos perguntaram se o Vasco est\u00e1 em dia com o @Atletico por Jair. Apurei que sim, o Vasco est\u00e1 honrando seu compromisso.    Jair foi comprado por aprox. R$13 milh\u00f5es. Faltam 2 parcelas de R$3,32 milh\u00f5es a serem pagas em janeiro e abril de 2024.    \ud83d\udcf8Gilson Lobo    <\/p>\n<table>\n<tr>\n<td><a><\/a><\/td>\n<\/tr>\n<\/table>\n<p>    Fonte: X do jornalista Lucas Tanaka<\/p>\n<p>Fonte: <a>www.netvasco.com.br\/n\/327069\/vasco-vem-honrando-os-pagamentos-das-parcelas-da-compra-de-jair<\/a><\/p>\n<p>   \t\t\t\t\t\t\t  \t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\tCategoria<a>vasco<\/a>                        <\/p>\n<p>Fonte: <a href=\"\/\/bolarolando.com.br\/index.php\/2023\/12\/23\/vasco-vem-honrando-os-pagamentos-das-parcelas-da-compra-de-jair-netvasco\" title=\"bolarolando.com.br\/index.php\/2023\/12\/23\/vasco-vem-honrando-os-pagamentos-das-parcelas-da-compra-de-jair-netvasco\" target=\"_blank\" rel=\"bookmark noopener\"><cite>bolarolando.com.br\/index.php\/2023\/12\/23\/vasco-vem-honrando-os-pagamentos-das-parcelas-da-compra-de-jair-netvasco<\/cite><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vasco vem honrando os pagamentos das parcelas da compra de Jair S\u00e1bado, 23\/12\/2023 &#8211; 04:41 Lucas Tanaka @LucasTanaka Alguns vasca\u00ednos perguntaram se o Vasco est\u00e1 em dia com o @Atletico por Jair. Apurei que sim, o Vasco est\u00e1 honrando seu compromisso. Jair foi comprado por aprox. R$13 milh\u00f5es. Faltam 2 parcelas de R$3,32 milh\u00f5es a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-13850","post","type-post","status-publish","format-standard","hentry","category-futebol-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13850"}],"version-history":[{"count":1,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13850\/revisions"}],"predecessor-version":[{"id":13851,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13850\/revisions\/13851"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}