{"id":14220,"date":"2023-12-29T02:16:02","date_gmt":"2023-12-29T05:16:02","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2023\/12\/29\/prefeitura-de-sorocaba-homenageia-58-gcms-e-instrutores-da-escola-de-gestao-municipal-por-relevantes-servicos-prestados-noticias\/"},"modified":"2023-12-29T02:16:02","modified_gmt":"2023-12-29T05:16:02","slug":"prefeitura-de-sorocaba-homenageia-58-gcms-e-instrutores-da-escola-de-gestao-municipal-por-relevantes-servicos-prestados-noticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2023\/12\/29\/prefeitura-de-sorocaba-homenageia-58-gcms-e-instrutores-da-escola-de-gestao-municipal-por-relevantes-servicos-prestados-noticias\/","title":{"rendered":"Prefeitura de Sorocaba homenageia 58 GCMs e instrutores da Escola de Gest\u00e3o Municipal por relevantes servi\u00e7os prestados \u2013 Noticias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Fotos: Renata Giron\/Secom<\/p>\n<p>Por: Lu\u00eds Gustavo Adabro\/Secom<\/p>\n<p>A Prefeitura de Sorocaba, por meio da Secretaria de seguran\u00e7a Urbana (Sesu), realizou, na manh\u00e3 desta quinta-feira (28), uma homenagem a 58 integrantes da Guarda Civil Municipal (GCM) e da Escola de Gest\u00e3o P\u00fablico (EGP), pelos relevantes servi\u00e7os prestados ao Munic\u00edpio. A solenidade celebrou tamb\u00e9m os 36 anos da Corpora\u00e7\u00e3o, comemorados no dia 4 de dezembro. O evento aconteceu no audit\u00f3rio do Centro de Referencia em Educa\u00e7\u00e3o (CRE), no Jardim Saira.<\/p>\n<p>Na ocasi\u00e3o, foram entregues barretas comemorativas que marcam o cumprimento de 20 e 30 anos de servi\u00e7os prestados \u00e0 GCM; bras\u00e3o aos tr\u00eas melhores colocados no concurso interno de carreira da Corpora\u00e7\u00e3o, para GCMS de 1\u00aa Classe, Classe Especial e Classe Distinta; certificados de empenho e presteza, al\u00e9m de Medalha de Honra ao M\u00e9rito de 3\u00ba Grau, tamb\u00e9m por presta\u00e7\u00e3o de servi\u00e7o excepcional \u00e0 popula\u00e7\u00e3o de Sorocaba.<\/p>\n<p>\u201c\u00c9 com muito prazer que entregamos essas congratula\u00e7\u00f5es, inclusive, para GCMs que se destacaram durante a\u00e7\u00f5es no dia a dia, em que arriscaram a pr\u00f3pria vida em prol de outros e em favor da seguran\u00e7a dos sorocabanos. Esse \u00e9 um gesto de agradecimento ao trabalho de todos voc\u00eas\u201d, enalteceu o secret\u00e1rio de Gabinete Central (SGC), Jo\u00e3o Alberto Corr\u00eaa Maia, que representou o prefeito Rodrigo Manga, no evento.<\/p>\n<p>\u201cDurante a atual gest\u00e3o, realizamos o concurso para novos GCM, que h\u00e1 21 anos, n\u00e3o ocorria na cidade. Al\u00e9m disso, demos andamento em uma s\u00e9rie de projetos, como aquisi\u00e7\u00e3o de novos uniformes para os servidores da seguran\u00e7a p\u00fablica, sistema de \u2018muralha eletr\u00f4nica\u2019, totem de videomonitoramento e intensifica\u00e7\u00e3o nas a\u00e7\u00f5es de patrulhamento e opera\u00e7\u00f5es integradas com outras for\u00e7as de seguran\u00e7a. Por isso, temos muitos motivos para comemorar e agradecer a toda essa equipe\u201d, disse o secret\u00e1rio da Sesu, Alexandre Caixeiro.<\/p>\n<p>\u201cHoje \u00e9 dia de homenagear e agradecer a todos, indistintamente, que contribu\u00edram de alguma forma para o sucesso das a\u00e7\u00f5es da GCM. Vale citar, ainda, a conquista da reforma e instala\u00e7\u00e3o da base da Inspetoria de Opera\u00e7\u00f5es Especiais (IOPE), no Parque dos Espanh\u00f3is, e da nova Escola de Forma\u00e7\u00e3o, Aperfei\u00e7oamento e Especializa\u00e7\u00e3o (Efae) da GCM, al\u00e9m do nosso concurso interno de promo\u00e7\u00e3o, entre outras tantas iniciativas\u201d, acrescentou o comandante-geral da GCM de Sorocaba, Davi Dutra.<\/p>\n<p>Tamb\u00e9m estiveram presentes na solenidade os secret\u00e1rios municipais de Rela\u00e7\u00f5es do Trabalho e Qualifica\u00e7\u00e3o Profissional (Sert), Hudson Pessini, e de Esporte e Qualidade de Vida (Sequav), Vitor Hugo Tavares, mais o vereador Dylan Dantas.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fotos: Renata Giron\/Secom Por: Lu\u00eds Gustavo Adabro\/Secom A Prefeitura de Sorocaba, por meio da Secretaria de seguran\u00e7a Urbana (Sesu), realizou, na manh\u00e3 desta quinta-feira (28), uma homenagem a 58 integrantes da Guarda Civil Municipal (GCM) e da Escola de Gest\u00e3o P\u00fablico (EGP), pelos relevantes servi\u00e7os prestados ao Munic\u00edpio. A solenidade celebrou tamb\u00e9m os 36 anos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14220","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14220"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14220\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}