{"id":14469,"date":"2024-01-01T12:34:20","date_gmt":"2024-01-01T15:34:20","guid":{"rendered":"https:\/\/novasdodia.com.br\/?p=14469"},"modified":"2024-01-01T12:34:20","modified_gmt":"2024-01-01T15:34:20","slug":"pedrinho-assumira-a-presidencia-do-vasco-no-dia-22-01-confira-os-primeiros-desafios-netvasco-bola-rolando","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/01\/01\/pedrinho-assumira-a-presidencia-do-vasco-no-dia-22-01-confira-os-primeiros-desafios-netvasco-bola-rolando\/","title":{"rendered":"Pedrinho assumir\u00e1 a presid\u00eancia do Vasco no dia 22\/01; confira os primeiros desafios | NETVASCO &#8211; BOLA ROLANDO"},"content":{"rendered":"\n<p>Pedrinho assumir\u00e1 a presid\u00eancia do Vasco no dia 22\/01; confira os primeiros desafios  \t\t\t\t\t\t                        Segunda-feira, 01\/01\/2024  &#8211; 08:18                              \t\t\t\t\tO Vasco entra em 2024 com a expectativa de receber seu novo presidente. Eleito em novembro, Pedrinho assumir\u00e1 a presid\u00eancia do clube associativo em janeiro e ter\u00e1 tr\u00eas anos de desafios. A expectativa \u00e9 que a posse ocorra no dia 22.    A reformar de S\u00e3o Janu\u00e1rio talvez seja o maior desafio de Pedrinho no tri\u00eanio, mas ela n\u00e3o sair\u00e1 do papel nos pr\u00f3ximos meses. O entendimento \u00e9 que h\u00e1 assuntos mais urgentes a serem resolvidos de imediato, a partir da posse. S\u00e3o eles:        Eleito no dia 11 de novembro, Pedrinho e seus pares pouco puderam fazer at\u00e9 o momento, uma vez que ainda n\u00e3o est\u00e3o legitimamente no poder. O grupo priorizou nas \u00faltimas semanas o processo de transi\u00e7\u00e3o. Tem ocorrido frequentes reuni\u00f5es entre os grupos de trabalho com a atual diretoria de Jorge Salgado.    Apesar da abertura e da transpar\u00eancia do processo, o diagn\u00f3stico \u00e9 preocupante. O entendimento \u00e9 que o clube associativo n\u00e3o gera receitas atualmente e vai precisar de um choque de ordem imediato. Um bom exemplo \u00e9 a \u00e1rea de marketing. Pedrinho e seus pares decidiram mudar o perfil do novo VP ap\u00f3s os primeiros diagn\u00f3sticos. H\u00e1 consenso de que o clube associativo vai precisar de algu\u00e9m ligado \u00e0 \u00e1rea comercial para arrecadar receitas para a pasta.    &#8211; A quantidade de desafios ser\u00e1 gigante. A associa\u00e7\u00e3o n\u00e3o est\u00e1 saud\u00e1vel &ndash; disse ao ge um dirigente, que vem participando do processo de transi\u00e7\u00e3o.    A rela\u00e7\u00e3o com a SAF tamb\u00e9m \u00e9 apontada como um desafio. At\u00e9 o momento houve encontros cordiais, promessas de aproxima\u00e7\u00e3o e uni\u00e3o, mas pouca coisa na pr\u00e1tica, fora a ajuda para conseguir patroc\u00ednios para o futebol feminino e para as categorias de base. A expectativa \u00e9 que a rela\u00e7\u00e3o engrene, de fato, a partir da posse de Pedrinho.    Os contratos com a 777 Partners j\u00e1 foram enviados ao departamento jur\u00eddico da equipe de Pedrinho, mas as lideran\u00e7as da chapa ainda n\u00e3o tiveram acesso, devido a acordos de confidencialidade. Nos \u00faltimos dias os advogados ficaram debru\u00e7ados sobre os documentos para entender quest\u00f5es como propriedade de marcas do Vasco e direitos dos s\u00f3cios. A ideia \u00e9 entender os direitos e deveres da associa\u00e7\u00e3o, especialmente em &#8220;\u00e1reas cinzentas&#8221; dos contratos.    Pedrinho tamb\u00e9m espera contribuir com o planejamento do futebol. Houve conversas nesse sentido com o CEO L\u00facio Barbosa, mas ainda muito superficiais. O ex-jogador chegou a sugerir alguns nomes como o do diretor Rodrigo Caetano e do meia Gustavo Scarpa, mas os dois estar\u00e3o no Atl\u00e9tico-MG na pr\u00f3xima temporada.    Pedrinho sabe que a 777 tem o controle do futebol, mas entende que pode contribuir no planejamento.    &#8211; Apesar de dar algumas sugest\u00f5es, eu ainda n\u00e3o estou participando do planejamento de futebol, do planejamento esportivo &#8211; disse o ex-jogador, em v\u00eddeo divulgado antes do Natal em suas redes sociais.    Sobre a reforma de S\u00e3o Janu\u00e1rio, n\u00e3o h\u00e1 nada que o clube possa fazer nesse momento. Com o recesso da C\u00e2mera de Vereadores, a expectativa \u00e9 que o projeto de lei do Potencial Construtivo seja votado entre mar\u00e7o e maio.    <\/p>\n<table>\n<tr>\n<td><a>Pedrinho tomar\u00e1 posse neste m\u00eas, provavelmente no dia 22 &mdash; Foto: Andr\u00e9 Dur\u00e3o<\/a><\/td>\n<\/tr>\n<\/table>\n<p>    Fonte: ge<\/p>\n<p>Fonte: <a>www.netvasco.com.br\/n\/327533\/pedrinho-assumira-a-presidencia-do-vasco-no-dia-2201-confira-os-primeiros-desafios<\/a><\/p>\n<p>   \t\t\t\t\t\t\t  \t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\tCategoria<a>vasco<\/a>                        <\/p>\n<p>Fonte: <a href=\"\/\/bolarolando.com.br\/index.php\/2024\/01\/01\/pedrinho-assumira-a-presidencia-do-vasco-no-dia-22-01-confira-os-primeiros-desafios-netvasco\" title=\"bolarolando.com.br\/index.php\/2024\/01\/01\/pedrinho-assumira-a-presidencia-do-vasco-no-dia-22-01-confira-os-primeiros-desafios-netvasco\" target=\"_blank\" rel=\"bookmark noopener\"><cite>bolarolando.com.br\/index.php\/2024\/01\/01\/pedrinho-assumira-a-presidencia-do-vasco-no-dia-22-01-confira-os-primeiros-desafios-netvasco<\/cite><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pedrinho assumir\u00e1 a presid\u00eancia do Vasco no dia 22\/01; confira os primeiros desafios Segunda-feira, 01\/01\/2024 &#8211; 08:18 O Vasco entra em 2024 com a expectativa de receber seu novo presidente. Eleito em novembro, Pedrinho assumir\u00e1 a presid\u00eancia do clube associativo em janeiro e ter\u00e1 tr\u00eas anos de desafios. A expectativa \u00e9 que a posse ocorra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-14469","post","type-post","status-publish","format-standard","hentry","category-futebol-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14469"}],"version-history":[{"count":1,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14469\/revisions"}],"predecessor-version":[{"id":14470,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14469\/revisions\/14470"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}