{"id":14512,"date":"2024-01-02T05:53:57","date_gmt":"2024-01-02T08:53:57","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/01\/02\/secretaria-de-saude-celebra-a-chegada-dos-dois-primeiros-bebes-cariocas-de-2024-prefeitura-da-cidade-do-rio-de-janeiro\/"},"modified":"2024-01-02T05:53:57","modified_gmt":"2024-01-02T08:53:57","slug":"secretaria-de-saude-celebra-a-chegada-dos-dois-primeiros-bebes-cariocas-de-2024-prefeitura-da-cidade-do-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/01\/02\/secretaria-de-saude-celebra-a-chegada-dos-dois-primeiros-bebes-cariocas-de-2024-prefeitura-da-cidade-do-rio-de-janeiro\/","title":{"rendered":"Secretaria de Sa\u00fade celebra a chegada dos dois primeiros beb\u00eas cariocas de 2024 &#8211; Prefeitura da Cidade do Rio de Janeiro"},"content":{"rendered":"<p><\/p>\n<div id=\"main\">\n<div class=\"wrapper-breadcrumbs\" wp_automatic_readability=\"26.712292002147\">\n<div class=\"image-post\" wp_automatic_readability=\"32\">\n                     Pietro veio ao mundo no Hospital Municipal Albert Schweitzer &#8211; Prefeitura do Rio                  <\/div>\n<p>A disputa pelo t\u00edtulo de primeiro beb\u00ea do ano de 2024 foi acirrada em duas maternidades da Zona Oeste do Rio. De um lado, Elysa, que precisou de uma ajudinha para vir ao mundo, chegando pontualmente \u00e0 0h. Do outro, o Pietro, que imp\u00f4s a hora do seu nascimento e, de forma natural, chegou \u00e0 0h02 desta segunda-feira, dia primeiro de janeiro.<\/p>\n<p>Elysa nasceu de parto ces\u00e1rea, no Hospital Municipal Pedro II, com 2.550kg e 47cm. A mam\u00e3e Mayara e o papai Gilmar ficaram muito emocionados, e agradeceram o acolhimento e apoio da equipe do hospital na chegada da primeira filha do casal.<\/p>\n<p>J\u00e1 Pietro veio ao mundo no Hospital Municipal Albert Schweitzer, em Realengo, de parto natural nos primeiros minutos de 2024. Com 45 cm e 2.615kg, o beb\u00ea nasceu de uma gravidez planejada e \u00e9 o quarto filho do casal Dielen e R\u00f4mulo.<\/p>\n<p>Independentemente da forma que vieram ao mundo e dos minutos de diferen\u00e7a, a chegada ao t\u00edtulo de primeiro beb\u00ea carioca de 2024 \u00e9 compartilhada entre estes dois vencedores.<\/p>\n<p>\u00a0<\/p>\n<figure id=\"attachment_100453\" aria-describedby=\"caption-attachment-100453\" style=\"width: 884px\" class=\"wp-caption alignnone\"><figcaption id=\"caption-attachment-100453\" class=\"wp-caption-text\">Elysa nasceu exatamente \u00e0 0h desse dia 1\u00ba de janeiro \u2013 Prefeitura do Rio<\/figcaption><\/figure>\n<p>             <!-- Compartilhe ---><\/p>\n<p>\t\t\t <!-- TAGS --><\/p>\n<section class=\"category-tags\">\n<div class=\"marcacao-category\">\n<article class=\"category-post\">\n<p>Categoria: <\/p>\n<\/article>\n<li>1 de janeiro de 2024<\/li><\/div>\n<article class=\"tags\">\n\t\t\t\t\tMarca\u00e7\u00f5es: 2024 Beb\u00ea maternidade primeiro virada do ano<br \/><\/article>\n<\/section>\n<p>            <!-- Mais Not&iacute;cias --><\/p>\n<p>\t\t<!-- Conte&uacute;do SIDEBAR --><\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pietro veio ao mundo no Hospital Municipal Albert Schweitzer &#8211; Prefeitura do Rio A disputa pelo t\u00edtulo de primeiro beb\u00ea do ano de 2024 foi acirrada em duas maternidades da Zona Oeste do Rio. De um lado, Elysa, que precisou de uma ajudinha para vir ao mundo, chegando pontualmente \u00e0 0h. Do outro, o Pietro, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14512","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14512"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14512\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}