{"id":16416,"date":"2024-01-28T00:02:40","date_gmt":"2024-01-28T03:02:40","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/01\/28\/prefeitura-faz-1-843-atendimentos-em-acari-com-o-programa-favela-com-dignidade-prefeitura-da-cidade-do-rio-de-janeiro\/"},"modified":"2024-01-28T00:02:40","modified_gmt":"2024-01-28T03:02:40","slug":"prefeitura-faz-1-843-atendimentos-em-acari-com-o-programa-favela-com-dignidade-prefeitura-da-cidade-do-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/01\/28\/prefeitura-faz-1-843-atendimentos-em-acari-com-o-programa-favela-com-dignidade-prefeitura-da-cidade-do-rio-de-janeiro\/","title":{"rendered":"Prefeitura faz 1.843 atendimentos em Acari com o programa Favela com Dignidade &#8211; Prefeitura da Cidade do Rio de Janeiro"},"content":{"rendered":"<p><\/p>\n<div id=\"main\">\n<div class=\"wrapper-breadcrumbs\" wp_automatic_readability=\"71.907364038512\">\n<div class=\"image-post\" wp_automatic_readability=\"32\">\n                     O programa Favela com Dignidade fez mais de 1.800 atendimentos em Acari &#8211; Prefeitura do Rio                  <\/div>\n<p>A Prefeitura do Rio, por meio da Secretaria de A\u00e7\u00e3o Comunit\u00e1ria, levou neste s\u00e1bado (27\/1) o programa Favela com Dignidade a Acari e registrou 1.843 atendimentos diretos. A a\u00e7\u00e3o conjunta foi realizada na Associa\u00e7\u00e3o de Moradores do bairro da Zona Norte e teve a participa\u00e7\u00e3o de diversas secretarias e \u00f3rg\u00e3os p\u00fablicos do munic\u00edpio e do estado.<\/p>\n<blockquote wp_automatic_readability=\"15\">\n<p>\u2013 Essa edi\u00e7\u00e3o do Favela com Dignidade em Acari foi fundamental para complementar o trabalho que v\u00e1rios \u00f3rg\u00e3os da Prefeitura v\u00eam fazendo na\u00a0 regi\u00e3o, uma das mais afetadas pelas chuvas. Entre os servi\u00e7os mais procurados estavam inscri\u00e7\u00f5es para o Minha Casa, Minha Vida, vacina\u00e7\u00e3o, dicas sobre preven\u00e7\u00e3o de dengue,\u00a0 zika e chikungunya, isen\u00e7\u00e3o para a 1\u00aa e 2\u00aa vias da carteira de identidade e para a 2\u00aa via de certid\u00f5es \u2013 disse o secret\u00e1rio de A\u00e7\u00e3o Comunit\u00e1ria, Chiquinho Braz\u00e3o.<\/p>\n<\/blockquote>\n<p>Bruna Costa e sua cunhada, Gl\u00e1ucia Melo, foram em busca da segunda via de certid\u00f5es de nascimento e de casamento.<\/p>\n<blockquote wp_automatic_readability=\"8\">\n<p>\u2013 Perdemos tudo na enchente e, agora, vamos conseguir tirar gratuitamente a segunda via dos nossos documentos \u2013 comemorou Bruna.<\/p>\n<\/blockquote>\n<p>A a\u00e7\u00e3o integrada ofereceu ainda agendamento para o Cad\u00danico, atendimento\u00a0 sobre problemas de consumo, orienta\u00e7\u00f5es sobre matr\u00edculas escolares para 2024, servi\u00e7os de barbeiro e trancista, oficinas de tran\u00e7as e design de sobrancelha, dicas sobre os cursos para jovens, informa\u00e7\u00f5es sobre os direitos das pessoas com defici\u00eancia\u00a0 e\u00a0 orienta\u00e7\u00f5es sobre matr\u00edculas escolares para 2024,<\/p>\n<blockquote wp_automatic_readability=\"8\">\n<p>\u2013 A Secretaria de Educa\u00e7\u00e3o veio orientar a popula\u00e7\u00e3o sobre as matr\u00edculas do ano letivo 2024. Estamos com toda a Prefeitura unida para servir o povo de Acari \u2013 destacou o secret\u00e1rio de Educa\u00e7\u00e3o, Renan Ferreirinha.<\/p>\n<\/blockquote>\n<p>A microchipagem, vacina\u00e7\u00e3o antirr\u00e1bica e agendamento para castra\u00e7\u00e3o de c\u00e3es e gatos, oferecidos pela Secretaria de Prote\u00e7\u00e3o e Defesa dos Animais e pelo Instituto de Vigil\u00e2ncia Sanit\u00e1ria (Ivisa-Rio) tamb\u00e9m tiveram grande procura.<\/p>\n<blockquote wp_automatic_readability=\"9\">\n<p>\u2013 Aproveitei o Favela com Dignidade aqui perto da minha casa pra trazer meu cachorro a uma consulta com o veterin\u00e1rio, dar a vacina contra raiva e\u00a0 microchipar \u2013 comentou Andressa Vit\u00f3ria, que estava acompanhada da fam\u00edlia.<\/p>\n<\/blockquote>\n<p>Um dos momentos mais animados do evento foi um aul\u00e3o de zumba, promovido pela Secretaria de Esportes, para estimular a atividade f\u00edsica.<\/p>\n<p><strong>Programa visa facilitar acesso da popula\u00e7\u00e3o aos servi\u00e7os p\u00fablicos<\/strong><\/p>\n<p>O Favela com Dignidade tem por finalidade facilitar o acesso aos servi\u00e7os p\u00fablicos da\u00a0popula\u00e7\u00e3o que vive em locais com baixos \u00cdndices de Desenvolvimento Social, proporcionando melhores condi\u00e7\u00f5es de vida aos moradores. Implantado em 2021, a iniciativa est\u00e1 em sua 25\u00aa edi\u00e7\u00e3o e j\u00e1 realizou 36.423 atendimentos diretos.<\/p>\n<p>Participaram da a\u00e7\u00e3o em Acari as seguintes secretarias: Sa\u00fade, Assist\u00eancia Social, Prote\u00e7\u00e3o e Defesa dos Animais, Educa\u00e7\u00e3o, Esportes, Pessoa com Defici\u00eancia, Pol\u00edticas e Promo\u00e7\u00e3o da Mulher, Juventude Carioca e Conserva\u00e7\u00e3o, al\u00e9m da Vigil\u00e2ncia Sanit\u00e1ria, Procon Carioca, Comlurb, Rioluz, IplanRio, Detran e Funda\u00e7\u00e3o Le\u00e3o XIII.<\/p>\n<p>             <!-- Compartilhe ---><\/p>\n<p>\t\t\t <!-- TAGS --><\/p>\n<section class=\"category-tags\">\n<article class=\"tags\">\n\t\t\t\t\tMarca\u00e7\u00f5es: Acari atendimento Favela com Dignidade Prefeitura do Rio programa<br \/><\/article>\n<\/section>\n<p>            <!-- Mais Not&iacute;cias --><\/p>\n<p>\t\t<!-- Conte&uacute;do SIDEBAR --><\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O programa Favela com Dignidade fez mais de 1.800 atendimentos em Acari &#8211; Prefeitura do Rio A Prefeitura do Rio, por meio da Secretaria de A\u00e7\u00e3o Comunit\u00e1ria, levou neste s\u00e1bado (27\/1) o programa Favela com Dignidade a Acari e registrou 1.843 atendimentos diretos. A a\u00e7\u00e3o conjunta foi realizada na Associa\u00e7\u00e3o de Moradores do bairro da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16416","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16416"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16416\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}