{"id":16810,"date":"2024-02-02T15:53:34","date_gmt":"2024-02-02T18:53:34","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/02\/02\/prefeita-adriane-lopes-destaca-compromisso-oportunidades-e-conquistas-na-abertura-do-ano-legislativo-em-campo-grande-cgnoticias\/"},"modified":"2024-02-02T15:53:34","modified_gmt":"2024-02-02T18:53:34","slug":"prefeita-adriane-lopes-destaca-compromisso-oportunidades-e-conquistas-na-abertura-do-ano-legislativo-em-campo-grande-cgnoticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/02\/02\/prefeita-adriane-lopes-destaca-compromisso-oportunidades-e-conquistas-na-abertura-do-ano-legislativo-em-campo-grande-cgnoticias\/","title":{"rendered":"Prefeita Adriane Lopes destaca Compromisso, Oportunidades e Conquistas na abertura do Ano Legislativo em Campo Grande \u2013 CGNot\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Na abertura dos trabalhos do Ano Legislativo de 2024 na C\u00e2mara Municipal, da 11\u00aa Legislatura, a prefeita Adriane Lopes refor\u00e7ou o compromisso do Poder Executivo em trabalhar incansavelmente para servir a popula\u00e7\u00e3o e criar oportunidades para todos os moradores da cidade.<\/p>\n<p>\u201cCom muita resili\u00eancia, f\u00e9 e determina\u00e7\u00e3o, estamos resolvendo os problemas da cidade. Campo Grande \u00e9 uma cidade que se aproxima de 1 milh\u00e3o de habitantes e certamente tem problemas di\u00e1rios, mas o nosso papel enquanto prefeita e vereadores \u00e9 juntos buscarmos solu\u00e7\u00f5es. Somos poderes independentes sim, mas com o mesmo objetivo, fortalecer Campo Grande. Pensar Campo Grande para o futuro. A capital avan\u00e7a no crescimento e expans\u00e3o. A nossa cidade hoje \u00e9 a capital da Rota Bioce\u00e2nica e cresce todos os dias. \u00c9 a cidade onde 85% dos seus moradores est\u00e3o orgulhosos de viverem aqui\u201d, defendeu.<\/p>\n<p>A prefeita destacou o desenvolvimento econ\u00f4mico da capital como prioridade\u00a0 da administra\u00e7\u00e3o municipal.\u00a0\u201cEstamos organizando os processos internos da prefeitura e focados na busca de solu\u00e7\u00f5es. Nosso projeto priorit\u00e1rio dessa cidade \u00e9 o desenvolvimento econ\u00f4mico. E n\u00f3s vamos continuar. Estamos avan\u00e7ando, trabalhando com muita garra, determina\u00e7\u00e3o, e com muito foco. \u00a0Encontramos muitas dificuldades, mas n\u00e3o focamos nos problemas, mas nas solu\u00e7\u00f5es, junto com a nossa equipe, uma equipe aguerrida de secret\u00e1rios, secret\u00e1rios e servidores que trabalham em prol dessa cidade.\u201d<\/p>\n<p>Ao cumprimentar o presidente da C\u00e2mara Municipal, vereador Carl\u00e3o, e todos os vereadores presentes, a prefeita destacou a import\u00e2ncia da parceria entre o Executivo e o Legislativo para promover a\u00e7\u00f5es e leis em benef\u00edcio da popula\u00e7\u00e3o.<\/p>\n<p>A prefeita expressou sua gratid\u00e3o aos l\u00edderes e membros da C\u00e2mara Municipal, mencionando individualmente cada vereador.<\/p>\n<p>Em seu discurso, Adriane Lopes ressaltou a atua\u00e7\u00e3o conjunta com o Executivo Estadual e a bancada federal, agradecendo ao governador Eduardo Riedel e \u00e0 senadora Tereza Cristina pelos investimentos na capital.<\/p>\n<p>Em meio aos desafios enfrentados, o ano de 2023 trouxe consigo chuvas emergenciais que testaram a resili\u00eancia da cidade. A prefeita Adriane Lopes, ciente das adversidades, destacou a prontid\u00e3o da administra\u00e7\u00e3o em fornecer respostas r\u00e1pidas e efetivas para atender \u00e0s necessidades da popula\u00e7\u00e3o.<\/p>\n<p>Segundo a prefeita, essa resposta \u00e1gil e eficiente ressalta o empenho da administra\u00e7\u00e3o municipal em lidar proativamente com situa\u00e7\u00f5es desafiadoras, reafirmando o compromisso de enfrentar adversidades e seguir avan\u00e7ando na constru\u00e7\u00e3o de uma cidade mais resiliente e preparada para enfrentar os imprevistos da natureza.<\/p>\n<\/p>\n<p>Al\u00e9m dos desafios enfrentados, a prefeita Adriane Lopes enfatizou as conquistas significativas para Campo Grande durante o ano de 2023. Ao abordar as realiza\u00e7\u00f5es, ela destacou iniciativas importantes, como o programa \u201cTodos em A\u00e7\u00e3o\u201d, levando mais de 200 servi\u00e7os a todas as regi\u00f5es da cidade, e o \u201cGabinete Itinerante\u201d, que permite ouvir as demandas da popula\u00e7\u00e3o em seu pr\u00f3prio territ\u00f3rio.<\/p>\n<p>No \u00e2mbito da Educa\u00e7\u00e3o, Adriane Lopes tamb\u00e9m reiterou seu compromisso com o desenvolvimento cont\u00ednuo da cidade. Destacou projetos inovadores, como o \u201cJuntos Pela Escola\u201d, que visa revitalizar as 205 unidades escolares, promovendo ambientes prop\u00edcios ao aprendizado. \u201cE n\u00e3o \u00e9 apenas uma m\u00e3o de tinta que est\u00e1 sendo passada nos pr\u00e9dios, mas principalmente a garantia da acessibilidade, que foi deixada de lado com o passar do tempo nas nossas escolas.\u201d<\/p>\n<p>A prefeita ressaltou a expans\u00e3o de 6,6 mil vagas por meio da constru\u00e7\u00e3o de 166 novas salas de aula, atendendo \u00e0 crescente demanda da popula\u00e7\u00e3o. \u201cS\u00f3 no ano passado, apenas com organiza\u00e7\u00e3o e planejamento conseguimos colocar 3 mil novos alunos dentro das salas de aula, reduzindo o d\u00e9ficit, e seguimos avan\u00e7ando.\u201d<\/p>\n<p>Para 2024, a Prefeitura anunciou a instala\u00e7\u00e3o de ar-condicionado em todas as salas, aliada \u00e0 implementa\u00e7\u00e3o de placas de energia solar. Essas iniciativas, delineadas para este ano, prometem melhorar significativamente a infraestrutura e a qualidade do ensino na cidade.<\/p>\n<p>Adriane Lopes assegurou tamb\u00e9m a retomada das obras de unidades escolares. \u201cAssumimos a gest\u00e3o com obras de Emeis e escolas paralisadas h\u00e1 15 anos, isso \u00e9 inadmiss\u00edvel. Conseguimos destravar 9 delas trabalhando em parceria, que s\u00e3o fundamentais para que a capital cres\u00e7a e se desenvolva.\u201d<\/p>\n<p>A prefeita mencionou ainda que a cidade avan\u00e7a nos projetos de infraestrutura, pavimenta\u00e7\u00e3o e mobilidade urbana, demonstrando o compromisso em tornar Campo Grande uma cidade de pleno emprego, com oportunidades di\u00e1rias para seus habitantes.<\/p>\n<p>A pandemia teve como consequ\u00eancia a desist\u00eancia das empresas que executavam obras em nossa cidade. Grande parte delas entregaram as obras porque o valor dos insumos mudaram ap\u00f3s a pandemia. Nos deparamos com obras abandonadas e com planejamento e responsabilidade estamos avan\u00e7ando.<\/p>\n<p>Algumas das regi\u00f5es que receberam investimento s\u00e3o o Jockey Club, Nova lima, North Park, Nashville, Oliveira, Tr\u00eas Barras, Cafezais, entre outras.<\/p>\n<p>Na \u00e1rea de Sa\u00fade, destacou as revitaliza\u00e7\u00f5es simult\u00e2neas nas unidades de sa\u00fade. J\u00e1 s\u00e3o 30 unidades que receberam a melhoria desde o ano passado, melhorando o ambiente para os usu\u00e1rios do SUS e tamb\u00e9m para os servidores que atuam nesses locais.<\/p>\n<p>Ao encerrar, a prefeita refor\u00e7ou a import\u00e2ncia da democracia na C\u00e2mara Municipal, desejando a todos um ano de grandes conquistas, entregas e a\u00e7\u00f5es em prol de Campo Grande.<\/p>\n<p>\u201cMinha mensagem \u00e9 lembrar da import\u00e2ncia de trabalharmos unidos pelo bem comum de Campo Grande, respeitando sim os poderes, mas focados nas solu\u00e7\u00f5es. Um ter\u00e7o da popula\u00e7\u00e3o reside aqui e, com muito respeito a todos os setores e segmentos, teremos um ano de muito trabalho e de muitas conquistas para que a nossa capital seja protagonista do centro-oeste do Brasil.\u201d<\/p>\n<\/p>\n<\/div>\n<p><script async defer async defer src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=1#xfbml=1&#038;version=v3.2\" id='prefeitura-campogrande-script-facebook-sdk-js'><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na abertura dos trabalhos do Ano Legislativo de 2024 na C\u00e2mara Municipal, da 11\u00aa Legislatura, a prefeita Adriane Lopes refor\u00e7ou o compromisso do Poder Executivo em trabalhar incansavelmente para servir a popula\u00e7\u00e3o e criar oportunidades para todos os moradores da cidade. \u201cCom muita resili\u00eancia, f\u00e9 e determina\u00e7\u00e3o, estamos resolvendo os problemas da cidade. Campo Grande [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-16810","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16810"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16810\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}