{"id":18323,"date":"2024-02-26T04:19:58","date_gmt":"2024-02-26T07:19:58","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/02\/26\/agencia-minas-gerais-laboratorio-central-da-copasa-renova-acreditacao-do-inmetro\/"},"modified":"2024-02-26T04:19:58","modified_gmt":"2024-02-26T07:19:58","slug":"agencia-minas-gerais-laboratorio-central-da-copasa-renova-acreditacao-do-inmetro","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/02\/26\/agencia-minas-gerais-laboratorio-central-da-copasa-renova-acreditacao-do-inmetro\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Laborat\u00f3rio Central da Copasa renova Acredita\u00e7\u00e3o do Inmetro"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A qualidade dos processos de an\u00e1lises desenvolvidos pelo Laborat\u00f3rio Central da Copasa, para garantir as exig\u00eancias da vigil\u00e2ncia sanit\u00e1ria e os padr\u00f5es de potabilidade estabelecidos pela legisla\u00e7\u00e3o vigente, foi novamente atestada pelo Instituto Nacional de Metrologia, Qualidade e Tecnologia (Inmetro). A unidade que fica em Belo Horizonte recebeu, mais uma vez, a recomenda\u00e7\u00e3o da CGCRE (Coordena\u00e7\u00e3o Geral de Acredita\u00e7\u00e3o do Inmetro) para manuten\u00e7\u00e3o da acredita\u00e7\u00e3o na norma ABNT NBR ISO\/IEC 17025 de 70 par\u00e2metros f\u00edsico-qu\u00edmicos, hidrobiol\u00f3gicos, microbiol\u00f3gicos e org\u00e2nicos.<\/p>\n<p>Em dezembro do ano passado, o Laborat\u00f3rio Regional de Montes Claros recebeu a auditoria para reavalia\u00e7\u00e3o da acredita\u00e7\u00e3o e\u00a0aumento de escopo, que passou de 26 par\u00e2metros para 39, nas matrizes de \u00e1gua tratada, \u00e1gua bruta e efluentes. Al\u00e9m das unidades Central e Montes Claros, os demais laborat\u00f3rios regionais da Companhia possuem par\u00e2metros acreditados e passam por auditorias rotineiras.<\/p>\n<p>A Copasa acredita que investir na estrutura\u00e7\u00e3o dos laborat\u00f3rios, bem como na qualifica\u00e7\u00e3o da equipe t\u00e9cnica, \u00e9 fundamental para demonstrar sua capacidade de produzir resultados v\u00e1lidos e consistentes. Entre os anos 2021 a 2024, foram cerca de R$ 25 milh\u00f5es investidos na compra de equipamentos de \u00faltima gera\u00e7\u00e3o para atender integralmente ao plano de amostragem da Portaria GM\/MS N\u00ba 888, de 4 de maio de 2021, do Minist\u00e9rio da Sa\u00fade e outras legisla\u00e7\u00f5es.<\/p>\n<p>A Companhia realiza uma m\u00e9dia de 38 testes por minuto em amostras de \u00e1gua em sua rede de laborat\u00f3rios. Isso equivale a 20 milh\u00f5es de an\u00e1lises anuais onde s\u00e3o realizados ensaios diversos para avaliar par\u00e2metros f\u00edsico-qu\u00edmicos, microbiol\u00f3gicos, hidrobiol\u00f3gicos e radioativos. Todo esse trabalho \u00e9 realizado pelos laborat\u00f3rios localizados em Belo Horizonte, Montes Claros, Arax\u00e1, Varginha, Vale do A\u00e7o, Te\u00f3filo Otoni e ETE Arrudas, al\u00e9m de 17 laborat\u00f3rios distritais e centenas de laborat\u00f3rios locais.<\/p>\n<p>Os resultados das an\u00e1lises anuais s\u00e3o enviados para os clientes da Companhia, sendo eles usu\u00e1rios, \u00f3rg\u00e3os ambientais, secretarias de sa\u00fade, Minist\u00e9rio P\u00fablico e \u00f3rg\u00e3os de regula\u00e7\u00e3o &#8211; como a Arsae, al\u00e9m de serem disponibilizados nas contas de \u00e1gua e Relat\u00f3rio Anual de Qualidade.<\/p>\n<p>A Companhia entende que garantir o controle de qualidade da \u00e1gua \u00e9 fundamental para melhor atender seus clientes e, por isso mesmo, mant\u00e9m uma equipe t\u00e9cnica capacitada em sua rede laboratorial e profissionais capazes de produzir resultados v\u00e1lidos e consistentes.<\/p>\n<p>Cristina Apol\u00f4nia Santos, coordenadora do Laborat\u00f3rio Central da Copasa, destaca que a\u00a0acredita\u00e7\u00e3o dos laborat\u00f3rios d\u00e1 credibilidade ao processo de controle de qualidade da empresa e contribui para o prop\u00f3sito da Companhia de cuidar da \u00e1gua e gerar valor para as pessoas. \u201cOs laborat\u00f3rios est\u00e3o inseridos no contexto do controle de qualidade e fornecem informa\u00e7\u00f5es que garantem a atua\u00e7\u00e3o da empresa na manuten\u00e7\u00e3o dos padr\u00f5es de vigil\u00e2ncia sanit\u00e1ria e de potabilidade estabelecidos pelo Minist\u00e9rio da Sa\u00fade\u201d, esclareceu.<\/p>\n<p>Cristina explica que os laborat\u00f3rios da Companhia t\u00eam trabalhado para obter e manter a certifica\u00e7\u00e3o na ISO\/IEC 17025 \u2013 uma norma reconhecida mundialmente, que estabelece os requisitos para a compet\u00eancia t\u00e9cnica e a imparcialidade de laborat\u00f3rios de ensaio e calibra\u00e7\u00e3o. \u00a0\u201cA manuten\u00e7\u00e3o da acredita\u00e7\u00e3o representa o reconhecimento formal da compet\u00eancia do laborat\u00f3rio para desenvolver suas atividades de acordo com requisitos pr\u00e9-estabelecidos, e a adequa\u00e7\u00e3o do sistema de gest\u00e3o da qualidade\u201d, destacou Santos. \u00a0<\/p>\n<p>A coordenadora do laborat\u00f3rio Central da Copasa defende que uma das miss\u00f5es dos laborat\u00f3rios \u00e9 manter a acredita\u00e7\u00e3o e a amplia\u00e7\u00e3o do escopo com a inclus\u00e3o de mais par\u00e2metros reconhecidos pelo Inmetro. \u201cO empenho da rede Laboratorial da Copasa para a acredita\u00e7\u00e3o demonstra a busca constante pela excel\u00eancia e a confiabilidade dos resultados gerados pela rede que se traduzem em \u00e1gua de qualidade para os clientes\u201d, concluiu.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A qualidade dos processos de an\u00e1lises desenvolvidos pelo Laborat\u00f3rio Central da Copasa, para garantir as exig\u00eancias da vigil\u00e2ncia sanit\u00e1ria e os padr\u00f5es de potabilidade estabelecidos pela legisla\u00e7\u00e3o vigente, foi novamente atestada pelo Instituto Nacional de Metrologia, Qualidade e Tecnologia (Inmetro). A unidade que fica em Belo Horizonte recebeu, mais uma vez, a recomenda\u00e7\u00e3o da CGCRE [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18323","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=18323"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18323\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=18323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=18323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=18323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}