{"id":18326,"date":"2024-02-26T06:18:28","date_gmt":"2024-02-26T09:18:28","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/02\/26\/governo-investe-r-97-milhoes-em-reforma-e-ampliacao-de-escolas-em-tres-lagoas-e-dourados\/"},"modified":"2024-02-26T06:18:28","modified_gmt":"2024-02-26T09:18:28","slug":"governo-investe-r-97-milhoes-em-reforma-e-ampliacao-de-escolas-em-tres-lagoas-e-dourados","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/02\/26\/governo-investe-r-97-milhoes-em-reforma-e-ampliacao-de-escolas-em-tres-lagoas-e-dourados\/","title":{"rendered":"Governo investe R$ 9,7 milh\u00f5es em reforma e amplia\u00e7\u00e3o de escolas em Tr\u00eas Lagoas e Dourados"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Seguindo o protocolo de investimentos na moderniza\u00e7\u00e3o das unidades escolares da Rede Estadual de Ensino, o Governo do Estado anunciou, no Di\u00e1rio Oficial Eletr\u00f4nico n. 11.421, extratos de contrato para reforma e amplia\u00e7\u00e3o de duas unidades escolares da REE (Rede Estadual de Ensino) em Tr\u00eas Lagoas e Dourados, no valor global de R$ 9,7 milh\u00f5es.<\/p>\n<p>A Escola Estadual Ramona da Silva Pedroso, localizada na rua Adroaldo Pizzini, no jardim S\u00e3o Pedro, em Dourados passara pelo servi\u00e7o de reforma geral e amplia\u00e7\u00e3o, o valor do investimento ser\u00e1 no montante de R$ 7,8 milh\u00f5es.<\/p>\n<p>O diretor Fabio Almeida e Silva menciona que a reforma e amplia\u00e7\u00e3o vieram de de encontro com os anseios da comunidade escolar \u201cdurante muitos anos a institui\u00e7\u00e3o estava sofrendo com as avarias, intemp\u00e9ries e desgastes estruturais provocados pela pr\u00f3pria a\u00e7\u00e3o dos agentes naturais e o tempo cronol\u00f3gico. Com o advento da educa\u00e7\u00e3o em tempo integral, a reforma vir\u00e1 de encontro as necessidades de um ambiente estrutural que atende a atual conjuntura da unidade, sendo oportunizado aos estudantes desenvolver suas habilidades e compet\u00eancias perante uma institui\u00e7\u00e3o que contar\u00e1 com o que h\u00e1 de mais sofisticado e moderno no que tange a estrutura f\u00edsica tais como: laborat\u00f3rios, sala de tecnologia, salas climatizadas, refeit\u00f3rio, remodela\u00e7\u00e3o dos espa\u00e7os externos, al\u00e9m de outras tantas melhorias\u201d, salienta gestor.<\/p>\n<p>Situada no bairro Ipacara\u00ed, em Tr\u00eas Lagoas, a Escola Estadual Jo\u00e3o Dantas Filgueiras receber\u00e1 os sevi\u00e7os de amplia\u00e7\u00e3o dos blocos de salas de aula, ser\u00e3o R$ 1,9 milh\u00e3o investidos.<\/p>\n<p>A diretora Joana Darc Alves Palhota relata a import\u00e2ncia da amplia\u00e7\u00e3o \u201cnossa unidade sempre teve uma demanda de vagas para 6\u00ba ano do EF, pois recebemos muitos alunos das escolas municipais, com essa amplia\u00e7\u00e3o do n\u00famero de salas de aulas vir\u00e1 resolver a situa\u00e7\u00e3o atual de oferta de vagas. A reforma se faz importante e necess\u00e1ria para que possamos ofertar tamb\u00e9m uma melhor qualidade estrutural garantindo ensino aprendizagem e preparando melhor os nossos discentes para um futuro promissor\u201d, finaliza diretora.<\/p>\n<p>O prazo para as empresas respons\u00e1veis conclu\u00edrem os trabalhos nas unidades escolares em Dourados e Tr\u00eas Lagoas, ap\u00f3s a ordem de servi\u00e7o, ser\u00e1 de 365 dias consecutivos (1 ano), assim que for dada a ordem de servi\u00e7o pela SED (Secretaria Estadual de Educa\u00e7\u00e3o).<\/p>\n<p>Tamb\u00e9m no DOE de quinta-feira foi publicado os extratos de ordem de execu\u00e7\u00e3o de servi\u00e7os em duas unidades da REE em Campo Grande. Na Escola Estadual Dolor Ferreira de Andrade ser\u00e3o investidos R$ 300 mil nos servi\u00e7os de reforma na rede el\u00e9trica, ja na Escola Estadual Professor Severino de Queiroz ser\u00e3o realizados os servi\u00e7os de instala\u00e7\u00e3o de gerador fotovoltaico de 39,6KWP, No valor de R$ 311 mil. Prazo de entrega ser\u00e1 de 180\u00a0 dias consecutivos, contados da data do recebimento da ordem de execu\u00e7\u00e3o dos mesmos.<\/p>\n<p><em>Adersino Junior, Comunica\u00e7\u00e3o SED<\/em><br \/><em>Fotos: Arquivo escolar<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seguindo o protocolo de investimentos na moderniza\u00e7\u00e3o das unidades escolares da Rede Estadual de Ensino, o Governo do Estado anunciou, no Di\u00e1rio Oficial Eletr\u00f4nico n. 11.421, extratos de contrato para reforma e amplia\u00e7\u00e3o de duas unidades escolares da REE (Rede Estadual de Ensino) em Tr\u00eas Lagoas e Dourados, no valor global de R$ 9,7 milh\u00f5es. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-18326","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=18326"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18326\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=18326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=18326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=18326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}