{"id":18697,"date":"2024-03-03T07:58:01","date_gmt":"2024-03-03T10:58:01","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/03\/03\/com-pesca-liberada-imasul-alerta-sobre-regras-ambientais-nos-rios-de-ms-agencia-de-noticias-do-governo-de-mato-grosso-do-sul\/"},"modified":"2024-03-03T07:58:01","modified_gmt":"2024-03-03T10:58:01","slug":"com-pesca-liberada-imasul-alerta-sobre-regras-ambientais-nos-rios-de-ms-agencia-de-noticias-do-governo-de-mato-grosso-do-sul","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/03\/03\/com-pesca-liberada-imasul-alerta-sobre-regras-ambientais-nos-rios-de-ms-agencia-de-noticias-do-governo-de-mato-grosso-do-sul\/","title":{"rendered":"Com pesca liberada, Imasul alerta sobre regras ambientais nos rios de MS \u2013 Ag\u00eancia de Noticias do Governo de Mato Grosso do Sul"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A temporada de pesca profissional e amadora foi liberada em todos os rios de Mato Grosso do Sul. O Imasul (Instituto de Meio Ambiente de Mato Grosso do Sul) alerta os pescadores sobre as\u00a0 regras vigentes no Estado, como as cotas de pescado e o pesque e solte, al\u00e9m da necessidade da emiss\u00e3o da Carteira de Pescador Amador, licen\u00e7a ambiental para quem pratica a pesca amadora.<\/p>\n<p>A pesca esteve proibida no Estado desde o dia 5 de novembro do ano passado. \u00c9 o per\u00edodo de defeso, popularmente conhecido como Piracema, quando os cardumes sobem os rios em dire\u00e7\u00e3o \u00e0s cabeceiras para a desova e a reprodu\u00e7\u00e3o das esp\u00e9cies com qualidade.\u00a0<\/p>\n<p>Esse percurso \u00e9 longo e cheio de contratempos \u2013 como cachoeiras, corredeiras \u2013 o que faz com que os peixes protagonizem cenas incr\u00edveis de saltos e muito barulho. Vendo isso, os ind\u00edgenas chamaram o fen\u00f4meno de pira (peixe) cema (subida, sa\u00edda), dando origem ao nome do per\u00edodo.<\/p>\n<p>Desde 2020, s\u00f3 \u00e9 permitido ao pescador levar um exemplar de peixes de esp\u00e9cie nativa (por exemplo: pacu, pintado, cachara, ja\u00fa, dentre outros), al\u00e9m de cinco exemplares de piranhas, dentro das medidas m\u00ednima e m\u00e1xima. Se a esp\u00e9cie pescada estiver fora dos tamanhos permitidos, deve ser solta imediatamente no local.<\/p>\n<p>J\u00e1 a pesca do dourado estava proibida at\u00e9 dezembro de 2024, por for\u00e7a da Lei 5.231 de 10 de janeiro de 2019 estabelecendo morat\u00f3ria de cinco anos para captura da esp\u00e9cie. A Assembleia Legislativa aprecia mat\u00e9ria a respeito da dilata\u00e7\u00e3o dessa norma.<\/p>\n<figure id=\"attachment_446298\" aria-describedby=\"caption-attachment-446298\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><figcaption id=\"caption-attachment-446298\" class=\"wp-caption-text\"><em>Pescaria no Pantanal (Foto: Bruno Rezende)<\/em><\/figcaption><\/figure>\n<p>Com rela\u00e7\u00e3o \u00e0s esp\u00e9cies consideradas ex\u00f3ticas, n\u00e3o h\u00e1 cota exigida pelo \u00f3rg\u00e3o ambiental para pesca e transporte. O pescador pode levar qualquer quantidade que conseguir pescar. S\u00e3o consideradas ex\u00f3ticas (n\u00e3o pertencem \u00e0 fauna local) as esp\u00e9cies apaiari, bagre africano, black bass, carpa, peixe-rei, sardinha-de-\u00e1gua doce, til\u00e1pia, tucunar\u00e9, zoiudo, tambaqui.<\/p>\n<p>Nos rios Perdido, Abobral, Vermelho e Negro \u00e9 permitido a pesca somente no sistema de pesque e solte. No Rio Perdido, a medida abrange todo o seu percurso, compreendendo os munic\u00edpios de Bonito, Jardim, Caracol e Porto Murtinho; no Rio Abobral, em todo seu percurso, compreendendo os munic\u00edpios de Aquidauana e Corumb\u00e1; no Rio Vermelho, tamb\u00e9m em toda sua a extens\u00e3o no munic\u00edpio de Corumb\u00e1 e, por fim, no Rio Negro, no trecho situado na conflu\u00eancia do rio Negro com o c\u00f3rrego Lajeado, localizado pr\u00f3ximo \u00e0 cidade de Rio Negro, at\u00e9 o brejo existente no limite Oeste da Fazenda Fazendinha, no munic\u00edpio de Aquidauana.<\/p>\n<p>A PMA (Pol\u00edcia Militar Ambiental) estar\u00e1 com todo efetivo em opera\u00e7\u00f5es de fiscaliza\u00e7\u00e3o nos principais pontos de pesca do Estado para garantir que as regras ambientais sejam respeitadas.<\/p>\n<p>Para n\u00e3o restar d\u00favidas quanto ao que pode e o que n\u00e3o pode ser utilizado, o Imasul e a PMA prepararam uma\u00a0<span style=\"color: #0000ff;\">Cartilha do Pescador<\/span>.<\/p>\n<p>Para emitir a Licen\u00e7a Digital de Pesca o interessado deve acessar o site do Imasul no\u00a0<span style=\"color: #0000ff;\">NESSE\u00a0link<\/span> ou pelo aplicativo MS Digital dispon\u00edvel nas lojas de Android e iOS.<\/p>\n<p><em>Jo\u00e3o Prestes, Comunica\u00e7\u00e3o Semadesc\/MS<br \/>Foto da capa: VisitMS<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A temporada de pesca profissional e amadora foi liberada em todos os rios de Mato Grosso do Sul. O Imasul (Instituto de Meio Ambiente de Mato Grosso do Sul) alerta os pescadores sobre as\u00a0 regras vigentes no Estado, como as cotas de pescado e o pesque e solte, al\u00e9m da necessidade da emiss\u00e3o da Carteira [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-18697","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=18697"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18697\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=18697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=18697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=18697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}