{"id":18842,"date":"2024-03-05T18:08:00","date_gmt":"2024-03-05T21:08:00","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/03\/05\/fac-realiza-a-11a-edicao-do-drive-thru-da-reciclagem-de-14-a-16-de-marco-cgnoticias\/"},"modified":"2024-03-05T18:08:00","modified_gmt":"2024-03-05T21:08:00","slug":"fac-realiza-a-11a-edicao-do-drive-thru-da-reciclagem-de-14-a-16-de-marco-cgnoticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/03\/05\/fac-realiza-a-11a-edicao-do-drive-thru-da-reciclagem-de-14-a-16-de-marco-cgnoticias\/","title":{"rendered":"FAC realiza a 11\u00aa edi\u00e7\u00e3o do Drive-Thru da Reciclagem de 14 a 16 de mar\u00e7o \u2013 CGNot\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A Prefeitura de Campo Grande, por meio do Fundo de Apoio \u00e0 Comunidade (FAC), em parceria com a Du Bem Sustent\u00e1vel, realiza de 14 a 16 de mar\u00e7o, das 9h \u00e0s 18h, o 11\u00ba Drive-Thru da Reciclagem \u2013<br \/>Sustentabilidade, Educa\u00e7\u00e3o, Cultura e Neg\u00f3cio. O foco da a\u00e7\u00e3o \u00e9 conscientizar a popula\u00e7\u00e3o para o descarte correto dos res\u00edduos e informar sobre pr\u00e1ticas sustent\u00e1veis e reciclagem. Como na \u00faltima edi\u00e7\u00e3o, o evento acontece nos Altos da Avenida Afonso Pena, no estacionamento ao lado do Bioparque Pantanal.<\/p>\n<p>Os condutores podem entrar com o ve\u00edculo e fazer o descarte correto sem descer do ve\u00edculo e, durante os tr\u00eas dias de evento, ser\u00e1 poss\u00edvel descartar materiais como papel, papel\u00e3o, pl\u00e1stico, garrafa pet, vidro, \u00f3leo de cozinha usado, sucata de a\u00e7o, ferro, eletr\u00f4nicos, tecido, banner, medicamento vencido, ra\u00e7\u00e3o, acess\u00f3rio e medicamento para pet, al\u00e9m de l\u00e2mpada, pilha, bateria, entre outros.<\/p>\n<p>Para a coordenadora-geral do FAC, Adir Diniz, o Drive-Thru da Reciclagem mostra a import\u00e2ncia das pr\u00e1ticas sustent\u00e1veis em todos os segmentos. \u201cAlinhado com os valores do FAC, o Drive-Thru promove o empreendedorismo social, fomenta a educa\u00e7\u00e3o ambiental atrav\u00e9s do descarte e desapego, al\u00e9m de contribuir com a economia circular. Como consequ\u00eancia, mostramos que as pr\u00e1ticas sustent\u00e1veis trazem sa\u00fade e bem-estar ao cidad\u00e3o\u201d, reitera.<\/p>\n<p>O complexo montado para o evento tamb\u00e9m contar\u00e1 com ambiente destinado \u00e0 capta\u00e7\u00e3o de doa\u00e7\u00f5es. Podem ser doadas pe\u00e7as de roupas, cal\u00e7ados, alimentos n\u00e3o-perec\u00edveis e tudo que estiver em boas condi\u00e7\u00f5es de uso. O material arrecadado ser\u00e1 repassado \u00e0s fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade social assistidas pelo FAC.<\/p>\n<p>A programa\u00e7\u00e3o conta com uma s\u00e9rie de atividades educativas e culturais, atra\u00e7\u00f5es musicais, teatro para as crian\u00e7as, oficinas, ambiente de leitura e oferta de mudas de \u00e1rvores frut\u00edferas \u00e0s pessoas que realizarem o descarte correto dos materiais.<\/p>\n<p>Roberta Queiroz, coordenadora de projetos do FAC, relembra que a prefeitura de Campo Grande realizou a primeira edi\u00e7\u00e3o do Drive-Thru da Reciclagem em 2020, e desde ent\u00e3o, o evento foi abra\u00e7ado pela popula\u00e7\u00e3o, que contribui cada vez mais para pr\u00e1ticas sustent\u00e1veis. \u201cA mudan\u00e7a de comportamento individual \u00e9 crucial para o sucesso do processo de reciclagem. Isso implica\u00a0 compreender o descarte apropriado, familiarizar-se com a ind\u00fastria de reciclagem e compreender o ciclo de vida dos materiais reaproveitados. Nesse contexto, a prefeitura se mobilizou, coordenando esfor\u00e7os com empresas privadas, organiza\u00e7\u00f5es n\u00e3o-governamentais e volunt\u00e1rios para garantir o \u00eaxito cont\u00ednuo do Drive-thru.\u201d<\/p>\n<p><strong>Edi\u00e7\u00f5es anteriores<\/strong><\/p>\n<p>Desde a primeira edi\u00e7\u00e3o, realizada em outubro de 2020 durante a pandemia de Covid-19, j\u00e1 foram coletadas 45 toneladas de materiais recicl\u00e1veis e mais de 1,6 bilh\u00f5es de litros de \u00e1gua preservados<br \/>Apenas na \u00faltima edi\u00e7\u00e3o realizada entre os dias 19 a 21 de outubro de 2023, resultou na preserva\u00e7\u00e3o de cerca de 36 milh\u00f5es de litros de \u00e1gua por meio do descarte correto de 75 quilos de medicamentos e 87 litros de \u00f3leo de cozinha usado.<\/p>\n<p>O descarte de vidro somou 880 quilos. Entre papel e papel\u00e3o, o montante somou aproximadamente uma tonelada. J\u00e1 a sucata de ferro e latinhas totalizaram 125 quilos de descarte. Garrafas pet, pl\u00e1sticos e derivados contabilizaram 270 quilos. Entre pilhas, baterias e l\u00e2mpadas somaram-se 240 quilos de descarte.<\/p>\n<p>Adubos org\u00e2nicos produzidos na Unidade T\u00e9cnica de Agricultura Urbana (UTA\/FAC) tamb\u00e9m foram distribu\u00eddos para quem realizou o descarte correto de materiais. De acordo com a Embaixadora do Instituto Lixo Zero Brasil em Mato Grosso do Sul e gestora do evento juntamente com o FAC, Ana Cristina Franzoloso, o intuito Drive-Thru da Reciclagem \u00e9 fortalecer a ideia do descarte correto como in\u00edcio da log\u00edstica reversa de economia circular.<\/p>\n<p>\u201cAtrav\u00e9s da Prefeitura de Campo Grande e do FAC com o apoio oficial que sempre aconteceu nas 10 edi\u00e7\u00f5es anteriores, conseguimos mais de 45 toneladas de recicl\u00e1veis, mais de 12 mil mudas foram doadas. A proposta desta edi\u00e7\u00e3o \u00e9 de que as cidades inteligentes sejam sustent\u00e1veis e estaremos l\u00e1 para mostrar que precisamos de todos juntos em prol da qualidade de vida no planeta\u201d, ressaltou Franzoloso.<\/p>\n<p><strong>Objetivos de Desenvolvimento Sustent\u00e1vel (ODS)<\/strong><\/p>\n<p>Em 2017, Campo Grande aderiu a Agenda 2030 para o Desenvolvimento Sustent\u00e1vel da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas, subscrita pela Rep\u00fablica Federativa do Brasil, que visa promover mudan\u00e7as positivas no mundo do futuro. Esses objetivos representam planos que todos os Estados-membros da ONU devem seguir para atingir algumas metas. Dentre elas destacam-se: erradica\u00e7\u00e3o da pobreza,<br \/>promo\u00e7\u00e3o da prosperidade e bem-estar geral, prote\u00e7\u00e3o do meio ambiente e mitiga\u00e7\u00e3o das mudan\u00e7as clim\u00e1ticas.<\/p>\n<p>A 11\u00aa edi\u00e7\u00e3o do Drive-Thru da Reciclagem contempla a meta 4 (Educa\u00e7\u00e3o de qualidade: essencial a promo\u00e7\u00e3o de uma educa\u00e7\u00e3o inclusiva, igualit\u00e1ria e baseada nos princ\u00edpios de direitos humanos e desenvolvimento sustent\u00e1vel); a meta 5 (Igualdade de g\u00eanero); a meta 6 (\u00c1gua pot\u00e1vel e saneamento: assegurar a disponibilidade e gest\u00e3o sustent\u00e1vel da \u00e1gua e saneamento para todas e todos), meta 11 (Cidades e Comunidades Sustent\u00e1veis) e a meta 12 (Consumo e produ\u00e7\u00e3o respons\u00e1veis: assegurar padr\u00f5es de produ\u00e7\u00e3o e de consumo sustent\u00e1veis).<\/p>\n<p>Tamb\u00e9m ser\u00e1 contemplada a meta 15, que tem como objetivo proteger, recuperar e promover o uso sustent\u00e1vel dos ecossistemas terrestres, gerir de forma sustent\u00e1vel as florestas, combater a desertifica\u00e7\u00e3o, deter e reverter a degrada\u00e7\u00e3o da terra e deter a perda de biodiversidade. Ao todo, s\u00e3o 17 objetivos que comp\u00f5em os ODS atualmente.<\/p>\n<p><strong>Servi\u00e7o:<\/strong><br \/>11\u00b0 Drive-Thru da Reciclagem<br \/>Local: Estacionamento ao lado do Bioparque Pantanal, Altos da Avenida Afonso Pena<br \/>Data: 14 a 16 de mar\u00e7o<br \/>Hor\u00e1rio: 9h \u00e0s 18h<br \/>Informa\u00e7\u00f5es: 2020-1361<br \/>Para mais informa\u00e7\u00f5es: 2020-1361 ou pelas redes sociais do FAC @fac.pmc\/ e do<br \/>Drive-Thru da Reciclagem @drivethrudareciclagem<\/p>\n<\/div>\n<p><script async defer async defer src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=1#xfbml=1&#038;version=v3.2\" id='prefeitura-campogrande-script-facebook-sdk-js'><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Campo Grande, por meio do Fundo de Apoio \u00e0 Comunidade (FAC), em parceria com a Du Bem Sustent\u00e1vel, realiza de 14 a 16 de mar\u00e7o, das 9h \u00e0s 18h, o 11\u00ba Drive-Thru da Reciclagem \u2013Sustentabilidade, Educa\u00e7\u00e3o, Cultura e Neg\u00f3cio. O foco da a\u00e7\u00e3o \u00e9 conscientizar a popula\u00e7\u00e3o para o descarte correto dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-18842","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=18842"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18842\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=18842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=18842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=18842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}