{"id":20562,"date":"2024-04-03T15:56:56","date_gmt":"2024-04-03T18:56:56","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/04\/03\/com-apoio-do-governo-de-ms-campo-grande-recebe-a-supercopa-feminina-de-futsal-agencia-de-noticias-do-governo-de-mato-grosso-do-sul\/"},"modified":"2024-04-03T15:56:56","modified_gmt":"2024-04-03T18:56:56","slug":"com-apoio-do-governo-de-ms-campo-grande-recebe-a-supercopa-feminina-de-futsal-agencia-de-noticias-do-governo-de-mato-grosso-do-sul","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/04\/03\/com-apoio-do-governo-de-ms-campo-grande-recebe-a-supercopa-feminina-de-futsal-agencia-de-noticias-do-governo-de-mato-grosso-do-sul\/","title":{"rendered":"Com apoio do Governo de MS, Campo Grande recebe a Supercopa Feminina de Futsal \u2013 Ag\u00eancia de Noticias do Governo de Mato Grosso do Sul"},"content":{"rendered":"<p><\/p>\n<div>\n<p><span style=\"font-weight: 400;\">Envolvendo as principais equipes do pa\u00eds, a sexta edi\u00e7\u00e3o da Supercopa Feminina de Futsal ser\u00e1 sediada em Campo Grande. A competi\u00e7\u00e3o, que classifica o campe\u00e3o para a Libertadores 2024, come\u00e7a nesta quarta-feira (3) e segue at\u00e9 domingo (7). <\/span><span style=\"font-weight: 400;\">As partidas acontecem no Gin\u00e1sio Poliesportivo Avelino dos Reis, o Guanandiz\u00e3o, com entrada gratuita.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A Supercopa \u00e9 organizada pela CBFS (Confedera\u00e7\u00e3o Brasileira de Futebol de Sal\u00e3o), com parceria local da FFSMS (Federa\u00e7\u00e3o de Futebol de Sal\u00e3o de Mato Grosso do Sul). O campeonato conta com apoio do Governo de Mato Grosso do Sul, por meio da Setesc (Secretaria de Estado de Turismo, Esporte e Cultura) e Fundesporte (Funda\u00e7\u00e3o de Desporto e Lazer de Mato Grosso do Sul). Para o evento foi destinado <\/span><span style=\"font-weight: 400;\">R$ 258,6 mil do FIE (Fundo de Investimentos Esportivos).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O torneio re\u00fane clubes de topo do cen\u00e1rio do futsal nacional, dos estados de Santa Catarina, Paran\u00e1, S\u00e3o Paulo e Mato Grosso do Sul. Ao todo, de acordo com a CBFS, v\u00e3o participar da Supercopa 132 atletas e cerca de<\/span><span style=\"font-weight: 400;\"> 6,5 mil telespectadores acompanhar\u00e3o as partidas pelas plataformas digitais.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mato Grosso do Sul ser\u00e1 representado pela Serc\/UCDB (Sociedade Esportiva Recreativa Chapad\u00e3o\/Universidade Cat\u00f3lica Dom Bosco), que est\u00e1 no Grupo A. O confronto de estreia ser\u00e1 na quinta-feira (4), \u00e0s 18 horas (hor\u00e1rio de MS), contra as Leoas da Serra (SC). O grupo tem ainda Stein Cascavel (PR), atual campe\u00e3o da Libertadores. A chave B \u00e9 composta por Female (SC), Londrina (PR) e Tabo\u00e3o (SP) fecham o Grupo B.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cA Supercopa feminina <\/span><span style=\"font-weight: 400;\">\u00e9 uma competi\u00e7\u00e3o de alto padr\u00e3o, com as equipes que se destacaram na \u00faltima Ta\u00e7a Brasil de Clubes e v\u00e3o garantir vaga na Copa Libertadores da Am\u00e9rica.<\/span> <span style=\"font-weight: 400;\">\u00c9 um privil\u00e9gio para a Fundesporte poder fazer parte disso, esperamos que os sul-mato-grossenses prestigiem os jogos\u201d, frisa o diretor-presidente da Fundesporte, Herculano Borges.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para o secret\u00e1rio de Estado de Turismo, Esporte e Cultura, Marcelo Ferreira Miranda, Mato Grosso do Sul j\u00e1 se consolidou como uma das casas do futsal brasileiro. \u201cAl\u00e9m de termos equipes de alto n\u00edvel, como a Serc\/UCDB, que nos representa nessa edi\u00e7\u00e3o e participou da Liga Feminina de Futsal no ano passado, Mato Grosso do Sul vem recebendo competi\u00e7\u00f5es de grande magnitude nos \u00faltimos anos. \u00c9 com satisfa\u00e7\u00e3o que recebemos a Supercopa e quem ganha s\u00e3o os espectadores, que ter\u00e3o o prazer de acompanhar grandes partidas no Guanandiz\u00e3o\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os jogos ser\u00e3o transmitidos pelo canal oficial da CBFS TV no YouTube <\/span><span style=\"color: #0000ff;\"><b>(clique aqui para acessar)<\/b><\/span><span style=\"font-weight: 400;\"> e pelo SporTV. A cerim\u00f4nia de abertura da Supercopa Feminina acontece nesta quarta-feira (3), \u00e0s 18 horas. Para quem quiser acompanhar presencialmente, a entrada no Guanandiz\u00e3o \u00e9 gratuita.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Confira as partidas da fase classificat\u00f3ria, com hor\u00e1rio no fuso de Mato Grosso do Sul:<\/span><\/p>\n<p><b>1\u00aa rodada (3 de abril)<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">17h \u2013 Tabo\u00e3o (SP) x Londrina (PR)<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">18h \u2013 Stein (PR) x Leoas da Serra (SC)<\/span><\/li>\n<\/ul>\n<p><b>2\u00aa rodada (4 de abril)<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">16h \u2013 Londrina (PR) x Female (SC)<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">18h \u2013 Serc\/UCDB (MS) x Leoas da Serra (SC)<\/span><\/li>\n<\/ul>\n<p><b>3\u00aa rodada (5 de abril)<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">16h \u2013 Female (SC) x Tabo\u00e3o (SP)<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">18<\/span><span style=\"font-weight: 400;\">h \u2013 Serc\/UCDB (MS) x Stein (PR)<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">As semifinais ser\u00e3o disputadas a partir de s\u00e1bado (6), \u00e0s 15h. A final ser\u00e1 no domingo (7), \u00e0s 9h30. O campe\u00e3o da Supercopa garante a vaga brasileira na Libertadores Feminina de Futsal, maior competi\u00e7\u00e3o interclubes da Am\u00e9rica do Sul.<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Bel Manvailer, Comunica\u00e7\u00e3o Fundesporte<br \/><\/span><\/i><i><span style=\"font-weight: 400;\">Lucas Castro, Comunica\u00e7\u00e3o Setesc<br \/><\/span><\/i><i><span style=\"font-weight: 400;\">Foto: Maur\u00edcio Moreira\/CBFS (arquivo)<\/span><\/i><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Envolvendo as principais equipes do pa\u00eds, a sexta edi\u00e7\u00e3o da Supercopa Feminina de Futsal ser\u00e1 sediada em Campo Grande. A competi\u00e7\u00e3o, que classifica o campe\u00e3o para a Libertadores 2024, come\u00e7a nesta quarta-feira (3) e segue at\u00e9 domingo (7). As partidas acontecem no Gin\u00e1sio Poliesportivo Avelino dos Reis, o Guanandiz\u00e3o, com entrada gratuita.\u00a0 A Supercopa \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-20562","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=20562"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20562\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=20562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=20562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=20562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}