{"id":23121,"date":"2024-06-06T09:22:55","date_gmt":"2024-06-06T12:22:55","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/06\/06\/aviso-de-licitacao-pregao-eletronico-no-13-2024-registro-de-precos-para-aquisicao-de-materiais-de-expediente-para-atender-a-demanda-do-municipio-prefeitura-municipal-de-bonito\/"},"modified":"2024-06-06T09:22:55","modified_gmt":"2024-06-06T12:22:55","slug":"aviso-de-licitacao-pregao-eletronico-no-13-2024-registro-de-precos-para-aquisicao-de-materiais-de-expediente-para-atender-a-demanda-do-municipio-prefeitura-municipal-de-bonito","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/06\/06\/aviso-de-licitacao-pregao-eletronico-no-13-2024-registro-de-precos-para-aquisicao-de-materiais-de-expediente-para-atender-a-demanda-do-municipio-prefeitura-municipal-de-bonito\/","title":{"rendered":"AVISO DE LICITA\u00c7\u00c3O PREG\u00c3O ELETR\u00d4NICO N\u00ba. 13\/2024 &#8211; REGISTRO DE PRE\u00c7OS PARA AQUISI\u00c7\u00c3O DE MATERIAIS DE EXPEDIENTE PARA ATENDER A DEMANDA DO MUNIC\u00cdPIO. &#8211; Prefeitura Municipal de Bonito"},"content":{"rendered":"<p><\/p>\n<div data-td-block-uid=\"tdi_64\">\n<div class=\"tdb-block-inner td-fix-index\">\n<h5 class=\"wp-block-heading\">O MUNIC\u00cdPIO DE BONITO\/MS, atrav\u00e9s da Secretaria Municipal de Administra\u00e7\u00e3o e Finan\u00e7as, torna p\u00fablico a abertura da Licita\u00e7\u00e3o, na Modalidade Preg\u00e3o Eletr\u00f4nico, que ser\u00e1 regida pela Lei Federal n\u00ba. 14.133, de 01 de abril de 2021, pelo Decreto Municipal n\u00ba. 229\/2023 e Decreto Municipal n\u00ba. 15 de 05 de fevereiro de 2024, que regulamenta as contrata\u00e7\u00f5es pelo Sistema de Registro de Pre\u00e7os, subsidiariamente pela Lei Complementar n\u00ba. 123\/2006 e suas altera\u00e7\u00f5es, conforme adiante especificada:<\/h5>\n<p><strong>OBJETO:<\/strong> Registro de Pre\u00e7os para aquisi\u00e7\u00e3o de materiais de expediente para atender a demanda do Munic\u00edpio.<\/p>\n<p><strong>ABERTURA DA SESS\u00c3O:<\/strong> 20 de junho de 2024.<\/p>\n<p><strong>HORAS: <\/strong>09h00min.(Hor\u00e1rio de Bras\u00edlia).<\/p>\n<h5 class=\"wp-block-heading\">LOCAL: Plataforma BLL, por meio do site www.bll.org.br<\/h5>\n<h5 class=\"wp-block-heading\">RETIRADA DO EDITAL: O edital com os dados completos encontra-se dispon\u00edvel aos interessados no endere\u00e7o acima especificado e no site da Prefeitura Municipal www.bonito.ms.gov.br, gratuitamente.<\/h5>\n<p>Bonito\/MS, 05 de junho de 2024.<\/p>\n<p>Assinado na Autoriza\u00e7\u00e3o<\/p>\n<p>Edilberto Cruz Gon\u00e7alves<\/p>\n<p>Secret\u00e1rio Municipal de Administra\u00e7\u00e3o e Finan\u00e7as.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O MUNIC\u00cdPIO DE BONITO\/MS, atrav\u00e9s da Secretaria Municipal de Administra\u00e7\u00e3o e Finan\u00e7as, torna p\u00fablico a abertura da Licita\u00e7\u00e3o, na Modalidade Preg\u00e3o Eletr\u00f4nico, que ser\u00e1 regida pela Lei Federal n\u00ba. 14.133, de 01 de abril de 2021, pelo Decreto Municipal n\u00ba. 229\/2023 e Decreto Municipal n\u00ba. 15 de 05 de fevereiro de 2024, que regulamenta as [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-23121","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23121"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23121\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}