{"id":23348,"date":"2024-06-10T14:12:51","date_gmt":"2024-06-10T17:12:51","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/06\/10\/sancionada-lei-que-assegura-ao-consumidor-informacoes-sobre-servicos-bancarios-gratuitos-agencia-de-noticias-do-governo-de-mato-grosso-do-sul\/"},"modified":"2024-06-10T14:12:51","modified_gmt":"2024-06-10T17:12:51","slug":"sancionada-lei-que-assegura-ao-consumidor-informacoes-sobre-servicos-bancarios-gratuitos-agencia-de-noticias-do-governo-de-mato-grosso-do-sul","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/06\/10\/sancionada-lei-que-assegura-ao-consumidor-informacoes-sobre-servicos-bancarios-gratuitos-agencia-de-noticias-do-governo-de-mato-grosso-do-sul\/","title":{"rendered":"Sancionada lei que assegura ao consumidor informa\u00e7\u00f5es sobre servi\u00e7os banc\u00e1rios gratuitos \u2013 Ag\u00eancia de Noticias do Governo de Mato Grosso do Sul"},"content":{"rendered":"<p><\/p>\n<div id=\"post-479120\">\n<div class=\"text-center\"><\/div>\n<div class=\"entry\">\n<p>O governador Eduardo Riedel sancionou a lei estadual que assegura ao consumidor informa\u00e7\u00f5es sobre servi\u00e7os banc\u00e1rios gratuitos. O objetivo \u00e9 dar mais transpar\u00eancia e prote\u00e7\u00e3o ao cidad\u00e3o. A nova legisla\u00e7\u00e3o entrou em vigor nesta segunda-feira (10), com a publica\u00e7\u00e3o no Di\u00e1rio Oficial do Estado.<\/p>\n<p>De autoria do deputado estadual Gerson Claro, a lei prev\u00ea que as institui\u00e7\u00f5es financeiras banc\u00e1rias e demais entidades autorizadas devem informar de forma clara e objetivo a exist\u00eancia de servi\u00e7os gratuitos na hora que o consumidor abrir uma conta (banc\u00e1ria).<\/p>\n<p>Caso o consumidor queira contratar servi\u00e7os diferenciados, a institui\u00e7\u00f5es financeiras devem informar o valor da tarifa, bem como as condi\u00e7\u00f5es de utiliza\u00e7\u00e3o e pagamento. A omiss\u00e3o ou falta de comunica\u00e7\u00e3o adequada sobre o pacote b\u00e1sico gratuito constitui uma viola\u00e7\u00e3o dos direitos do consumidor.<\/p>\n<p>A nova lei se aplica \u00e0s institui\u00e7\u00f5es financeiras banc\u00e1rias e \u00e0s demais entidades autorizadas a funcionar pelo Banco Central do Brasil, em Mato Grosso do Sul. A medida visa garantir que todos os indiv\u00edduos que tenham acesso a estes servi\u00e7os gratuitos, sem imposi\u00e7\u00e3o de tarifas abusivas.<\/p>\n<p>Na justificativa do projeto se reconhece que os bancos t\u00eam o direito de cobrar pelos servi\u00e7os que ultrapassarem as cotas m\u00ednimas gratuitas, bem como por servi\u00e7os adicionais que desejem oferecer.<\/p>\n<p>\u201cNo entanto, \u00e9 fundamental garantir que essas cobran\u00e7as sejam transparentes, justas e devidamente informadas aos consumidores, evitando abusos e garantindo a prote\u00e7\u00e3o dos direitos no setor banc\u00e1rio. A lei busca estabelecer uma prote\u00e7\u00e3o legal aos consumidores, assegurando a gratuidade de servi\u00e7os banc\u00e1rios essenciais e promovendo a inclus\u00e3o financeira da popula\u00e7\u00e3o\u201d.<\/p>\n<p><em>Leonardo Rocha, Comunica\u00e7\u00e3o do Governo de MS<\/em><br \/><em>Foto: Edemir Rodrigues\/Arquivo<\/em><\/p>\n<p>\u00a0<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O governador Eduardo Riedel sancionou a lei estadual que assegura ao consumidor informa\u00e7\u00f5es sobre servi\u00e7os banc\u00e1rios gratuitos. O objetivo \u00e9 dar mais transpar\u00eancia e prote\u00e7\u00e3o ao cidad\u00e3o. A nova legisla\u00e7\u00e3o entrou em vigor nesta segunda-feira (10), com a publica\u00e7\u00e3o no Di\u00e1rio Oficial do Estado. De autoria do deputado estadual Gerson Claro, a lei prev\u00ea que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-23348","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23348"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23348\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}