{"id":23483,"date":"2024-06-12T18:03:37","date_gmt":"2024-06-12T21:03:37","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/06\/12\/museu-recebe-oficina-de-elaboracao-de-projetos-para-o-fmc\/"},"modified":"2024-06-12T18:03:37","modified_gmt":"2024-06-12T21:03:37","slug":"museu-recebe-oficina-de-elaboracao-de-projetos-para-o-fmc","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/06\/12\/museu-recebe-oficina-de-elaboracao-de-projetos-para-o-fmc\/","title":{"rendered":"Museu recebe oficina de Elabora\u00e7\u00e3o de Projetos para o FMC"},"content":{"rendered":"<p><\/p>\n<div>\n<p><b>Jo\u00e3o Paulo Sardinha<\/b><br \/>&#13;<br \/>\n&#13;<br \/>\n                <span style=\"font-weight: bold;\">Funda\u00e7\u00e3o Cultural Cassiano Ricardo<\/span><\/p>\n<p><em>*Colaborou o estagi\u00e1rio Vin\u00edcius Fr\u00f3es<\/em><\/p>\n<p>O Museu Municipal de S\u00e3o Jos\u00e9 dos Campos, na regi\u00e3o central de S\u00e3o Jos\u00e9 dos Campos, recebe, entre os dias 17 e 20 de junho, uma oficina gratuita sobre a elabora\u00e7\u00e3o de projetos para o FMC (Fundo Municipal de Cultura).<\/p>\n<p>Ser\u00e3o disponibilizadas turmas em dois hor\u00e1rios, das 15h30 \u00e0s 18h e das 19h \u00e0s 21h30, ambas com 25 vagas. Os interessados devem realizar a inscri\u00e7\u00e3o pelo aplicativo S\u00e3o Jos\u00e9 Viva.<\/p>\n<p>Durante os encontros, os participantes aprender\u00e3o sobre os conceitos da elabora\u00e7\u00e3o de projetos culturais, como fazer propostas, planejamento t\u00e9cnico e divulga\u00e7\u00e3o, al\u00e9m de observa\u00e7\u00f5es sobre a execu\u00e7\u00e3o, gest\u00e3o e presta\u00e7\u00e3o de contas de projetos culturais para o Fundo Municipal de Cultura.<\/p>\n<p>Tamb\u00e9m ter\u00e3o a oportunidade de exercitar na pr\u00e1tica os conte\u00fados aprendidos, por meio de exerc\u00edcios, para os quais recomenda-se que os participantes tragam material para anota\u00e7\u00f5es.<\/p>\n<p><span class=\"intertitulo\">Sobre a orientadora<\/span><\/p>\n<p>Luciana Machado conta com uma carreira s\u00f3lida desenvolvida em diversas facetas do setor desde a d\u00e9cada de 90. Atualmente, \u00e9 Diretora-Executiva da empresa Asas Arte &amp; Tecnologia, onde coordena projetos art\u00edsticos em multilinguagens e desenvolve iniciativas inovadoras no \u00e2mbito da Economia da Cultura e Ind\u00fastrias Criativas.<\/p>\n<p><span class=\"intertitulo\">Plant\u00f5es de tira-d\u00favidas<\/span><\/p>\n<p>Dos dias 24 a 28 de junho, os alunos da oficina ter\u00e3o prioridade nos plant\u00f5es de d\u00favidas que ser\u00e3o oferecidos pelo FMC. Os atendimentos ocorrer\u00e3o de forma individualizada, com dura\u00e7\u00e3o de 30 minutos, por meio de plataforma Meet.<\/p>\n<p>Os hor\u00e1rios disponibilizados ser\u00e3o das 9h \u00e0s 12h e das 14h \u00e0s 17h, mas \u00e9 necess\u00e1rio reservar previamente o atendimento, por meio dos telefones: (12) 3924-7338 \/ 3924-7345<\/p>\n<p><span class=\"intertitulo\">Servi\u00e7o<\/span><\/p>\n<p><strong>Museu Municipal<br \/><\/strong>Endere\u00e7o: Pra\u00e7a Afonso Pena, 29 &#8211; Centro<\/p>\n<p>&#13;<br \/>\n                        <strong>MAIS NOT\u00cdCIAS<\/strong><br \/>&#13;<br \/>\n                        Funda\u00e7\u00e3o Cultural Cassiano Ricardo&#13;\n                    <\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jo\u00e3o Paulo Sardinha&#13; &#13; Funda\u00e7\u00e3o Cultural Cassiano Ricardo *Colaborou o estagi\u00e1rio Vin\u00edcius Fr\u00f3es O Museu Municipal de S\u00e3o Jos\u00e9 dos Campos, na regi\u00e3o central de S\u00e3o Jos\u00e9 dos Campos, recebe, entre os dias 17 e 20 de junho, uma oficina gratuita sobre a elabora\u00e7\u00e3o de projetos para o FMC (Fundo Municipal de Cultura). Ser\u00e3o disponibilizadas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-23483","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23483"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23483\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}