{"id":25835,"date":"2024-08-08T09:52:23","date_gmt":"2024-08-08T12:52:23","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/08\/08\/agencia-minas-gerais-vice-governador-destaca-atuacao-do-ministerio-publico-de-minas-gerais-durante-congresso-estadual-da-entidade\/"},"modified":"2024-08-08T09:52:23","modified_gmt":"2024-08-08T12:52:23","slug":"agencia-minas-gerais-vice-governador-destaca-atuacao-do-ministerio-publico-de-minas-gerais-durante-congresso-estadual-da-entidade","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/08\/08\/agencia-minas-gerais-vice-governador-destaca-atuacao-do-ministerio-publico-de-minas-gerais-durante-congresso-estadual-da-entidade\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Vice-governador destaca atua\u00e7\u00e3o do Minist\u00e9rio P\u00fablico de Minas Gerais durante Congresso Estadual da entidade"},"content":{"rendered":"<p><\/p>\n<div>\n<p>O vice-governador Professor Mateus participou, nessa quarta-feira (7\/8), em Belo Horizonte, da abertura do 15\u00ba Congresso Estadual do Minist\u00e9rio P\u00fablico de Minas Gerais, promovido pela Associa\u00e7\u00e3o Mineira do Minist\u00e9rio P\u00fablico (AMMP).<\/p>\n<p>O evento ter\u00e1 dura\u00e7\u00e3o de tr\u00eas dias, com uma programa\u00e7\u00e3o composta por paineis, palestras e apresenta\u00e7\u00f5es de teses envolvendo a tem\u00e1tica \u201cMinist\u00e9rio P\u00fablico: por uma atua\u00e7\u00e3o resolutiva\u201d.<\/p>\n<p>O congresso foi aberto com a palestra magna do vice-governador Professor Mateus, que destacou o perfil do Minist\u00e9rio P\u00fablico mineiro, que se destaca pela sua atua\u00e7\u00e3o de resolver problemas e conflitos por meio da concilia\u00e7\u00e3o.<\/p>\n<p>\u201cO Minist\u00e9rio P\u00fablico de Minas Gerais v\u00eam atuando no sentido de encontrar constru\u00e7\u00f5es a partir da consensualidade com o Governo do Estado e outros entes p\u00fablicos\u201d, salientou.<br \/>&#13;<br \/>\n\u00a0<\/p>\n<p>\u00a0<\/p>\n<table align=\"center\" border=\"0\" cellpadding=\"1\" cellspacing=\"1\" style=\"width: 100%;\">&#13;<\/p>\n<tbody>&#13;<\/p>\n<tr>&#13;<\/p>\n<td colspan=\"5\" style=\"text-align: center; vertical-align: middle;\">&#13;<\/p>\n<p style=\"text-align:center\">\n<p>&#13;\n\t\t\t<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<\/p>\n<td colspan=\"3\" rowspan=\"3\" style=\"text-align: center; vertical-align: middle;\">&#13;<br \/>\n\t\t\t&#13;\n\t\t\t<\/td>\n<p>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td colspan=\"5\" style=\"text-align: center; vertical-align: middle;\">&#13;<\/p>\n<p style=\"text-align:center\">\n<p>&#13;\n\t\t\t<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<br \/>\n\t<\/tbody>\n<p>&#13;<br \/>\n<\/table>\n<p>A previs\u00e3o \u00e9 de que o encontro re\u00fana em torno de 400 congressistas, promotores, procuradores de Justi\u00e7a e outros convidados em \u00e2mbito estadual e nacional.<\/p>\n<p><strong>AMMP<\/strong><\/p>\n<p>A Associa\u00e7\u00e3o Mineira do Minist\u00e9rio P\u00fablico \u00e9 uma entidade que congrega promotores e procuradores de Justi\u00e7a de Minas e pensionistas, que tem como principais finalidades a representa\u00e7\u00e3o e defesa dos direitos, garantias, autonomias, prerrogativas, interesses e reinvindica\u00e7\u00f5es dos membros do Minist\u00e9rio P\u00fablico.<\/p>\n<p><strong>Medalha da Inconfid\u00eancia<\/strong><\/p>\n<p>Na oportunidade o vice-governador Professor Mateus entregou a Medalha da Inconfid\u00eancia ao procurador-geral de Justi\u00e7a do Rio de Janeiro, Luciano Mattos.<\/p>\n<p>\u00a0<\/p>\n<p>Ele foi um dos homenageados com a honraria, que marca as celebra\u00e7\u00f5es do Dia de Tiradentes (21 de abril), m\u00e1rtir da Inconfid\u00eancia Mineira, mas n\u00e3o p\u00f4de estar presente na cerim\u00f4nia realizada em Ouro Preto.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O vice-governador Professor Mateus participou, nessa quarta-feira (7\/8), em Belo Horizonte, da abertura do 15\u00ba Congresso Estadual do Minist\u00e9rio P\u00fablico de Minas Gerais, promovido pela Associa\u00e7\u00e3o Mineira do Minist\u00e9rio P\u00fablico (AMMP). O evento ter\u00e1 dura\u00e7\u00e3o de tr\u00eas dias, com uma programa\u00e7\u00e3o composta por paineis, palestras e apresenta\u00e7\u00f5es de teses envolvendo a tem\u00e1tica \u201cMinist\u00e9rio P\u00fablico: por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25835","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=25835"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25835\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=25835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=25835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=25835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}