{"id":26217,"date":"2024-08-19T08:17:30","date_gmt":"2024-08-19T11:17:30","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/08\/19\/acoes-de-neutralizacao-de-carbono-destacam-responsabilidade-ambiental-do-turismo-no-fib-2024\/"},"modified":"2024-08-19T08:17:30","modified_gmt":"2024-08-19T11:17:30","slug":"acoes-de-neutralizacao-de-carbono-destacam-responsabilidade-ambiental-do-turismo-no-fib-2024","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/08\/19\/acoes-de-neutralizacao-de-carbono-destacam-responsabilidade-ambiental-do-turismo-no-fib-2024\/","title":{"rendered":"A\u00e7\u00f5es de neutraliza\u00e7\u00e3o de carbono destacam responsabilidade ambiental do turismo no FIB 2024"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Principal destino de ecoturismo do Brasil e refer\u00eancia internacional, Bonito \u00e9 palco de mais um Festival de Inverno cheio de atra\u00e7\u00f5es musicais, muita arte e responsabilidade ambiental. Al\u00e9m da agenda cultural, o Festival de Inverno de Bonito (FIB) 2024 contar\u00e1 com a\u00e7\u00f5es e pr\u00e1ticas com foco na neutraliza\u00e7\u00e3o de carbono, contribuindo com os objetivos do Programa Estadual de Mudan\u00e7as Clim\u00e1ticas. Uma delas \u00e9 compensa\u00e7\u00e3o de carbono, realizada pela Compensei, com o apoio da Setesc (Secretaria Estadual de Turismo, Esporte e Cultura).<\/p>\n<p>\u201cA FundturMS \u00e9 parceira do FIB mais uma vez, especialmente nas a\u00e7\u00f5es relacionadas ao clima e \u00e0 conserva\u00e7\u00e3o, mais uma vez contribuindo para que seja um evento carbono neutro. Teremos um espa\u00e7o, juntamente com a Compensei, medindo e depois compensando as emiss\u00f5es de carbono geradas pelos visitantes e o p\u00fablico que vai passar pelo festival\u201d, destaca o diretor-presidente da Funda\u00e7\u00e3o de Turismo de Mato Grosso do Sul, Bruno Wendling.<\/p>\n<p>O diretor-presidente destaca tamb\u00e9m uma novidade nas a\u00e7\u00f5es durante o FIB 2024.<\/p>\n<p>\u201cEste ano, em especial, iremos lan\u00e7ar o \u201cBonito Cidade Ecocriativa \u2013 Smart City\u201d, um movimento que j\u00e1 vem acontecendo h\u00e1 quase dois anos e que vai trabalhar uma s\u00e9rie de eixos estrat\u00e9gicos. E estaremos com espa\u00e7o l\u00e1 no Festival para apresentar esse movimento durante os dias do evento e para que as pessoas conhe\u00e7am um pouco mais sobre a atua\u00e7\u00e3o da FundturMS, que n\u00e3o \u00e9 s\u00f3 a parte de promo\u00e7\u00e3o e de apoio \u00e0 comercializa\u00e7\u00e3o e governan\u00e7a, mas tamb\u00e9m de apoio a a\u00e7\u00f5es estruturantes, para o fortalecimento do territ\u00f3rio. Queremos levar Bonito para um pr\u00f3ximo n\u00edvel, mantendo o destino na vanguarda de destinos respons\u00e1veis e como o principal destino de ecoturismo do pa\u00eds\u201d, explica Wendling.<\/p>\n<p>O \u2018Bonito Cidade Ecocriativa\u2019 possui 4 eixos estrat\u00e9gicos principais: a educa\u00e7\u00e3o, que pretende gerar novas oportunidades para os jovens acessarem novos conhecimentos, al\u00e9m de apoiar a qualifica\u00e7\u00e3o permanente do trade e colaboradores; \u00a0a sustentabilidade, para promover novas pr\u00e1ticas que contribuam para a redu\u00e7\u00e3o das emiss\u00f5es de carbono no setor do turismo (\u00e1gua, energia, res\u00edduos); a economia criativa, que vai apoiar a comunidade em estrat\u00e9gias que incentivem uma governan\u00e7a comunit\u00e1ria efetiva, que permita acesso \u00e0 cultura e ao lazer e que incentive a economia criativa associada ao turismo; e a inova\u00e7\u00e3o, com o objetivo de apoiar o desenvolvimento de solu\u00e7\u00f5es tecnol\u00f3gicas e inovadoras para os desafios do destino tur\u00edstico de Bonito.<\/p>\n<p><strong>Estrat\u00e9gias<\/strong><\/p>\n<p>Com a certifica\u00e7\u00e3o de Bonito como 1\u00ba Destino de Ecoturismo Carbono Neutro do mundo em 2022, a FundturMS (Funda\u00e7\u00e3o de Turismo de Mato Grosso do Sul) e o munic\u00edpio de Bonito internalizaram as necessidades relacionadas \u00e0 emerg\u00eancia clim\u00e1tica e v\u00eam construindo estrat\u00e9gias que promovam a descarboniza\u00e7\u00e3o do turismo local.<\/p>\n<p>Um desdobramento do trabalho foi a elabora\u00e7\u00e3o do plano de a\u00e7\u00e3o clim\u00e1tica, com o estabelecimento das metas de redu\u00e7\u00e3o, em conformidade com as tend\u00eancias globais no desenvolvimento de solu\u00e7\u00f5es de mitiga\u00e7\u00e3o de emiss\u00f5es de carbono.<\/p>\n<p>Dentre os compromissos assumidos no \u00e2mbito da Declara\u00e7\u00e3o de Glasgow, a Fundtur-MS est\u00e1 apoiando os trabalhos para o 2\u00ba ciclo de invent\u00e1rio de emiss\u00f5es de gases de efeito estufa do turismo em Bonito, com vistas \u00e0 certifica\u00e7\u00e3o pela Green Initiative, umas das certificadoras reconhecidas pela ONU Turismo, numa jornada que envolve a coleta de dados de forma cont\u00ednua e sistem\u00e1tica, em conformidade com o GHG Protocol e o mercado regulado de carbono.<\/p>\n<p>Segundo dados do Observat\u00f3rio do Turismo de Bonito, o destino recebeu 30.491 turistas em julho de 2024, n\u00famero recorde em compara\u00e7\u00e3o ao mesmo per\u00edodo nos \u00faltimos nove anos.<\/p>\n<p>Assim, ao mesmo tempo que o crescimento do n\u00famero de turistas em Bonito indica o potencial de impacto econ\u00f4mico da atividade, o aumento expressivo aliado \u00e0 crise clim\u00e1tica faz necess\u00e1ria uma prepara\u00e7\u00e3o para administrar os desafios que se imp\u00f5e como: conserva\u00e7\u00e3o dos recursos naturais, mitiga\u00e7\u00e3o das emiss\u00f5es de gases de efeito estufa e adapta\u00e7\u00e3o \u00e0s mudan\u00e7as clim\u00e1ticas, trabalho decente, redu\u00e7\u00e3o de impactos sociais, dentre outros.<\/p>\n<p><em>D\u00e9bora Bordin, Comunica\u00e7\u00e3o FundturMS<br \/><\/em><em>Foto: Est\u00e2ncia Mimosa<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Principal destino de ecoturismo do Brasil e refer\u00eancia internacional, Bonito \u00e9 palco de mais um Festival de Inverno cheio de atra\u00e7\u00f5es musicais, muita arte e responsabilidade ambiental. Al\u00e9m da agenda cultural, o Festival de Inverno de Bonito (FIB) 2024 contar\u00e1 com a\u00e7\u00f5es e pr\u00e1ticas com foco na neutraliza\u00e7\u00e3o de carbono, contribuindo com os objetivos do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-26217","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=26217"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26217\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=26217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=26217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=26217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}