{"id":26810,"date":"2024-09-05T18:30:27","date_gmt":"2024-09-05T21:30:27","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/09\/05\/lancamento-da-caminhada-passos-pela-vida-reune-parceiros-para-conscientizar-sobre-doacao-de-orgaos\/"},"modified":"2024-09-05T18:30:27","modified_gmt":"2024-09-05T21:30:27","slug":"lancamento-da-caminhada-passos-pela-vida-reune-parceiros-para-conscientizar-sobre-doacao-de-orgaos","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/09\/05\/lancamento-da-caminhada-passos-pela-vida-reune-parceiros-para-conscientizar-sobre-doacao-de-orgaos\/","title":{"rendered":"Lan\u00e7amento da caminhada \u2018Passos pela Vida\u2019 re\u00fane parceiros para conscientizar sobre doa\u00e7\u00e3o de \u00f3rg\u00e3os"},"content":{"rendered":"<p><\/p>\n<div>\n<p>O lan\u00e7amento oficial da 1\u00ba caminhada \u201c Passos pela Vida \u2013 Juntos pela Doa\u00e7\u00e3o de \u00d3rg\u00e3os e C\u00f3rneas\u201d, realizado quarta-feira (4) na CET\/MS (Central Estadual de Transplantes de Mato Grosso do Sul), reuniu dezenas de apoiadores da causa para refor\u00e7ar a import\u00e2ncia da doa\u00e7\u00e3o de \u00f3rg\u00e3os.<\/p>\n<p>A caminhada, que ser\u00e1 realizada no dia 15 de setembro, \u00e0s 8h, com in\u00edcio no Centro de M\u00faltiplo Uso \u2013 Arquiteta Zuleide Simabuco Higa, pr\u00f3ximo ao Quartel do Corpo de Bombeiros do Parque dos Poderes, em Campo Grande, contar\u00e1 com din\u00e2mica interativa e orienta\u00e7\u00f5es sobre doa\u00e7\u00e3o de \u00f3rg\u00e3os e c\u00f3rneas, avalia\u00e7\u00e3o f\u00edsica, participa\u00e7\u00e3o dos her\u00f3is da Liga do Bem, entre outras atividades.<\/p>\n<p>Durante o evento de lan\u00e7amento, a coordenadora da CET\/MS, Claire Carmen Miozzo, refor\u00e7ou a import\u00e2ncia da parceria em prol das doa\u00e7\u00f5es e agradeceu o apoio dos parceiros. \u201cEsse ano estamos fazendo uma mobiliza\u00e7\u00e3o nunca vista antes, muitos parceiros e amigos da causa unidos para conscientizar as fam\u00edlias sobre a import\u00e2ncia do sim a doa\u00e7\u00e3o de \u00f3rg\u00e3os. Gratid\u00e3o a todos que participam conosco desta iniciativa\u201d.<\/p>\n<p>Para o diretor-presidente da Fundesporte (Funda\u00e7\u00e3o de Desporto e Lazer de Mato Grosso do Sul), Paulo Ricardo Martins Nu\u00f1ez, a parceria \u00e9 fundamental. \u201cVamos participar de todo apoio log\u00edstico e estaremos com acad\u00eamicos de universidades presentes para a realiza\u00e7\u00e3o de atividades com todos os participantes, ser\u00e1 um dia para a fam\u00edlia toda\u201d.<\/p>\n<p>Segundo a superintendente de Gest\u00e3o do Hospital S\u00e3o Juli\u00e3o, J\u00e9ssica Mendes, que na ocasi\u00e3o representava o presidente da institui\u00e7\u00e3o Dr. Carlos Melke, o evento refor\u00e7a o trabalho realizado por toda rede. \u201c\u00c9 uma campanha de grande import\u00e2ncia para n\u00f3s, um trabalho que realizamos todos os dias juntos as fam\u00edlias. Hoje, o S\u00e3o Juli\u00e3o realiza cerca de 90% de todos os transplantes de c\u00f3rnea do Estado\u201d, refor\u00e7a.<\/p>\n<p><strong>Esperan\u00e7a<\/strong><\/p>\n<figure id=\"attachment_489614\" aria-describedby=\"caption-attachment-489614\" style=\"width: 300px\" class=\"wp-caption alignleft\"><figcaption id=\"caption-attachment-489614\" class=\"wp-caption-text\">Com f\u00e9 e esperan\u00e7a, Neila aguarda o dia da chegada do seu Sim. Foto: Marcus Moura<\/figcaption><\/figure>\n<p>A professora aposentada Neila Mara Flores veio de Jardim para prestigiar o lan\u00e7amento da caminhada. Diagnosticada com c\u00e2ncer f\u00edgado, ela est\u00e1 na fila de transplante e diz que positividade e f\u00e9 fazem toda a diferen\u00e7a. \u201cFaz um ano e seis meses que eu estou aguardando. Precisamos falar disso em todos os lugares, n\u00f3s temos que conscientizar nossas fam\u00edlias que somos doadores. Hoje, eu sei qu\u00e3o importante \u00e9 doar por estar nessa condi\u00e7\u00e3o, mas tenho muita f\u00e9 em Deus e positividade para enfrentar esse desafio\u201d, destaca.<\/p>\n<p>O aut\u00f4nomo Roberto Pino conhece bem a espera pela doa\u00e7\u00e3o, diagnosticado com uma comorbidade em 2012, ele aguardou cerca de quatro anos pelo sim. \u201cAgora, dia 13 de agosto, fez oito anos da minha cirurgia. Antes da doen\u00e7a, eu n\u00e3o falava sobre doa\u00e7\u00e3o, n\u00e3o era algo comum para mim, mas depois de viver tudo que vivi, sei da import\u00e2ncia em falarmos a respeito da doa\u00e7\u00e3o. Um sim pode salvar muitas vidas\u201d.<\/p>\n<p>O evento \u00e9 uma realiza\u00e7\u00e3o da SES (Secretaria de Estado de Sa\u00fade), por meio da CET\/MS, Fundesporte (Funda\u00e7\u00e3o de Desporto e Lazer de Mato Grosso do Sul), SETESC (Secretaria de Estado de Turismo, Esporte e Cultura) e Assembleia Legislativa de Mato Grosso do Sul, e apoio da OPO Santa Casa, OPO Hospital da Vida de Dourados, Hospital S\u00e3o Juli\u00e3o, Fratello, Hemosul, Hospital Universit\u00e1rio Maria Aparecida Pedrossian, Banco de Olhos da Santa Casa de Campo Grande, Jeito de Cuidar Unimed, deputado estadual Renato C\u00e2mara, Instituto Sangue Bom, Faccilita Intelig\u00eancia Cont\u00e1bil, AVC Center, Instituto da Vis\u00e3o de Mato Grosso do Sul, Esta\u00e7\u00e3o Sul, Hospital dos Olhos Dourados, Santa Casa Campo Grande, Hospital Adventista do P\u00eanfigo, Unimed Campo Grande, Cassems, Pr\u00f3 Oftalmo Cl\u00ednica de Olhos, Hospital Proncor, Hospital Santa Marina, Laborat\u00f3rio Sabin e Bio Molecular.<\/p>\n<figure id=\"attachment_489612\" aria-describedby=\"caption-attachment-489612\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><figcaption id=\"caption-attachment-489612\" class=\"wp-caption-text\">Lan\u00e7amento da caminhada aconteceu na sede da CET\/MS. Foto: Marcus Moura<\/figcaption><\/figure>\n<p><strong>Doe \u00f3rg\u00e3os, salve vidas<\/strong><\/p>\n<p>A doa\u00e7\u00e3o de \u00f3rg\u00e3os \u00e9 um gesto de solidariedade e amor ao pr\u00f3ximo, que permite que muitas pessoas possam ter uma nova chance de vida. Para ser doador, basta comunicar essa vontade aos familiares, pois a autoriza\u00e7\u00e3o para a doa\u00e7\u00e3o deve ser feita pela fam\u00edlia no momento oportuno. Eventos como a Caminhada \u201cPassos pela Vida\u201d s\u00e3o fundamentais para refor\u00e7ar a import\u00e2ncia dessa decis\u00e3o.<\/p>\n<p><em>Marcus Moura\/ Comunica\u00e7\u00e3o SES<\/em><br \/><em>Foto de capa: Luciana Nassar\/Alems<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O lan\u00e7amento oficial da 1\u00ba caminhada \u201c Passos pela Vida \u2013 Juntos pela Doa\u00e7\u00e3o de \u00d3rg\u00e3os e C\u00f3rneas\u201d, realizado quarta-feira (4) na CET\/MS (Central Estadual de Transplantes de Mato Grosso do Sul), reuniu dezenas de apoiadores da causa para refor\u00e7ar a import\u00e2ncia da doa\u00e7\u00e3o de \u00f3rg\u00e3os. A caminhada, que ser\u00e1 realizada no dia 15 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-26810","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=26810"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26810\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=26810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=26810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=26810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}