{"id":27736,"date":"2024-10-09T11:43:35","date_gmt":"2024-10-09T14:43:35","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/10\/09\/sorocaba-recebe-a-oktoberfest-cerveja-livre-nos-dias-19-e-20-de-outubro-agencia-de-noticias\/"},"modified":"2024-10-09T11:43:35","modified_gmt":"2024-10-09T14:43:35","slug":"sorocaba-recebe-a-oktoberfest-cerveja-livre-nos-dias-19-e-20-de-outubro-agencia-de-noticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/10\/09\/sorocaba-recebe-a-oktoberfest-cerveja-livre-nos-dias-19-e-20-de-outubro-agencia-de-noticias\/","title":{"rendered":"Sorocaba recebe a Oktoberfest Cerveja Livre nos dias 19 e 20 de outubro \u2013 Ag\u00eancia de Not\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<div class=\"col\">\n<p class=\"mt-0\">\n                        <strong><br \/>\n                            <span class=\"far fa-calendar mr-1 mt-2\"\/><br \/>\n                            9 de outubro de 2024<br \/>\n                            <span class=\"far fa-clock ml-3 mt-2\"\/><br \/>\n                            11:03<br \/>\n                        <\/strong>\n                    <\/p>\n<p class=\"mb-0\">Por: <strong>Lu\u00eds Gustavo Adabro<\/strong><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<p>Nos dias 19 e 20 de outubro, das 11h \u00e0s 21h, Sorocaba receber\u00e1 mais uma edi\u00e7\u00e3o da Oktoberfest Cerveja Livre, no Parque \u201cCarlos Alberto de Souza\u201d, no Campolim. Nesta edi\u00e7\u00e3o, o evento contar\u00e1 com a participa\u00e7\u00e3o de 11 cervejarias artesanais da regi\u00e3o de Sorocaba, al\u00e9m de atra\u00e7\u00f5es, gastronomia e cultura t\u00edpicas.<\/p>\n<p>A realiza\u00e7\u00e3o \u00e9 da Associa\u00e7\u00e3o Cerveja Livre, com o apoio da Prefeitura de Sorocaba, por meio da Secretaria de Desenvolvimento Econ\u00f4mico e Turismo (Sedetur).<\/p>\n<p>Participar\u00e3o da festa as seguintes cervejarias: Burgman, Bulgaros, Cervejaria Los Gatos, Comendador, Esta\u00e7\u00e3o Beer, Hoffen, Imperatriz, Sanches, S\u00e9timo Copo, Sorocabana e Wayne 190. Tamb\u00e9m haver\u00e1 uma pra\u00e7a de alimenta\u00e7\u00e3o no local, com diversos foodtrucks al\u00e9m de espa\u00e7o kids.<\/p>\n<p>No s\u00e1bado (19), a atra\u00e7\u00e3o musical ficar\u00e1 a cargo das bandas Mamonas, Jam Go Livre e Banda Live by Night. J\u00e1 no domingo (20), ter\u00e1 show infantil da banda Blaze Train, al\u00e9m de musica ao vivo da banda Blaze Train e Megazord.<\/p>\n<p>Mais informa\u00e7\u00f5es sobre a Oktoberfest Cerveja Livre podem ser obtidas pelo perfil oficial dos organizadores do evento no Instagram: @cerveja.livre.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>9 de outubro de 2024 11:03 Por: Lu\u00eds Gustavo Adabro Nos dias 19 e 20 de outubro, das 11h \u00e0s 21h, Sorocaba receber\u00e1 mais uma edi\u00e7\u00e3o da Oktoberfest Cerveja Livre, no Parque \u201cCarlos Alberto de Souza\u201d, no Campolim. Nesta edi\u00e7\u00e3o, o evento contar\u00e1 com a participa\u00e7\u00e3o de 11 cervejarias artesanais da regi\u00e3o de Sorocaba, al\u00e9m [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27736","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27736"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27736\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}