{"id":28113,"date":"2024-10-20T08:57:58","date_gmt":"2024-10-20T11:57:58","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/10\/20\/no-rancho-fundo-resumo-dos-capitulos-161-a-166-da-novela-da-globo-de-21-a-26-10\/"},"modified":"2024-10-20T08:57:58","modified_gmt":"2024-10-20T11:57:58","slug":"no-rancho-fundo-resumo-dos-capitulos-161-a-166-da-novela-da-globo-de-21-a-26-10","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/10\/20\/no-rancho-fundo-resumo-dos-capitulos-161-a-166-da-novela-da-globo-de-21-a-26-10\/","title":{"rendered":"No Rancho Fundo &#8211; Resumo dos cap\u00edtulos 161 a 166 da novela da Globo de 21 a 26\/10"},"content":{"rendered":"<p> Por MRNews<br \/>\n<\/p>\n<div>\n<p>RESUMO SEMANAL \u2013 NOVELA \u201cNO RANCHO FUNDO\u201d<\/p>\n<h2>Aqui est\u00e1 o resumo semanal da novela \u201cNo Rancho Fundo\u201d, dos cap\u00edtulos de 21 a 26 de outubro de 2024:<\/h2>\n<p>**Cap\u00edtulo 161** \u2013 Segunda-feira<br \/>Zefa Leonel e Seu Tico confrontam Deodora e Ariosto sobre o desaparecimento de Primo C\u00edcero. Jord\u00e3o Nic\u00e1cio vigia Primo C\u00edcero no cativeiro, enquanto Guilherme Tell se oferece para pagar as d\u00edvidas de Caridade, levantando suspeitas. Ariosto, Seu Tico e Padre Zezo tentam descobrir o paradeiro de Primo C\u00edcero, e Deodora manipula Jord\u00e3o Nic\u00e1cio para mat\u00e1-lo.<\/p>\n<p>**Cap\u00edtulo 162** \u2013 Ter\u00e7a-feira<br \/>Deodora pressiona Jord\u00e3o para assassinar Primo C\u00edcero. Ariosto questiona Deodora sobre sua arma. Jord\u00e3o hesita antes de atirar em Primo C\u00edcero. Zefa Leonel descobre uma mensagem secreta no bilhete de Fub\u00e1 Mimoso. Marcelo Gouveia revela que Ariosto foi o mandante do sequestro de Artur. Jord\u00e3o finalmente atira em Primo C\u00edcero.<\/p>\n<p>**Cap\u00edtulo 163** \u2013 Quarta-feira<br \/>Jord\u00e3o informa Deodora que cumpriu o combinado, mas Cira escuta. Caridade fica desconfiada do comportamento de Esperan\u00e7a em rela\u00e7\u00e3o ao sequestro. Vespertino questiona Deodora sobre seu envolvimento no cabar\u00e9, e Ariosto pede a Quinota que interceda por ele. Blandina e Marcelo Gouveia decidem mudar o cativeiro de Primo C\u00edcero, sem saber que ele foi baleado.<\/p>\n<p>**Cap\u00edtulo 164** \u2013 Quinta-feira<br \/>Primo C\u00edcero sobrevive ao tiro gra\u00e7as ao relic\u00e1rio de Militana e volta para a casa de Zefa Leonel. Ariosto \u00e9 expulso por Artur, e Deodora manipula Vespertino, beijando-o. Jord\u00e3o descobre que Primo C\u00edcero fugiu. Marcelo Gouveia acredita que Primo esteja morto. Artur descobre o envolvimento de Marcelo com o contrabando de turmalinas.<\/p>\n<p>**Cap\u00edtulo 165** \u2013 Sexta-feira<br \/>Artur for\u00e7a Marcelo a lev\u00e1-lo \u00e0 Gruta Azul, onde ele come\u00e7a a investigar as pedras roubadas. Zefa Leonel organiza a prote\u00e7\u00e3o de Primo C\u00edcero, escondendo-o no Rancho Fundo. Enquanto isso, Elias Cris\u00f3stomo suspeita que os Leonel est\u00e3o tramando algo. Quinota e Zefa entram na Gruta Azul, onde a situa\u00e7\u00e3o se complica.<\/p>\n<p>**Cap\u00edtulo 166** \u2013 S\u00e1bado<br \/>Deodora repreende Ariosto por esconder Elias, e Artur obriga Marcelo Gouveia a explorar a mina da Gruta Azul. Quinota revela a Zefa sobre o roubo de pedras. Enquanto isso, Timb\u00f3 e Seu Tico armam a falsa morte de Primo C\u00edcero para proteg\u00ea-lo. Blandina e Marcelo passam mal na Gruta, mas Zefa e Artur conseguem escapar.<\/p>\n<p>Esses resumos podem sofrer altera\u00e7\u00f5es conforme a edi\u00e7\u00e3o da novela.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por MRNews RESUMO SEMANAL \u2013 NOVELA \u201cNO RANCHO FUNDO\u201d Aqui est\u00e1 o resumo semanal da novela \u201cNo Rancho Fundo\u201d, dos cap\u00edtulos de 21 a 26 de outubro de 2024: **Cap\u00edtulo 161** \u2013 Segunda-feiraZefa Leonel e Seu Tico confrontam Deodora e Ariosto sobre o desaparecimento de Primo C\u00edcero. Jord\u00e3o Nic\u00e1cio vigia Primo C\u00edcero no cativeiro, enquanto [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-28113","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=28113"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28113\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=28113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=28113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=28113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}