{"id":28833,"date":"2024-11-06T19:41:06","date_gmt":"2024-11-06T22:41:06","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2024\/11\/06\/confira-a-programacao-da-operacao-cata-bagulho-deste-sabado-09-prefeitura-estancia-turistica-guaratingueta\/"},"modified":"2024-11-06T19:41:06","modified_gmt":"2024-11-06T22:41:06","slug":"confira-a-programacao-da-operacao-cata-bagulho-deste-sabado-09-prefeitura-estancia-turistica-guaratingueta","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2024\/11\/06\/confira-a-programacao-da-operacao-cata-bagulho-deste-sabado-09-prefeitura-estancia-turistica-guaratingueta\/","title":{"rendered":"Confira a programa\u00e7\u00e3o da Opera\u00e7\u00e3o Cata-bagulho deste s\u00e1bado (09) \u2013 Prefeitura Est\u00e2ncia Tur\u00edstica Guaratinguet\u00e1"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Neste s\u00e1bado a Opera\u00e7\u00e3o Cata-bagulho atender\u00e1 o seguinte bairro:<\/p>\n<p>S\u00e1bado (09\/11): Jardim do Vale II.<\/p>\n<p>Separe os materiais inserv\u00edveis para serem recolhidos, com exce\u00e7\u00e3o de restos de material de constru\u00e7\u00e3o e roupas, lembrando que eles devem ser colocados para fora de casa at\u00e9 o 12h.<\/p>\n<p>Essa a\u00e7\u00e3o faz parte da Campanha contra a dengue do munic\u00edpio, eliminando materiais que s\u00e3o criadouros para os mosquitos e abrigo para animais pe\u00e7onhentos, envolvendo uma for\u00e7a-tarefa da Administra\u00e7\u00e3o Municipal.<\/p>\n<p>Para uma cidade limpa, precisamos da colabora\u00e7\u00e3o de todos!<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Neste s\u00e1bado a Opera\u00e7\u00e3o Cata-bagulho atender\u00e1 o seguinte bairro: S\u00e1bado (09\/11): Jardim do Vale II. Separe os materiais inserv\u00edveis para serem recolhidos, com exce\u00e7\u00e3o de restos de material de constru\u00e7\u00e3o e roupas, lembrando que eles devem ser colocados para fora de casa at\u00e9 o 12h. Essa a\u00e7\u00e3o faz parte da Campanha contra a dengue do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-28833","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=28833"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28833\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=28833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=28833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=28833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}