{"id":31913,"date":"2025-01-22T16:13:10","date_gmt":"2025-01-22T19:13:10","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/01\/22\/fumace-percorre-sete-bairros-de-campo-grande-nessa-quarta-feira-22-cgnoticias\/"},"modified":"2025-01-22T16:13:10","modified_gmt":"2025-01-22T19:13:10","slug":"fumace-percorre-sete-bairros-de-campo-grande-nessa-quarta-feira-22-cgnoticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/01\/22\/fumace-percorre-sete-bairros-de-campo-grande-nessa-quarta-feira-22-cgnoticias\/","title":{"rendered":"Fumac\u00ea percorre sete bairros de Campo Grande nessa quarta-feira (22)\u00a0 \u2013 CGNot\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>O combate ao mosquito Aedes Aegypti, transmissor de arboviroses como Dengue, Zika e Chikungunya, ser\u00e1 refor\u00e7ado em cinco bairros de Campo Grande, com o uso do servi\u00e7o de borrifa\u00e7\u00e3o ultrabaixo volume (UBV) \u2013 conhecido como Fumac\u00ea, nesta quarta-feira (22).<\/p>\n<p>As equipes da Coordenadoria de Controle de Endemias Vetoriais (CCEV) da Secretaria Municipal de Sa\u00fade (Sesau) circular\u00e3o das 16h \u00e0s 22h pelas ruas dos seguintes bairros: Guanandi, Tiradentes, Jardim Leblon, Parati, Jardim Aero Rancho, Amamba\u00ed e Monte L\u00edbano.\u00a0<\/p>\n<p>Para uma maior efic\u00e1cia do inseticida, \u00e9 necess\u00e1rio que o morador abra portas e janelas, assim o veneno consegue atingir os locais onde h\u00e1 maior probabilidade de estarem os mosquitos.\u00a0<\/p>\n<p>Os servi\u00e7os podem ser adiados ou at\u00e9 mesmo cancelados em caso de chuvas, ventos ou neblina, uma vez que tais atividades meteorol\u00f3gicas prejudicam a aplica\u00e7\u00e3o do veneno.\u00a0<\/p>\n<p>O inseticida atinge os mosquitos adultos, preferencialmente as f\u00eameas, que s\u00e3o as transmissoras das doen\u00e7as. Ainda assim \u00e9 poss\u00edvel que outras esp\u00e9cies sejam atingidas e, por isso, \u00e9 necess\u00e1ria uma aplica\u00e7\u00e3o criteriosa do veneno.\u00a0<\/p>\n<p><strong>Confira o itiner\u00e1rio:<\/strong>\u00a0<\/p>\n<\/p>\n<p><em><strong>#PraTodosVerem<\/strong> : Na capa da mat\u00e9ria h\u00e1 uma foto que mostra uma caminhonete branca, de cabine dupla, equipada com o dispositivo de fumac\u00ea, percorrendo ruas de Campo Grande durante a aplica\u00e7\u00e3o do inseticida. <\/em><\/p>\n<\/div>\n<p><script async defer async defer src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=1#xfbml=1&amp;version=v3.2\" id=\"prefeitura-campogrande-script-facebook-sdk-js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O combate ao mosquito Aedes Aegypti, transmissor de arboviroses como Dengue, Zika e Chikungunya, ser\u00e1 refor\u00e7ado em cinco bairros de Campo Grande, com o uso do servi\u00e7o de borrifa\u00e7\u00e3o ultrabaixo volume (UBV) \u2013 conhecido como Fumac\u00ea, nesta quarta-feira (22). As equipes da Coordenadoria de Controle de Endemias Vetoriais (CCEV) da Secretaria Municipal de Sa\u00fade (Sesau) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-31913","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=31913"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31913\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=31913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=31913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=31913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}