{"id":32835,"date":"2025-02-13T14:55:09","date_gmt":"2025-02-13T17:55:09","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/02\/13\/aplicativo-na-palma-da-mao-auxilia-populacao-no-cadastro-ao-servico-familia-acolhedora\/"},"modified":"2025-02-13T14:55:09","modified_gmt":"2025-02-13T17:55:09","slug":"aplicativo-na-palma-da-mao-auxilia-populacao-no-cadastro-ao-servico-familia-acolhedora","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/02\/13\/aplicativo-na-palma-da-mao-auxilia-populacao-no-cadastro-ao-servico-familia-acolhedora\/","title":{"rendered":"Aplicativo \u2018Na Palma da M\u00e3o\u2019 auxilia popula\u00e7\u00e3o no cadastro ao Servi\u00e7o Fam\u00edlia Acolhedora"},"content":{"rendered":"<p><\/p>\n<div>\n<p>O aplicativo \u2018Jo\u00e3o Pessoa na Palma da M\u00e3o\u2019 tem auxiliado a popula\u00e7\u00e3o no acesso a diversos servi\u00e7os ofertados pela Prefeitura Municipal de Jo\u00e3o Pessoa, e em parceria com a Secretaria de Direitos Humanos e Cidadania (Sedhuc), facilita o acesso ao Servi\u00e7o Fam\u00edlia Acolhedora.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><\/figure>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<\/figure>\n<p>O servi\u00e7o auxilia fam\u00edlias interessadas no acolhimento provis\u00f3rio de crian\u00e7as e adolescentes afastados do n\u00facleo familiar de origem por medida de prote\u00e7\u00e3o e inseridas em fam\u00edlias volunt\u00e1rias.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><\/figure>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<\/figure>\n<p>O cadastro pode ser feito pelo aplicativo, dispon\u00edvel tanto para o android quanto para ro Iphone, ou pelo site prefeituraconectada.joaopessoa.pb.gov.br\/. Assim como no atendimento presencial, a primeira etapa consiste no preenchimento de informa\u00e7\u00f5es b\u00e1sicas, como nome, idade, data de nascimento, CPF e RG, al\u00e9m do endere\u00e7o, contato e renda. O cadastro tamb\u00e9m conta com o perfil desejado pela fam\u00edlia, como faixa et\u00e1ria, g\u00eanero e as motiva\u00e7\u00f5es para o acolhimento.<\/p>\n<p>\u201cAtualmente, o aplicativo \u2018Na Palma da M\u00e3o\u2019 tem sido uma ferramenta de grande contribui\u00e7\u00e3o, pois tem facilitado muito a amplia\u00e7\u00e3o da informa\u00e7\u00e3o sobre essa modalidade de acolhimento familiar, que se refere ao acolhimento provis\u00f3rio de crian\u00e7as e adolescentes. N\u00f3s que fazemos o servi\u00e7o, ficamos muito satisfeitos em saber que, atrav\u00e9s do aplicativo sempre dispon\u00edvel, as pessoas podem ter acesso, deixando o cadastro sempre atualizado, para que nossa equipe entre em contato, para agendar um encontro na sede do servi\u00e7o, para que a\u00ed sim, atendendo aos requisitos necess\u00e1rios, \u00e0 inscri\u00e7\u00e3o seja efetivada\u201d, contou a coordenadora do servi\u00e7o, Andr\u00e9a Ara\u00fajo.<\/p>\n<p>De acordo com Andr\u00e9a, o cadastro realizado pelo aplicativo n\u00e3o garante a inscri\u00e7\u00e3o, mas agiliza o processo para as fam\u00edlias que desejam ingressar no acolhimento volunt\u00e1rio. \u201cDesde a ativa\u00e7\u00e3o do servi\u00e7o no aplicativo n\u00f3s tivemos muito \u00eaxito na quantidade de pessoas que entraram em contato para realizar o cadastramento. S\u00f3 nesta semana n\u00f3s agendamos cinco visitas, vindas pelo aplicativo. Ent\u00e3o a ferramenta vem se provando muito \u00fatil pro servi\u00e7o da Fam\u00edlia Acolhedora\u201d, completou a coordenadora.<\/p>\n<p><strong>Sobre o servi\u00e7o<\/strong> \u2013 O Servi\u00e7o de Acolhimento em Fam\u00edlia Acolhedora possui a finalidade de acolher, provisoriamente, crian\u00e7as e adolescentes (zero a 18 anos) afastados de sua fam\u00edlia de origem por medida de prote\u00e7\u00e3o e inseridas em fam\u00edlias volunt\u00e1rias, cadastradas e capacitadas, possibilitando a conviv\u00eancia familiar.<\/p>\n<p>O Servi\u00e7o Fam\u00edlia Acolhedora n\u00e3o est\u00e1 relacionada com ado\u00e7\u00e3o. Em s\u00edntese, uma Acolhedora deve ser uma fam\u00edlia normal, com a responsabilidade de administrar as atividades cotidianas e rotineiras do acolhido, levando-o \u00e0 escola e ao atendimento de sa\u00fade, por exemplo, tudo sob supervis\u00e3o de uma equipe t\u00e9cnica auxiliar, que deve ajud\u00e1-las na obten\u00e7\u00e3o destes atendimentos, preferencialmente na rede p\u00fablica.<\/p>\n<p>A sede do Servi\u00e7o Fam\u00edlia Acolhedora est\u00e1 localizada na rua Desembargador Jos\u00e9 Peregrino, n\u00ba 72, no Centro da cidade. E al\u00e9m do aplicativo, as fam\u00edlias interessadas no acolhimento podem entrar em contato pelo telefone (83) 9 8208-0126, para tirar d\u00favidas ou agendar uma visita \u00e0 sede.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O aplicativo \u2018Jo\u00e3o Pessoa na Palma da M\u00e3o\u2019 tem auxiliado a popula\u00e7\u00e3o no acesso a diversos servi\u00e7os ofertados pela Prefeitura Municipal de Jo\u00e3o Pessoa, e em parceria com a Secretaria de Direitos Humanos e Cidadania (Sedhuc), facilita o acesso ao Servi\u00e7o Fam\u00edlia Acolhedora. O servi\u00e7o auxilia fam\u00edlias interessadas no acolhimento provis\u00f3rio de crian\u00e7as e adolescentes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32835","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=32835"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32835\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=32835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=32835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=32835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}