{"id":33647,"date":"2025-03-03T13:30:25","date_gmt":"2025-03-03T16:30:25","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/03\/03\/domingo-e-marcado-pelo-novo-formato-dos-desfiles-na-sapucai-prefeitura-da-cidade-do-rio-de-janeiro\/"},"modified":"2025-03-03T13:30:25","modified_gmt":"2025-03-03T16:30:25","slug":"domingo-e-marcado-pelo-novo-formato-dos-desfiles-na-sapucai-prefeitura-da-cidade-do-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/03\/03\/domingo-e-marcado-pelo-novo-formato-dos-desfiles-na-sapucai-prefeitura-da-cidade-do-rio-de-janeiro\/","title":{"rendered":"Domingo \u00e9 marcado pelo novo formato dos desfiles na Sapuca\u00ed &#8211; Prefeitura da Cidade do Rio de Janeiro"},"content":{"rendered":"<p><\/p>\n<div wp_automatic_readability=\"727.07845843508\">\n<div class=\"image-post\" wp_automatic_readability=\"34\">\n                     Desfile da Unidos de Padre Miguel, durante o primeiro dia das escolas de samba do Grupo Especial &#8211; Marcos de Paula\/Prefeitura                  <\/div>\n<p><span style=\"font-weight: 400\">Quatro escolas abriram o primeiro dia do Grupo Especial, neste domingo (02\/03), na Marqu\u00eas de Sapuca\u00ed. A Unidos de Padre Miguel, campe\u00e3 da S\u00e9rie Ouro no ano passado, foi a primeira a entrar na avenida. Na sequ\u00eancia, Imperatriz Leopoldinense, Viradouro e Mangueira completaram o novo formato da festa que, a partir desse ano, passa a contar com tr\u00eas dias consecutivos de desfiles e rodas de samba na Pra\u00e7a da Apoteose. O primeiro dia teve Cacique de Ramos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">A religiosidade afro-brasileira prevaleceu nos enredos da Unidos de Padre Miguel, da Imperatriz Leopoldinense e da Viradouro. J\u00e1 a Verde e Rosa, que encerrou a primeira noite, trouxe para a avenida a <\/span><span style=\"font-weight: 400\">influ\u00eancia dos povos bantus para a forma\u00e7\u00e3o cultural da cidade do Rio de Janeiro.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m de toda a emo\u00e7\u00e3o das escolas, o Oscar de melhor filme estrangeiro de \u201cAinda Estou Aqui\u201d foi anunciado na Marqu\u00eas de Sapuca\u00ed e levou o p\u00fablico ao del\u00edrio. Do outro lado da cidade, na Intendente Magalh\u00e3es, a not\u00edcia tamb\u00e9m foi recebida com grande euforia pelos foli\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Neste domingo, o tradicional palco da Zona Norte contou com a abertura dos desfiles da S\u00e9rie Prata, valendo uma vaga na Sapuca\u00ed, no pr\u00f3ximo ano. O p\u00fablico de cerca de 45 mil pessoas acompanhou as dez escolas at\u00e9 o in\u00edcio da manh\u00e3 de hoje (confira a programa\u00e7\u00e3o completa neste boletim).<\/span><\/p>\n<p><span style=\"font-weight: 400\">Entre os festejos da cidade, o Terreir\u00e3o do Samba teve um domingo animado com Jorge Arag\u00e3o, Tiee, Gustavo Lins, Fl\u00e1via Saolli e DJ. No Centro, o tradicional Baile da Cinel\u00e2ndia e o cortejo dos Blocos de Embalo e de Enredo, na Avenida Chile, completaram a programa\u00e7\u00e3o do domingo de Carnaval.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m disso, a festa dos blocos segue pela cidade. A Praia do Leblon foi tomada pelo bloco Areia, que reuniu os foli\u00f5es no t\u00edpico clima de ver\u00e3o carioca. Na Vila Kosmos, foi dia de o Charanga Talism\u00e3 encher as ruas do bairro. No Centro, o tradicional Cord\u00e3o do Boitat\u00e1 juntou seus admiradores na Pra\u00e7a Tiradentes. E, na parte da tarde, no Largo S\u00e3o Francisco da Prainha, a Marcha Nerd reuniu modelos variados de fantasias.<\/span><\/p>\n<p><span style=\"font-weight: 400\">No total, <\/span><b>52 <\/b><span style=\"font-weight: 400\">blocos foram \u00e0s ruas neste domingo, com cerca de 500 mil foli\u00f5es. At\u00e9 a quarta-feira de cinzas, mais de <\/span><b>240 blocos<\/b><span style=\"font-weight: 400\"> agitam a cidade, sem contar com os outros <\/span><b>38,<\/b><span style=\"font-weight: 400\"> que desfilam<\/span> <span style=\"font-weight: 400\">no fim de semana ap\u00f3s o carnaval.<\/span><\/p>\n<p><b>FOTOGRAFIAS<\/b><\/p>\n<p><span style=\"font-weight: 400\">No site www.carnaval.rio voc\u00ea encontra as not\u00edcias de tudo o que envolve o mundo do Carnaval e do samba.<\/span><\/p>\n<p><span style=\"font-weight: 400\">As fotos dos desfiles do Grupo Especial, dos shows do Terreir\u00e3o e do Carnaval de rua est\u00e3o dispon\u00edveis no Flickr da Riotur:\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">https:\/\/www.flickr.com\/photos\/riotur\/albums\/<\/span><\/p>\n<p><span style=\"font-weight: 400\">Mais fotos, no Flickr da Prefeitura do Rio: <\/span><span style=\"font-weight: 400\">https:\/\/flic.kr\/ps\/3Z6AUB<\/span><\/p>\n<p><b>V\u00cdDEO RELEASE<\/b><\/p>\n<p><span style=\"font-weight: 400\">Segue v\u00eddeo release dos servi\u00e7os da Prefeitura do Rio no primeiro dia de desfiles do Grupo Especial no Samb\u00f3dromo. Cr\u00e9dito das imagens: Marcelo Alvarenga\/Prefeitura do Rio. Link para download: <\/span><span style=\"font-weight: 400\">https:\/\/shre.ink\/bUpf<\/span><\/p>\n<p><b>ORDEM P\u00daBLICA E GUARDA MUNICIPAL<\/b><\/p>\n<p><b>Agentes atuam em 27 princ\u00edpios de tumulto<\/b><\/p>\n<p><i><span style=\"font-weight: 400\">Nas fiscaliza\u00e7\u00f5es de tr\u00e2nsito foram aplicadas 148 autua\u00e7\u00f5es\u00a0<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">No \u00faltimo domingo (02\/03), a Secretaria de Ordem P\u00fablica (SEOP) e a Guarda Municipal do Rio (GM-Rio) realizaram a\u00e7\u00f5es de ordenamento, fiscaliza\u00e7\u00e3o e controle de tr\u00e2nsito em toda a cidade, com foco nas zonas Sul e Central \u2014 regi\u00f5es que concentram o maior n\u00famero de blocos de rua \u2014, al\u00e9m do Samb\u00f3dromo, para garantir o cumprimento das normas durante os desfiles das escolas de samba.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Durante as opera\u00e7\u00f5es, agentes da SEOP apreenderam centenas de produtos irregulares, como bebidas diversas e garrafas de vidro, cuja venda \u00e9 proibida por quest\u00f5es de seguran\u00e7a.<\/span><\/p>\n<p><span style=\"font-weight: 400\">As equipes apreenderam tamb\u00e9m mais um crach\u00e1 de identifica\u00e7\u00e3o e um colete de ambulante que estavam sendo utilizados por terceiros n\u00e3o autorizados em um bloco na Zona Sul. O uso indevido desses itens \u00e9 proibido pelo regulamento dos ambulantes no Carnaval de Rua do Rio. As informa\u00e7\u00f5es ser\u00e3o encaminhadas \u00e0 Pol\u00edcia Civil para investiga\u00e7\u00e3o de poss\u00edvel comercializa\u00e7\u00e3o irregular da licen\u00e7a.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nas fiscaliza\u00e7\u00f5es de tr\u00e2nsito foram aplicadas 148 autua\u00e7\u00f5es, al\u00e9m de 66 remo\u00e7\u00f5es por estacionamento irregular.<\/span><\/p>\n<p><span style=\"font-weight: 400\">No domingo (02\/03), durante o desfile do Bloco Toca Raul, no Centro, guardas do Grupamento T\u00e1tico M\u00f3vel (GTM) conduziram um suspeito de praticar roubos, ap\u00f3s den\u00fancias dos foli\u00f5es. Com ele foram encontradas facas, tamb\u00e9m apreendidas e levadas para DP. Ao todo, as equipes da GM-Rio registraram tr\u00eas condu\u00e7\u00f5es para delegacia. Tamb\u00e9m houve um registro de crian\u00e7a perdida que foi devolvida aos respons\u00e1veis em um bloco da Barra da Tijuca.\u00a0 Os guardas municipais ainda atuaram na conten\u00e7\u00e3o de 27 princ\u00edpios de tumulto e auxiliaram 21 pessoas que tiveram algum tipo de mal s\u00fabito.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Link para fotos: \u200b<\/span><span style=\"font-weight: 400\">https:\/\/abrir.link\/YFzyD<\/span><\/p>\n<p><b>CET-RIO\u00a0<\/b><\/p>\n<p><b>Interdi\u00e7\u00f5es para os desfiles e rotas alternativas<\/b><\/p>\n<p><i><span style=\"font-weight: 400\">Ruas voltam a ser fechadas \u00e0s 19h e liberadas \u00e0s 7h30 dos dias subsequentes<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">As interdi\u00e7\u00f5es efetuadas para o desfile do Grupo da S\u00e9rie Ouro seguem mantidas, exceto as da Rua Frei Caneca e do Viaduto 31 de Mar\u00e7o, reabertas ao tr\u00e1fego \u00e0s 7h30 da manh\u00e3 de domingo (02\/03). As vias voltam a ser fechadas novamente \u00e0s 19h de cada dia de desfiles e liberadas \u00e0s 7h30 dos dias subsequentes.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ao longo desta segunda-feira (03\/03)\u00a0 e de ter\u00e7a-feira (04\/03), diversos blocos est\u00e3o programados para desfilar na regi\u00e3o central da Cidade.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nos dias de Carnaval, durante as interven\u00e7\u00f5es no tr\u00e2nsito para os desfiles no Samb\u00f3dromo, a \u00c1rea de Lazer da Pra\u00e7a da Cruz Vermelha e o estacionamento da Avenida Presidente Vargas para o com\u00e9rcio da SAARA, est\u00e3o suspensos.<\/span><\/p>\n<p><b>Alternativas de circula\u00e7\u00e3o<\/b><\/p>\n<p><span style=\"font-weight: 400\">Os ve\u00edculos vindos da Avenida Francisco Bicalho, sentido Centro, dever\u00e3o seguir pela Avenida Paulo de Frontin, Pra\u00e7a Condessa Paulo de Frontin, Rua Estrela e Rua Itapiru at\u00e9 o acesso ao T\u00fanel Martim de S\u00e1.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Os ve\u00edculos vindos da Pra\u00e7a da Bandeira, sentido Centro, devem acessar: Rua do Matoso, Rua Haddock Lobo, Avenida Paulo de Frontin, Rua Estrela, Rua Itapiru e, sob a sa\u00edda do T\u00fanel Santa B\u00e1rbara, seguir pelo T\u00fanel Martim de S\u00e1 at\u00e9 a Rua Riachuelo.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Os ve\u00edculos vindos da Avenida Brasil e da Ponte Rio-Niter\u00f3i, com destino ao Centro e Zona Sul, dever\u00e3o utilizar o T\u00fanel Marcello Alencar, exceto durante as madrugadas, quando houver deslocamento dos carros aleg\u00f3ricos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Os ve\u00edculos vindos da Pra\u00e7a da Bandeira, sentido Centro ou Botafogo, pelo T\u00fanel Santa B\u00e1rbara, dever\u00e3o seguir por: Rua do Matoso, Rua Haddock Lobo, Avenida Paulo de Frontin, Pra\u00e7a Condessa Paulo de Frontin, Rua Estrela, Rua Itapiru, Rua Dr. Agra e T\u00fanel Martim de S\u00e1, para o Centro. Para Botafogo, deve-se seguir o mesmo trajeto at\u00e9 a Rua Dr. Agra e pegar o retorno para o acesso ao T\u00fanel Santa B\u00e1rbara.<\/span><\/p>\n<p><b>Proibi\u00e7\u00e3o de estacionamento<\/b><\/p>\n<p><span style=\"font-weight: 400\">Para preservar a circula\u00e7\u00e3o de sa\u00edda dos carros aleg\u00f3ricos e pedestres, al\u00e9m dos locais onde j\u00e1 existe regulamenta\u00e7\u00e3o de proibi\u00e7\u00e3o, o estacionamento no entorno do Samb\u00f3dromo estar\u00e1 proibido \u00e0s 10h de quarta-feira, nas vias internas aos bloqueios e nas principais ruas e avenidas da regi\u00e3o central.<\/span><\/p>\n<p><b>Como chegar ao Samb\u00f3dromo<\/b><\/p>\n<p><b>METR\u00d4<\/b><\/p>\n<p><span style=\"font-weight: 400\">O p\u00fablico do setor par poder\u00e1 utilizar as esta\u00e7\u00f5es Cidade Nova, Est\u00e1cio e Pra\u00e7a Onze. E aqueles destinados ao setor \u00edmpar dever\u00e3o utilizar a esta\u00e7\u00e3o Central do Brasil.<\/span><\/p>\n<p><b>TREM<\/b><\/p>\n<p><span style=\"font-weight: 400\">Dever\u00e3o utilizar a esta\u00e7\u00e3o Central do Brasil.<\/span><\/p>\n<p><b>\u00d4NIBUS DE LINHAS REGULARES<\/b><\/p>\n<p><span style=\"font-weight: 400\">Mais de 50 linhas passam pela \u00e1rea do evento, vindas de diversas regi\u00f5es da cidade.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><strong>TRANSPORTES<\/strong><\/p>\n<p data-start=\"701\" data-end=\"817\"><strong data-start=\"101\" data-end=\"143\">Opera\u00e7\u00e3o especial para atender foli\u00f5es<\/strong><br data-start=\"143\" data-end=\"146\"\/>\u00d4nibus, BRT, VLT, Metr\u00f4 e Supervia funcionam em hor\u00e1rio estendido<\/p>\n<p data-start=\"213\" data-end=\"538\">A Secretaria Municipal de Transportes programou uma opera\u00e7\u00e3o especial para a circula\u00e7\u00e3o do p\u00fablico a caminho do Samb\u00f3dromo, no Centro, e da Estrada Intendente Magalh\u00e3es, na Zona Norte. \u00d4nibus, BRT, VLT, Metr\u00f4 e Supervia estar\u00e3o funcionando durante a madrugada, e t\u00e1xis operar\u00e3o em pontos de embarque no entorno do Samb\u00f3dromo.<\/p>\n<p data-start=\"540\" data-end=\"697\">A opera\u00e7\u00e3o dos servi\u00e7os noturnos de transporte de \u00f4nibus que atendem \u00e0 regi\u00e3o do Samb\u00f3dromo teve refor\u00e7o, com op\u00e7\u00e3o de integra\u00e7\u00e3o com o Terminal Gentileza:<\/p>\n<ul data-start=\"698\" data-end=\"880\">\n<li data-start=\"698\" data-end=\"755\">Linhas 104 \/ SN104 (Terminal Gentileza x S\u00e3o Conrado)<\/li>\n<li data-start=\"756\" data-end=\"880\">SN309 (Terminal Gentileza x Alvorada), com ponto na pista lateral da Avenida Presidente Vargas, sentido Pra\u00e7a da Bandeira.<\/li>\n<\/ul>\n<p data-start=\"882\" data-end=\"1132\">O BRT estar\u00e1 funcionando 24 horas durante o Carnaval. Para chegar ao Samb\u00f3dromo via Terminal Gentileza, o p\u00fablico pode fazer integra\u00e7\u00e3o com o VLT ou com as linhas 104 \/ SN104 (Terminal Gentileza x S\u00e3o Conrado) e SN309 (Terminal Gentileza x Alvorada).<\/p>\n<p data-start=\"1134\" data-end=\"1450\">Para a Estrada Intendente Magalh\u00e3es, na ida, o p\u00fablico deve utilizar as esta\u00e7\u00f5es Campinho ou Pinto Teles, que ter\u00e3o um hor\u00e1rio de funcionamento especial. O retorno, ap\u00f3s os desfiles, deve ser realizado pelo Terminal Paulo da Portela, a partir das 4h, ou pela esta\u00e7\u00e3o Madureira \u2013 Manaceia, que estar\u00e1 aberta 24 horas.<\/p>\n<p data-start=\"1452\" data-end=\"1585\">At\u00e9 ter\u00e7a-feira (04\/03) e tamb\u00e9m no s\u00e1bado (08\/03), o acesso dos t\u00e1xis \u00e0s \u00e1reas bloqueadas do Samb\u00f3dromo se dar\u00e1 da seguinte forma:<\/p>\n<ul data-start=\"1586\" data-end=\"1842\">\n<li data-start=\"1586\" data-end=\"1693\">In\u00edcio do bloqueio \u00e0s 19h; at\u00e9 as 20h, liberado para todos os t\u00e1xis com passageiros (para desembarque);<\/li>\n<li data-start=\"1694\" data-end=\"1770\">Das 20h at\u00e9 o fim do bloqueio: somente T\u00e1xi.Rio credenciado com QR Code;<\/li>\n<li data-start=\"1771\" data-end=\"1842\">T\u00e1xi especial para PCD pode acessar a \u00e1rea de bloqueio sem restri\u00e7\u00e3o.<\/li>\n<\/ul>\n<p data-start=\"1844\" data-end=\"2053\"><strong data-start=\"1844\" data-end=\"1861\">Setores Pares<\/strong><br data-start=\"1861\" data-end=\"1864\"\/>Ponto T\u00e1xi Rio (credenciados) \u2013 Rua Afonso Cavalcanti, esquina com a Rua Laura de Ara\u00fajo.<br data-start=\"1953\" data-end=\"1956\"\/><strong data-start=\"1956\" data-end=\"1975\">Setores \u00cdmpares<\/strong><br data-start=\"1975\" data-end=\"1978\"\/>Ponto de T\u00e1xi Comum \u2013 Rua Marqu\u00eas de Pombal, esquina com a Rua Frei Caneca.<\/p>\n<p data-start=\"2055\" data-end=\"2383\">Durante o Carnaval, o Metr\u00f4Rio funcionar\u00e1 at\u00e9 as 23h59 de quarta-feira (05\/03). Para o Desfile das Campe\u00e3s (08\/03), o funcionamento ser\u00e1 entre as 5h do dia 08\/03 (s\u00e1bado) e as 23h do dia 9\/03 (domingo). Para acessar o Samb\u00f3dromo, para os setores pares, o desembarque ser\u00e1 na esta\u00e7\u00e3o Pra\u00e7a Onze (concentra\u00e7\u00e3o nos Edif\u00edcios\u00a0dos Correios).<\/p>\n<p data-start=\"444\" data-end=\"904\">A Supervia preparou um esquema especial para garantir a mobilidade dos foli\u00f5es durante o Carnaval, com viagens extras ao longo do dia e durante as madrugadas. O atendimento ser\u00e1 realizado nos ramais de Japeri, Santa Cruz (incluindo Deodoro), Saracuruna e Belford Roxo. A Esta\u00e7\u00e3o Central do Brasil ficar\u00e1 aberta 24 horas at\u00e9 o \u00faltimo trem da quarta-feira (05\/03). Durante a madrugada, todas as outras esta\u00e7\u00f5es funcionar\u00e3o apenas para desembarque de passageiros.<\/p>\n<p data-start=\"906\" data-end=\"1302\">Entre s\u00e1bado (1\/03) e quarta-feira (05\/03), os trens funcionar\u00e3o com a grade de s\u00e1bado como refer\u00eancia para toda a opera\u00e7\u00e3o. Ser\u00e3o feitas viagens extras ao longo do dia, conforme a demanda, e haver\u00e1 partidas adicionais da Central do Brasil no fim da noite. Na quinta e sexta-feira p\u00f3s-Carnaval (06 e 07\/03), os trens circular\u00e3o conforme a grade de dias \u00fateis, com ajustes de acordo com a demanda.<\/p>\n<p><b>SA\u00daDE<\/b><\/p>\n<p><b>Postos m\u00e9dicos do Samb\u00f3dromo atendem 465 pessoas<\/b><\/p>\n<p><i><span style=\"font-weight: 400\">No total das tr\u00eas noites, foram 1.134 atendimentos com 81 remo\u00e7\u00f5es<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">Na terceira noite de desfiles no Samb\u00f3dromo, primeira do Grupo Especial, os seis postos m\u00e9dicos da Secretaria Municipal de Sa\u00fade (SMS) atenderam 465 pessoas das 19h de domingo (02\/03) at\u00e9 as 6h de segunda-feira (03\/03). Dessas, 29 precisaram ser transferidas para hospitais da rede. No total das tr\u00eas noites at\u00e9 o momento, foram 1.134 atendimentos com 81 remo\u00e7\u00f5es. A maior parte dos casos foi devido a traumas por quedas, cortes, entorses, intoxica\u00e7\u00e3o ex\u00f3gena por bebida alco\u00f3lica em excesso e mal-estar e pico de press\u00e3o devido ao esfor\u00e7o do desfile.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Envolvendo 200 profissionais e 16 ambul\u00e2ncias com suporte avan\u00e7ado (UTI m\u00f3vel), o esquema especial da SMS no samb\u00f3dromo apresenta estrutura com 32 leitos, sendo sete de suporte avan\u00e7ado, e 12 poltronas de hidrata\u00e7\u00e3o.<\/span><\/p>\n<p><b>Vigil\u00e2ncia em Sa\u00fade<\/b><\/p>\n<p><span style=\"font-weight: 400\">Com o objetivo de detectar poss\u00edveis eventos de relev\u00e2ncia para sa\u00fade p\u00fablica, a\u00a0 Superintend\u00eancia de Vigil\u00e2ncia em Sa\u00fade segue atuando no Samb\u00f3dromo com uma equipe do Centro de Informa\u00e7\u00f5es Estrat\u00e9gicas de Vigil\u00e2ncia em Sa\u00fade (CIEVS-Rio) monitorando os atendimentos nos postos m\u00e9dicos. No terceiro dia de desfiles, foram identificadas 17 ocorr\u00eancias de notifica\u00e7\u00e3o compuls\u00f3ria, por\u00e9m sem registro de doen\u00e7as ou agravos de interesse epidemiol\u00f3gico.<\/span><\/p>\n<p><b>A\u00e7\u00f5es da Vigil\u00e2ncia Sanit\u00e1ria<\/b><\/p>\n<p><span style=\"font-weight: 400\">As equipes do Instituto Municipal de Vigil\u00e2ncia Sanit\u00e1ria, Vigil\u00e2ncia de Zoonoses e Inspe\u00e7\u00e3o Agropecu\u00e1ria (Ivisa-Rio) fizeram, nesta terceira noite de desfiles, 57 visitas a servi\u00e7os de alimenta\u00e7\u00e3o, postos de atendimento m\u00e9dico, ambul\u00e2ncias, estandes e instala\u00e7\u00f5es no Samb\u00f3dromo. Foram lavrados tr\u00eas autos de infra\u00e7\u00e3o por falta de asseio na manipula\u00e7\u00e3o de alimentos ou nas instala\u00e7\u00f5es, medicamentos ou insumos com prazo de validade expirado, e medicamentos e\/ou maquiagens sem registro na Anvisa. Ao todo, 42 amostras de alimentos foram coletadas para an\u00e1lise pelo Laborat\u00f3rio Municipal de Sa\u00fade P\u00fablica (LASP).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Tamb\u00e9m foram afixadas 45 placas adesivadas com informa\u00e7\u00f5es sobre a legisla\u00e7\u00e3o referente \u00e0s restri\u00e7\u00f5es de fumo em ambientes de uso coletivo total ou parcialmente fechados.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b>COMLURB<\/b><\/p>\n<p><b>Na primeira noite do Grupo Especial, quantidade de res\u00edduos supera 67 toneladas<\/b><\/p>\n<p><i><span style=\"font-weight: 400\">Opera\u00e7\u00e3o de Carnaval mobiliza 8.500 garis em todos os pontos de folia da cidade<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">A primeira noite de desfiles das grandes escolas de samba do Grupo Especial, neste domingo (02\/03), resultou na remo\u00e7\u00e3o de 67,6 toneladas de res\u00edduos, sendo 42 toneladas da \u00e1rea interna,\u00a0 6,8 toneladas de materiais potencialmente recicl\u00e1veis,\u00a0 al\u00e9m dos 18,8 toneladas de res\u00edduos na parte externa\u00a0 do Samb\u00f3dromo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m disso, os blocos de rua que se apresentaram no domingo geraram 104,3 toneladas de res\u00edduos. Entre eles, destacaram-se o bloco Cord\u00e3o do Boitat\u00e1, com 12,7 toneladas; o bloco Areia, com 9,54 toneladas; e o Simpatia \u00e9 Quase Amor, com 8,5 toneladas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Os desfiles na Intendente Magalh\u00e3es, na Avenida Chile, e nos bailes populares realizados nos bairros geraram 131 toneladas de res\u00edduos no domingo.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Para garantir a limpeza eficiente, a Comlurb mobilizou cerca de 8.500 garis em todos os pontos de festa, incluindo o Samb\u00f3dromo, blocos de rua, Intendente Magalh\u00e3es e bailes populares. A opera\u00e7\u00e3o de limpeza conta com mais de 200 ve\u00edculos motorizados e 12.500 cont\u00eaineres de diferentes capacidades (240 litros e 1.200 litros) para o descarte correto dos res\u00edduos pelos foli\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A megaopera\u00e7\u00e3o de limpeza da Comlurb ocorre antes, durante e ap\u00f3s a passagem dos blocos e escolas de samba, abrangendo as vias principais, as ruas de acesso e adjacentes, com servi\u00e7os de varri\u00e7\u00e3o mecanizada, lavagem, esvaziamento de papeleiras e cont\u00eaineres e remo\u00e7\u00e3o de res\u00edduos. Este ano, a Companhia contou com 20 mil litros de sab\u00e3o e 5 mil litros de ess\u00eancia de eucalipto, mais que o dobro da quantidade utilizada no ano passado. Esses produtos s\u00e3o aplicados ap\u00f3s a limpeza hidr\u00e1ulica e nos pulverizadores, especialmente nas \u00e1reas de banheiros qu\u00edmicos, proporcionando um ambiente mais agrad\u00e1vel para os foli\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A Comlurb tamb\u00e9m realiza a limpeza dos postos m\u00e9dicos instalados nas \u00e1reas de desfile dos megablocos, no Centro, e dos quatro postos m\u00e9dicos do Samb\u00f3dromo, com o apoio de dois garis em cada unidade.<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u00a0<\/span><b>ASSIST\u00caNCIA SOCIAL\u00a0<\/b><\/p>\n<p><b>SMAS distribui 1.254 pulseiras de identifica\u00e7\u00e3o no primeiro dia de desfiles do Grupo Especial<\/b><\/p>\n<p><i><span style=\"font-weight: 400\">Espa\u00e7o de Conviv\u00eancia recebeu filhos de ambulantes que trabalham no Carnaval<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">A Secretaria Municipal de Assist\u00eancia Social (SMAS) seguiu firme na miss\u00e3o de proteger crian\u00e7as e adolescentes no Carnaval carioca. No domingo (02\/03), primeiro dia de desfiles do Grupo Especial, 1.254 crian\u00e7as e adolescentes receberam pulseiras de identifica\u00e7\u00e3o nos principais pontos da folia.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A distribui\u00e7\u00e3o foi realizada nos seguintes locais:<\/span><\/p>\n<p><span style=\"font-weight: 400\">Marqu\u00eas de Sapuca\u00ed (Grupo Especial) \u2013 149 pulseiras<\/span><\/p>\n<p><span style=\"font-weight: 400\">Av. Intendente Magalh\u00e3es (Blocos de Enredo) \u2013 500 pulseiras<\/span><\/p>\n<p><span style=\"font-weight: 400\">Simpatia \u00e9 Quase Amor \u2013 230 pulseiras<\/span><\/p>\n<p><span style=\"font-weight: 400\">Parque Realengo Susana Naspolini \u2013 375 pulseiras<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m disso, no Espa\u00e7o de Conviv\u00eancia, onde filhos e filhas de at\u00e9 12 anos de ambulantes que trabalham no Carnaval recebem cuidado, alimenta\u00e7\u00e3o e atividades recreativas, foram atendidas 24 crian\u00e7as. A a\u00e7\u00e3o \u00e9 realizada no EDI Rachel de Queiroz, vizinho ao Samb\u00f3dromo. Na Intendente Magalh\u00e3es, no Simpatia \u00e9 Quase Amor e no Parque de Realengo, n\u00e3o houve ades\u00e3o ao servi\u00e7o.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Essas iniciativas fazem parte da campanha da SMAS no Carnaval: \u201cRespeite o meu samba, a inf\u00e2ncia e os nossos direitos: prote\u00e7\u00e3o \u00e9 o bloco de geral\u201d.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b>MULHERES<\/b><\/p>\n<p><b>N\u00famero de profissionais especializadas em acolhimento a v\u00edtimas de ass\u00e9dio e viol\u00eancia no Carnaval triplicou este ano<\/b><\/p>\n<p><i><span style=\"font-weight: 400\">Hoje, s\u00e3o 270 mobilizadoras atuando. Em 2024, eram 88<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">A Secretaria Especial de Pol\u00edticas para Mulheres e Cuidados da Prefeitura do Rio realizou, domingo (02\/03), dois atendimentos na cidade. As equipes da campanha Carnaval Mais Seguro para as Mulheres est\u00e3o na Sapuca\u00ed, na Estrada Intendente Magalh\u00e3es, Zona Norte, e nos principais blocos. O objetivo \u00e9 apoiar foli\u00e3s, turistas e trabalhadoras, al\u00e9m de promover conscientiza\u00e7\u00e3o sobre viol\u00eancia e importuna\u00e7\u00e3o sexual. A secretaria triplicou o n\u00famero de profissionais especializadas para oferecer acolhimento e suporte imediato \u00e0s mulheres em casos de ass\u00e9dio ou de viol\u00eancia e tamb\u00e9m encaminhamento emergencial, por meio de uma parceria com a L\u2019Or\u00e9al Paris. Ano passado, eram 88 mobilizadoras; este ano, s\u00e3o 270.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b>MEIO AMBIENTE<\/b><\/p>\n<p><b>Folia Verde chega \u00e0 marca de 11 toneladas de res\u00edduos s\u00f3lidos coletados<\/b><\/p>\n<p><i><span style=\"font-weight: 400\">No Samb\u00f3dromo, um espa\u00e7o interativo recebe os foli\u00f5es para a\u00e7\u00f5es educativas sobre sustentabilidade<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">A Secretaria Municipal de Meio Ambiente e Clima (SMAC) continua com suas iniciativas de educa\u00e7\u00e3o ambiental durante o Carnaval atrav\u00e9s da campanha Folia Verde, levando a\u00e7\u00f5es de conscientiza\u00e7\u00e3o e sustentabilidade para os principais polos da folia. Com coleta e separa\u00e7\u00e3o de res\u00edduos na Sapuca\u00ed e blocos de rua, a SMAC j\u00e1 contabiliza 11 toneladas reunidas desde a \u00faltima sexta-feira (28\/03).\u00a0<\/span><\/p>\n<p><b>Sapuca\u00ed Sustent\u00e1vel<\/b><\/p>\n<p><span style=\"font-weight: 400\">Na noite de abertura dos desfiles do Grupo Especial, a Secret\u00e1ria de Meio Ambiente e Clima, Tain\u00e1 de Paula, entregou para os dirigentes da Rio Carnaval o Selo Folia Verde, que verifica o maior espet\u00e1culo da Terra como um espet\u00e1culo sustent\u00e1vel.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u2013 A ideia \u00e9 que a gente consiga reduzir a produ\u00e7\u00e3o de res\u00edduos e elimine o impacto no Carnaval da Sapuca\u00ed, gerando emprego e renda, e trazendo melhorias, como qualidade de vida n\u00e3o s\u00f3 para o Carnaval, mas para milhares de pessoas, milhares de fam\u00edlias que extraem dessa festa o seu sustento, o seu trabalho \u2013 comentou a secret\u00e1ria Tain\u00e1 de Paula.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m disso, o p\u00fablico aproveitou os estandes distribu\u00eddos pelo Samb\u00f3dromo, onde um espa\u00e7o interativo recebe os foli\u00f5es para atividades educativas e informa\u00e7\u00f5es sobre as a\u00e7\u00f5es da SMAC em prol da sustentabilidade no Carnaval.<\/span><\/p>\n<p><b>Blocos pelo Rio: foli\u00f5es conscientes, cidade mais limpa<\/b><\/p>\n<p><span style=\"font-weight: 400\">Os profissionais de coleta de res\u00edduos percorreram blocos de rua, incentivando a separa\u00e7\u00e3o correta de res\u00edduos e distribuindo materiais informativos sobre a import\u00e2ncia da reciclagem. A atividade contou com a participa\u00e7\u00e3o do Centro de Educa\u00e7\u00e3o Ambiental (CEA), com integrantes interagindo com os foli\u00f5es por meio de atividades l\u00fadicas e educativas sobre temas como descarte respons\u00e1vel, consumo consciente e preserva\u00e7\u00e3o da natureza.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Neste domingo (02\/03), receberam o Selo os blocos Divinas Tretas; o Cord\u00e3o do Boitat\u00e1; o Largo o Machadinho, S\u00f3 N\u00e3o Largo O Suquinho e o Bloco Arteiros da Gl\u00f3ria.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A campanha Folia Verde refor\u00e7a o compromisso da SMAC em construir um Rio de Janeiro mais verde e sustent\u00e1vel.<\/span><\/p>\n<p><b>CONSERVA\u00c7\u00c3O<\/b><\/p>\n<p><b>Equipes de prontid\u00e3o para manter as galerias de escoamento limpas<\/b><\/p>\n<p><i><span style=\"font-weight: 400\">Abertura do Grupo Especial ocorreu sem emerg\u00eancias na \u00e1rea da conserva\u00e7\u00e3o<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">A Coordenadoria Geral de Opera\u00e7\u00f5es Especiais, da Secretaria Municipal de Conserva\u00e7\u00e3o e Servi\u00e7os P\u00fablicos, limpou 46 ralos e desobstruiu os ramais da Marqu\u00eas de Sapuca\u00ed, ap\u00f3s a terceira noite de desfiles. N\u00e3o houve nenhum acionamento de emerg\u00eancia durante a madrugada.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Link de fotos: https:\/\/we.tl\/t-x26b13xtGH<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b>DEFESA DO CONSUMIDOR<\/b><\/p>\n<p><b>Procon fiscaliza mais 21 estabelecimentos na Sapuca\u00ed<\/b><\/p>\n<p><i><span style=\"font-weight: 400\">Nove deles receberam instru\u00e7\u00f5es para adequa\u00e7\u00f5es<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">No primeiro dia do desfile do Grupo Especial, neste domingo (2), a Secretaria de Prote\u00e7\u00e3o e Defesa do Consumidor, por meio do Procon Carioca, fiscalizou mais 21 estabelecimentos na Sapuca\u00ed. Nove deles receberam instru\u00e7\u00f5es para adequa\u00e7\u00f5es. Entre os problemas encontrados, estavam: falta de acessibilidade para pessoas com defici\u00eancias, hor\u00e1rio de abertura, identifica\u00e7\u00e3o no armazenamento e manipula\u00e7\u00e3o de alimentos, placas de sinaliza\u00e7\u00e3o obrigat\u00f3rias e certificados. Nos tr\u00eas dias de desfiles, os fiscais do Procon Carioca realizaram 75 fiscaliza\u00e7\u00f5es no total.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b>PROGRAMA\u00c7\u00c3O\u00a0<\/b><\/p>\n<p><b>SEGUNDA (03\/03)\u00a0<\/b><\/p>\n<p><b>Desfiles na Marqu\u00eas de Sapuca\u00ed\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">Os desfiles das escolas do Grupo Especial continuam nesta segunda-feira (03\/03) e na ter\u00e7a-feira (04\/03), com as agremia\u00e7\u00f5es de elite do Carnaval carioca, incluindo a campe\u00e3 de 2024, Acad\u00eamicos do Viradouro.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b>GRUPO ESPECIAL<\/b><\/p>\n<p><b>SEGUNDA, 03\/03 (Grupo Especial) <\/b><\/p>\n<p><span style=\"font-weight: 400\">Unidos da Tijuca \u2013 22h<\/span><\/p>\n<p><span style=\"font-weight: 400\">Beija-Flor \u2013 entre 23h20 e 23h30<\/span><\/p>\n<p><span style=\"font-weight: 400\">Salgueiro \u2013 entre 00:40h e 1h<\/span><\/p>\n<p><span style=\"font-weight: 400\">Vila Isabel \u2013 entre 2h e 2h30<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b>Terreir\u00e3o do Samba\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">Hoje (03\/03) \u00e9 dia de Ferrugem liderar a programa\u00e7\u00e3o do Terreir\u00e3o, que inclui tamb\u00e9m Grupo no Lance, Coisa S\u00e9ria, Yan e DJs. O p\u00fablico vai poder curtir shows de \u00edcones do samba, al\u00e9m de destaques da nova gera\u00e7\u00e3o. Tudo isso a pre\u00e7o popular: R$ 20 (meia-entrada ou entrada solid\u00e1ria, com 1kg de alimento n\u00e3o perec\u00edvel).<\/span><\/p>\n<p><span style=\"font-weight: 400\">Os port\u00f5es da casa mais democr\u00e1tica e ic\u00f4nica do samba abrem sempre \u00e0s 20h. Para facilitar, o foli\u00e3o pode antecipar a compra do seu ingresso pela plataforma www.bilheteriadigital.com.br, mas se preferir pode comprar na hora tamb\u00e9m. Hor\u00e1rio de funcionamento da bilheteria do Terreir\u00e3o: nos dias de eventos, das 17h \u00e0s 3h.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b>Segunda-feira | 03\/03<\/b><\/p>\n<p><span style=\"font-weight: 400\">20h \u2013 21h30 \u2013 DJ FM O Dia\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">21h30 \u2013 23h \u2013 Grupo no Lance<\/span><\/p>\n<p><span style=\"font-weight: 400\">23h30 \u2013 0h40 \u2013 Coisa S\u00e9ria<\/span><\/p>\n<p><span style=\"font-weight: 400\">01h10 \u2013 2h20 \u2013 Yan<\/span><\/p>\n<p><span style=\"font-weight: 400\">02h50 \u2013 4h20 \u2013 Ferrugem<\/span><\/p>\n<p><span style=\"font-weight: 400\">04h20 \u2013 5h \u2013 DJ FM O Dia<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<p><b>SERVI\u00c7O:<\/b><\/p>\n<p><span style=\"font-weight: 400\">Terreir\u00e3o do Samba<\/span><\/p>\n<p><span style=\"font-weight: 400\">Local: Rua Benedito Hip\u00f3lito 66, Pra\u00e7a Onze<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ingressos: a partir de R$ 20, \u00e0 venda pelo site e <\/span><span style=\"font-weight: 400\">www.bilheteriadigital.com.br<\/span><span style=\"font-weight: 400\"> e na bilheteria do terreir\u00e3o<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<p><b>Bailes da Cinel\u00e2ndia<\/b><\/p>\n<p><span style=\"font-weight: 400\">Muito al\u00e9m dos blocos de rua e dos desfiles apote\u00f3ticos da Sapuca\u00ed, h\u00e1 outra op\u00e7\u00e3o de folia que j\u00e1 virou tradi\u00e7\u00e3o na cidade: os bailes da Cinel\u00e2ndia. No palco armado diante das escadarias da C\u00e2mara Municipal, artistas diversos e Orquestra fazem a festa com uma sele\u00e7\u00e3o de temas carnavalescos e marchinhas cl\u00e1ssicas durante os quatro dias de programa\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400\">O Concurso Foli\u00e3o Original desta segunda ser\u00e1 na categoria originalidade\/palha\u00e7o, e o Baile da Cinel\u00e2ndia ter\u00e1 Orquestra Tupy, Tom da Bahia, Vladimir Cabanas e muito mais.\u00a0<\/span><\/p>\n<p><b>Confira a programa\u00e7\u00e3o do tradicional Baile da Cinel\u00e2ndia:\u00a0<\/b><\/p>\n<p>\u00a0<\/p>\n<p><b>3 DE MAR\u00c7O DE 2025 \u2013 SEGUNDA-FEIRA<\/b><\/p>\n<p><span style=\"font-weight: 400\">CATEGORIA ORIGINALIDADE\/PALHA\u00c7O<\/span><\/p>\n<p><span style=\"font-weight: 400\">13h \/15h \u2013 Inscri\u00e7\u00f5es\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <\/span><\/p>\n<p><span style=\"font-weight: 400\">16h30\/18h \u2013 In\u00edcio dos Concursos\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">19h\/19h30 \u2013 Resultados<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b>BAILE DA CINEL\u00c2NDIA 2025<\/b><\/p>\n<p><span style=\"font-weight: 400\">Hor\u00e1rio\u00a0 <\/span> <span style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Artista<\/span><\/p>\n<p><span style=\"font-weight: 400\">19h30 <\/span> <span style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 In\u00edcio Dj\/Locutor<\/span><\/p>\n<p><span style=\"font-weight: 400\">20h \u2013 20h30<\/span> <span style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Orquestra Tupy<\/span><\/p>\n<p><span style=\"font-weight: 400\">20h30 \u2013 20h50<\/span> <span style=\"font-weight: 400\">Osmar do Bregue<\/span><\/p>\n<p><span style=\"font-weight: 400\">20h50 \u2013 21h10<\/span> <span style=\"font-weight: 400\">Alberto Gino<\/span><\/p>\n<p><span style=\"font-weight: 400\">21h10 \u2013 21h30<\/span> <span style=\"font-weight: 400\">Tom da Bahia<\/span><\/p>\n<p><span style=\"font-weight: 400\">21h30 \u2013 21h50<\/span> <span style=\"font-weight: 400\">Ellen de Lima<\/span><\/p>\n<p><span style=\"font-weight: 400\">21h50 \u2013 22h10<\/span> <span style=\"font-weight: 400\">Selma Costa<\/span><\/p>\n<p><span style=\"font-weight: 400\">22h10 \u2013 22h30<\/span> <span style=\"font-weight: 400\">Intervalo Locutor\/Dj<\/span><\/p>\n<p><span style=\"font-weight: 400\">22h30 \u2013 22h50<\/span> <span style=\"font-weight: 400\">Marcio Gomes<\/span><\/p>\n<p><span style=\"font-weight: 400\">22h50 \u2013 23h10<\/span> <span style=\"font-weight: 400\">Gottsha<\/span><\/p>\n<p><span style=\"font-weight: 400\">23h10 \u2013 23h30<\/span> <span style=\"font-weight: 400\">S\u00f4nia Delphino<\/span><\/p>\n<p><span style=\"font-weight: 400\">23h30 \u2013 23h50<\/span> <span style=\"font-weight: 400\">Paulo Nunes<\/span><\/p>\n<p><span style=\"font-weight: 400\">23h50 \u2013 00h10<\/span> <span style=\"font-weight: 400\">Reginaldo Bessa<\/span><\/p>\n<p><span style=\"font-weight: 400\">00h10 \u2013 00h30<\/span> <span style=\"font-weight: 400\">Luis Cesar<\/span><\/p>\n<p><span style=\"font-weight: 400\">00h30 \u2013 00h50<\/span> <span style=\"font-weight: 400\">Wadimir Cabanas<\/span><\/p>\n<p data-start=\"906\" data-end=\"1302\"><span style=\"font-weight: 400\">00h40 \u2013 01h \u00a0 <\/span> <span style=\"font-weight: 400\">Encerramento Orquestra Tupy<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b>Blocos de Embalo e de Enredo da Avenida Chile e Intendente Magalh\u00e3es<\/b><\/p>\n<p><span style=\"font-weight: 400\">Fugindo dos roteiros tradicionais, o Carnaval carioca ganha refor\u00e7o com uma programa\u00e7\u00e3o variada pelo Centro do Rio, com desfiles na Avenida Chile, e na Zona Norte, na conhecida Intendente Magalh\u00e3es.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><b>Confira abaixo a ordem dos desfiles da Intendente Magalh\u00e3es:<\/b><\/p>\n<p>\u00a0<\/p>\n<p><b><i>S\u00e9rie Prata: desfiles em 2, 3 e 4 de mar\u00e7o<\/i><\/b><\/p>\n<p><b>Segunda, 3 de mar\u00e7o<\/b><\/p>\n<p><span style=\"font-weight: 400\">Avalia\u00e7\u00e3o \u2013 18h Novo Imp\u00e9rio\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">18h30 Dif\u00edcil \u00e9 o Nome<\/span><\/p>\n<p data-start=\"906\" data-end=\"1302\"><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<p><b>Desfiles<\/b><\/p>\n<p><span style=\"font-weight: 400\">20h \u2013 Independente de Olaria 2<\/span><\/p>\n<p><span style=\"font-weight: 400\">20h40 \u2013 Flor da Mina Andara\u00ed\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">21h20 \u2013 Imp\u00e9rio de Nova Igua\u00e7u\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">22h \u2013 Flamangua\u00e7a 2<\/span><\/p>\n<p><span style=\"font-weight: 400\">22h40 \u2013 Engenho da Rainha<\/span><\/p>\n<p><span style=\"font-weight: 400\">23h20 \u2013 Santa Cruz\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">00h \u2013 Vizinha Faladeira\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">00h40 \u2013 Rocinha\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">1h20 \u2013 Le\u00e3o Nova Igua\u00e7u\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">2h \u2013 Alegria de Copacabana<\/span><\/p>\n<p data-start=\"906\" data-end=\"1302\"><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<p><b>Confira abaixo a ordem dos desfiles da Av. Chile:<\/b><\/p>\n<p><span style=\"font-weight: 400\">Desfiles de Blocos de Embalo \u2013 LIBERJ<\/span><\/p>\n<p><span style=\"font-weight: 400\">16h \u2013 Badalo de Sta Teresa\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">16h30 \u2013 Foli\u00f5es do Rio\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">17h \u2013 Cervejeiro\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">17h30 \u2013 Engata no Centro\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">18h \u2013 Vinil Social\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">18h30 \u2013 Bo\u00eamios S\u00e3o Crist\u00f3v\u00e3o\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">19h \u2013 Xod\u00f3 da Piedade\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">19h30 \u2013 Confraria da Bebidinha<\/span><\/p>\n<p><span style=\"font-weight: 400\">21h \u2013 Cacique de Ramos<\/span><\/p>\n<p data-start=\"906\" data-end=\"1302\"><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<p><b>Blocos de Rua<\/b><\/p>\n<p><b>48 blocos desfilar\u00e3o na segunda-feira de Carnaval<\/b><\/p>\n<p data-start=\"906\" data-end=\"1302\"><span style=\"font-weight: 400\">A segunda-feira de Carnaval (03\/03) conta com <\/span><b>48 blocos <\/b><span style=\"font-weight: 400\">em todas as zonas da cidade. Os destaques da manh\u00e3: Vem C\u00e1 Minha Flor, na Avenida Marechal C\u00e2mara, no Centro; Que Pena Amor, na Pra\u00e7a M\u00e1rio Lago; e Sargento Pimenta, cl\u00e1ssico que junta Beatles e Carnaval, no Aterro, e comemora 15 anos, homenageando Elis Regina. De tarde, A Rocha da G\u00e1vea faz a alegria na Lagoa, na Zona Sul.<\/span><\/p>\n<p data-start=\"371\" data-end=\"796\"><strong data-start=\"371\" data-end=\"386\">PROGRAMA\u00c7\u00c3O<\/strong><br data-start=\"386\" data-end=\"389\"\/>Para ver a programa\u00e7\u00e3o completa dos blocos, com data, hor\u00e1rio e percurso, basta baixar o aplicativo\u00a0<strong data-start=\"489\" data-end=\"511\">Blocos do Rio 2025<\/strong>, dispon\u00edvel em todas as plataformas digitais. A ferramenta \u00e9 gratuita e funciona por geolocaliza\u00e7\u00e3o. Para mais informa\u00e7\u00f5es, basta acessar o site\u00a0<strong data-start=\"657\" data-end=\"678\">carnavalderua.rio<\/strong>, que, al\u00e9m da programa\u00e7\u00e3o, apresenta not\u00edcias, galerias e informa\u00e7\u00f5es mais atualizadas do Carnaval de Rua Rio 2025.<\/p>\n<p>\u00a0<\/p>\n<p data-start=\"0\" data-end=\"29\"><strong data-start=\"0\" data-end=\"29\">Recomenda\u00e7\u00f5es importantes<\/strong><\/p>\n<ul data-start=\"31\" data-end=\"1298\" data-is-last-node=\"\">\n<li data-start=\"31\" data-end=\"96\"><strong data-start=\"33\" data-end=\"79\">Use preferencialmente o transporte p\u00fablico<\/strong>\u00a0(trem ou metr\u00f4).<\/li>\n<li data-start=\"97\" data-end=\"202\"><strong data-start=\"99\" data-end=\"202\">Se for embarcar no Aeroporto Santos Dumont e na Rodovi\u00e1ria do Rio, procure antecipar a sua chegada.<\/strong><\/li>\n<li data-start=\"203\" data-end=\"307\"><strong data-start=\"205\" data-end=\"244\">Evite circular de carro nas regi\u00f5es<\/strong>\u00a0por onde haver\u00e1 deslocamento de blocos e de carros aleg\u00f3ricos.<\/li>\n<li data-start=\"308\" data-end=\"446\"><strong data-start=\"310\" data-end=\"340\">Busque rotas alternativas.<\/strong>\u00a0H\u00e1 um grande n\u00famero de interdi\u00e7\u00f5es pela cidade, com movimenta\u00e7\u00e3o de carros aleg\u00f3ricos, blocos e cortejos.<\/li>\n<li data-start=\"447\" data-end=\"614\"><strong data-start=\"449\" data-end=\"529\">Nos dias de Carnaval, a Prefeitura do Rio monitora a concentra\u00e7\u00e3o de p\u00fablico<\/strong>\u00a0na regi\u00e3o da Lapa, contudo n\u00e3o est\u00e3o previstas interdi\u00e7\u00f5es ao tr\u00e1fego na localidade.<\/li>\n<li data-start=\"615\" data-end=\"756\"><strong data-start=\"617\" data-end=\"670\">Respeite os locais de proibi\u00e7\u00e3o de estacionamento<\/strong>\u00a0e fique atento aos hor\u00e1rios de restri\u00e7\u00e3o, pois reboques est\u00e3o circulando pela cidade.<\/li>\n<li data-start=\"757\" data-end=\"916\"><strong data-start=\"759\" data-end=\"884\">Para garantir a seguran\u00e7a dos foli\u00f5es, informamos que a travessia deve ser realizada exclusivamente na faixa de pedestres<\/strong>\u00a0e sempre com aten\u00e7\u00e3o redobrada.<\/li>\n<li data-start=\"917\" data-end=\"1053\"><strong data-start=\"919\" data-end=\"1002\">\u00c9 muito importante que sejam respeitadas as orienta\u00e7\u00f5es dos agentes de tr\u00e2nsito<\/strong>\u00a0e tamb\u00e9m de toda a sinaliza\u00e7\u00e3o implantada na \u00e1rea.<\/li>\n<li data-start=\"1054\" data-end=\"1298\" data-is-last-node=\"\"><strong data-start=\"1056\" data-end=\"1176\">Moradores que possuam carro particular e vaga de garagem e que necessitem acessar a regi\u00e3o interditada do Samb\u00f3dromo<\/strong>\u00a0devem faz\u00ea-lo pelo Largo do Est\u00e1cio, sempre portando comprovante de resid\u00eancia (conta de luz, g\u00e1s, telefone) em seu nome.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>             <!-- Compartilhe ---><\/p>\n<p>\t\t\t <!-- TAGS --><\/p>\n<section class=\"category-tags\">\n<div class=\"marcacao-category\">\n<article class=\"category-post\">\n<p>Categoria: <\/p>\n<\/article>\n<li>3 de mar\u00e7o de 2025<\/li><\/div>\n<article class=\"tags\">\n\t\t\t\t\tMarca\u00e7\u00f5es: Blocos de Rua Carnaval Grupo Especial Prefeitura do Rio Samb\u00f3dromo sa\u00fade Transportes<br \/><\/article>\n<\/section>\n<p>            <!-- Mais Not&iacute;cias --><\/p>\n<p>\t\t<!-- Conte&uacute;do SIDEBAR --><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Desfile da Unidos de Padre Miguel, durante o primeiro dia das escolas de samba do Grupo Especial &#8211; Marcos de Paula\/Prefeitura Quatro escolas abriram o primeiro dia do Grupo Especial, neste domingo (02\/03), na Marqu\u00eas de Sapuca\u00ed. A Unidos de Padre Miguel, campe\u00e3 da S\u00e9rie Ouro no ano passado, foi a primeira a entrar na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-33647","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=33647"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33647\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=33647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=33647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=33647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}