{"id":34623,"date":"2025-03-25T11:22:08","date_gmt":"2025-03-25T14:22:08","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/03\/25\/palco-soul-promete-encontros-memoraveis-no-campao-cultural-com-grandes-nomes-da-mpb-soul-e-samba\/"},"modified":"2025-03-25T11:22:08","modified_gmt":"2025-03-25T14:22:08","slug":"palco-soul-promete-encontros-memoraveis-no-campao-cultural-com-grandes-nomes-da-mpb-soul-e-samba","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/03\/25\/palco-soul-promete-encontros-memoraveis-no-campao-cultural-com-grandes-nomes-da-mpb-soul-e-samba\/","title":{"rendered":"Palco Soul promete encontros memor\u00e1veis no Camp\u00e3o Cultural com grandes nomes da MPB, Soul e Samba"},"content":{"rendered":"<p><\/p>\n<div>\n<p>O Camp\u00e3o Cultural \u2013 III Festival de Arte, Diversidade e Cidadania acontecer\u00e1 na Capital sul-mato-grossense entre os dias 27 e 30 de mar\u00e7o e entre 4 e 6 de abril, contando com intensa programa\u00e7\u00e3o em diversos locais e atra\u00e7\u00f5es art\u00edsticas espalhadas pela cidade. O Festival \u00e9 realizado pelo Governo de Mato Grosso do Sul, por meio da FCMS (Funda\u00e7\u00e3o de Cultura de Mato Grosso do Sul).\u00a0<\/p>\n<p>Um dos destaques da programa\u00e7\u00e3o ser\u00e1 o Palco Soul, que nos dias 29 e 30 de mar\u00e7o, na Pra\u00e7a do R\u00e1dio, recebe grandes apresenta\u00e7\u00f5es, reunindo talentos da m\u00fasica em performances variadas e cheias de colabora\u00e7\u00f5es especiais.<\/p>\n<p>No s\u00e1bado, 29 de mar\u00e7o, a programa\u00e7\u00e3o come\u00e7a \u00e0s 18h com o show envolvente do Ultra Soul, que sobe ao palco ao lado de Aparecido. Em seguida, \u00e0s 20h, \u00e9 a vez da lend\u00e1ria Black Rio, com a cantora Thulla Melo. No domingo, 30 de mar\u00e7o, a noite ganha ainda mais brilho com a uni\u00e3o de Isabel Fillardis e Sandra de S\u00e1, que se apresentam juntas \u00e0s 19h.<\/p>\n<p>\u201cO Camp\u00e3o \u00e9 essa mistura de ritmos urbanos que levaremos para todos os cantos da cidade e nada mais emblem\u00e1tico que levar artistas como Black Rio, e Sandra S\u00e1 para o centro, para o palco da Pra\u00e7a do R\u00e1dio, com acesso da popula\u00e7\u00e3o e todos que queiram curtir uma boa m\u00fasica\u201d, enfatiza o diretor-presidente da Funda\u00e7\u00e3o de Cultura de Mato Grosso do Sul, Eduardo Mendes Pinto.<\/p>\n<p><b>Confira as atra\u00e7\u00f5es:<\/b><\/p>\n<p><b>Sandra de S\u00e1<\/b><\/p>\n<\/p>\n<p>Dona de uma personalidade marcante e um timbre de voz singular, Sandra de S\u00e1 interpretou can\u00e7\u00f5es que se tornaram verdadeiros hits da nossa m\u00fasica. Elas n\u00e3o apenas fazem parte de sua identidade, mas tamb\u00e9m retratam a realidade vivida, sempre com uma vis\u00e3o alegre e otimista.<\/p>\n<p>A proposta \u00e9 um show que passeia por diversos ritmos, da MPB, Soul e Samba ao Funk. Criado com muito amor e carinho, o espet\u00e1culo \u00e9 dirigido pela pr\u00f3pria Sandra de S\u00e1, que desfila sucessos inesquec\u00edveis de seu repert\u00f3rio, como \u201cRetratos e Can\u00e7\u00f5es\u201d, \u201cVale Tudo\u201d, \u201cJoga Fora\u201d, \u201cBye Bye Tristeza\u201d e \u201cOlhos Coloridos\u201d. Um show repleto de emo\u00e7\u00e3o e talento, que promete ser mais um grande sucesso.<\/p>\n<p><b>Banda Black Rio<\/b><\/p>\n<\/p>\n<p>A banda Black Rio se formou em 1977, sob o comando do conceituado saxofonista Oberdan Magalh\u00e3es. O seu in\u00edcio foi marcado pelo lan\u00e7amento do \u00e1lbum Maria Fuma\u00e7a que se tornou s\u00edmbolo do movimento Black Rio, do qual veio o nome da banda.\u00a0<\/p>\n<p>O hist\u00f3rico Maria Fuma\u00e7a apresenta faixas como Mr. Funky Samba, exaltando a fus\u00e3o do samba brasileiro com o funk setentista norte-americano, e de mesmo nome do \u00e1lbum, que foi tema da novela Locomotivas, da TV Globo, dando notoriedade \u00e0 banda na \u00e9poca.<\/p>\n<p>Em 1978, foi lan\u00e7ado o Gafieira Universal, impulsionado pela grande repercuss\u00e3o que o Maria Fuma\u00e7a teve com o p\u00fablico. A banda seguiu a est\u00e9tica do primeiro \u00e1lbum, adicionando vocais \u00e0 algumas de suas composi\u00e7\u00f5es, como Vidigal.<\/p>\n<p><b>Aparecido<\/b><\/p>\n<\/p>\n<p>Todo o groove e malemol\u00eancia das terras tupiniquins reverberadas em forma de m\u00fasica e bailado solto. Aparecido da Silva conduz com a eleg\u00e2ncia de um crooner jazz\u00edstico e o carisma de um bom malandro do samba, um baile recheado de brasilidade e swing.<\/p>\n<p>Homenagem a M\u00fasica Preta Brasileira \u00e9 o atual projeto com o Baile do Aparecido, com vers\u00f5es de sucessos de Tim Maia, Gil, Zeca Pagodinho, Djavan, Seu Jorge, Jorge Ben Jor, autorais e muito mais.<\/p>\n<p>Paulo Vinicius Aparecido da Silva, \u00e9 um cantor, ator e compositor brasileiro. Como ator, estudou na escola O Tablado e tamb\u00e9m se dedicou \u00e0 palha\u00e7aria, tendo ganho tr\u00eas festivais. Na m\u00fasica Aparecido come\u00e7ou sua carreira com a banda \u201cA La Fonseca\u201d, fazendo um tributo a Lula Queiroga. Como compositor, ele tem um disco gravado por Leandro L\u00e9o, que inclui uma m\u00fasica escrita em parceria com Maria Gad\u00fa.\u00a0<\/p>\n<p><b>Ultra Soul<\/b><\/p>\n<\/p>\n<p>A Ultra Soul foi criada por Sandro Coiado com o intuito de resgatar a m\u00fasica negra americana como a Soul Music, o Funk e o R&amp;B dos anos 70 e 80. A banda j\u00e1 acompanhou alguns artistas como: Ed Motta, L\u00e9o Maia, Vanessa Jackson, Dom Paulinho Lima, Edu Camargo, ambos do The Voice Brasil, entre outros.<\/p>\n<p>Estruturada com quatro vocais que revezam entre si, fazendo bel\u00edssimas apresenta\u00e7\u00f5es com espetaculares arranjos. H\u00e1 10 anos t\u00eam levado o melhor do Soul, Funk e R&amp;B em lugares como: Virada Cultural Paulista, Bourbon Street, Charles Edward, Festival de Inverno, e tamb\u00e9m em outros estados como Bahia, Minas Gerais, Esp\u00edrito Santo, Rio de Janeiro e em v\u00e1rias cidades do interior paulista. A banda faz cl\u00e1ssicos como: Eart, Wind and Fire, Stevie Wonder, Zapp, Maxwell, Michael Jackson, Chaka Khan entre outros.\u00a0<\/p>\n<p><b>Isabel Fillardis<\/b><\/p>\n<\/p>\n<p>Al\u00e9m de seu talento como atriz, Isabel Fillardis tamb\u00e9m se destaca como cantora. Com uma voz cativante, iniciou sua carreira musical nos anos 90, lan\u00e7ando \u00e1lbuns que mesclam influ\u00eancias do samba, soul, pop e da m\u00fasica popular brasileira.<\/p>\n<p>Refeita \u00e9 o nome do Show de estreia de Isabel Fillardis como cantora solo. O \u00e1lbum traz can\u00e7\u00f5es autorais e releituras de cl\u00e1ssicos da MPB, do samba, do soul e do pop, que refletem a trajet\u00f3ria, as influ\u00eancias e as inspira\u00e7\u00f5es da artista. Em seu show Isabel apresenta com grandes nomes como: Liniker, Djavan, S\u00e9rgio Loroza e Luedji Luna.<\/p>\n<p><em>Bel Manvailer, Comunica\u00e7\u00e3o Setesc<\/em><br \/><em>Fotos: Arquivo\/ Setesc<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Camp\u00e3o Cultural \u2013 III Festival de Arte, Diversidade e Cidadania acontecer\u00e1 na Capital sul-mato-grossense entre os dias 27 e 30 de mar\u00e7o e entre 4 e 6 de abril, contando com intensa programa\u00e7\u00e3o em diversos locais e atra\u00e7\u00f5es art\u00edsticas espalhadas pela cidade. O Festival \u00e9 realizado pelo Governo de Mato Grosso do Sul, por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-34623","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=34623"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34623\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=34623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=34623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=34623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}