{"id":34687,"date":"2025-03-26T16:15:09","date_gmt":"2025-03-26T19:15:09","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/03\/26\/setor-de-bioenergia-anuncia-aumento-de-producao-e-novos-investimentos-em-mato-grosso-do-sul-agencia-de-noticias-do-governo-de-mato-grosso-do-sul\/"},"modified":"2025-03-26T16:15:09","modified_gmt":"2025-03-26T19:15:09","slug":"setor-de-bioenergia-anuncia-aumento-de-producao-e-novos-investimentos-em-mato-grosso-do-sul-agencia-de-noticias-do-governo-de-mato-grosso-do-sul","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/03\/26\/setor-de-bioenergia-anuncia-aumento-de-producao-e-novos-investimentos-em-mato-grosso-do-sul-agencia-de-noticias-do-governo-de-mato-grosso-do-sul\/","title":{"rendered":"setor de bioenergia anuncia aumento de produ\u00e7\u00e3o e novos investimentos em Mato Grosso do Sul \u2013 Ag\u00eancia de Noticias do Governo de Mato Grosso do Sul"},"content":{"rendered":"<p><\/p>\n<div>\n<p>O setor de bioenergia de Mato Grosso do Sul prev\u00ea uma produ\u00e7\u00e3o de etanol pr\u00f3xima a 4,7 bilh\u00f5es de litros, volume 11% maior em rela\u00e7\u00e3o ao ciclo atual (2024\/2025). J\u00e1 a produ\u00e7\u00e3o de a\u00e7\u00facar no Estado ser\u00e1 de 2,6 milh\u00f5es de toneladas, alcan\u00e7ando um crescimento de 30% para o ciclo 2025\/2026.<\/p>\n<p>Os dados foram apresentados hoje (26) na Expocanas ao governador Eduardo Riedel, lideran\u00e7as do setor, entidades, prefeitos da regi\u00e3o, secret\u00e1rios estaduais e parlamentares.<\/p>\n<p>Junto com a divulga\u00e7\u00e3o do aumento da produ\u00e7\u00e3o, a Atvos, usina sucroalcooleira que produz etanol e a\u00e7\u00facar em tr\u00eas munic\u00edpios de Mato Grosso do Sul, anunciou a instala\u00e7\u00e3o da maior planta de biometano com origem de vinha\u00e7a do mundo, em Nova Alvorada do Sul, um investimento de R$ 350 milh\u00f5es. A iniciativa est\u00e1 alinhada com o projeto estrat\u00e9gico de descarboniza\u00e7\u00e3o do Governo do Estado.<\/p>\n<p>Ao comemorar a not\u00edcia, o governador Riedel destacou que o investimento anunciado \u00e9 uma demonstra\u00e7\u00e3o de confian\u00e7a.<\/p>\n<p>\u201cN\u00f3s temos constru\u00eddo este ambiente que gera confian\u00e7a aos investidores. A Atvos est\u00e1 presente no Estado e com an\u00fancios importantes que contribuem para o crescimento e desenvolvimento de Mato Grosso do Sul. Quando o acionista resolve colocar recurso em alguma atividade aqui no Estado \u00e9 porque ele confia e acredita nas pessoas e neste local. E o Mato Grosso do Sul tem constru\u00eddo essa confian\u00e7a com todas essas institui\u00e7\u00f5es e investidores&#8221;, frisou o governador.<\/p>\n<p>A licen\u00e7a de instala\u00e7\u00e3o da unidade foi entregue ao executivo da Atvos, Bruno Serapi\u00e3o, pelo secret\u00e1rio Jaime Verruck, da Semadesc (Secretaria de Meio Ambiente, Desenvolvimento, Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o).<\/p>\n<p>\u201cO setor de bioenergia \u00e9 um dos eixos estruturantes da pol\u00edtica de desenvolvimento do Estado. E o Governo definiu como priorit\u00e1rio em investimentos, porque temos competitividade, assim como nas florestas e na prote\u00edna animal\u201d, declarou Verruck.<\/p>\n<p>Para o CEO da Atvos, a bioenergia est\u00e1 moldando o futuro. \u201cNo ano passado, anunciamos no evento o nosso primeiro projeto de biometano e refor\u00e7o nosso compromisso com o desenvolvimento de Mato Grosso do Sul, pois o Estado tem papel fundamental para impulsionar a transi\u00e7\u00e3o energ\u00e9tica no Brasil e no mundo\u201d, complementou o executivo.<\/p>\n<p>Mato Grosso do Sul \u00e9 um dos l\u00edderes nacionais na produ\u00e7\u00e3o de energia limpa e renov\u00e1vel, com destaque para a produ\u00e7\u00e3o de etanol, a\u00e7\u00facar e bioeletricidade a partir da cana-de-a\u00e7\u00facar e do milho. Atualmente, o Estado conta com 22 usinas de bioenergia em opera\u00e7\u00e3o e cerca de 50 fornecedores de cana, respons\u00e1veis por mais de 30 mil empregos diretos e presentes em mais de 40 munic\u00edpios.<\/p>\n<p>De acordo com o presidente da Biosul (Associa\u00e7\u00e3o dos Produtores de Bioenergia de Mato Grosso do Sul), Amaury Pekelman, as perspectivas para ciclo 2025\/2026 s\u00e3o boas, mas o setor tem desafios pela frente como poss\u00edvel aumento de 30% de etanol \u00e0 gasolina.<\/p>\n<p>O setor de bioenergia de Mato Grosso do Sul registrou produ\u00e7\u00e3o hist\u00f3rica de 4,2 bilh\u00f5es de litros de etanol na safra 2024\/25, mantendo o estado como quarto maior produtor do Pa\u00eds.<\/p>\n<p>O avan\u00e7o foi impulsionado pelo etanol de milho, que atingiu participa\u00e7\u00e3o expressiva de 37% no total produzido. J\u00e1 a produ\u00e7\u00e3o de a\u00e7\u00facar se manteve est\u00e1vel em 2 milh\u00f5es de toneladas, com ligeiro aumento de 0,1%.<\/p>\n<p>Ainda segundo Pekelman, dois fatores foram determinantes para o ciclo 2024\/2025. \u201cA complementariedade do etanol de milho, que trouxe um salto tecnol\u00f3gico e estrat\u00e9gico para a produ\u00e7\u00e3o do biocombust\u00edvel. Outro aspecto importante foi a resili\u00eancia do setor, que mesmo com a redu\u00e7\u00e3o na moagem de cana devido a eventos clim\u00e1ticos adversos, manteve sua capacidade produtiva e gerou resultados importantes\u201d, avaliou.<\/p>\n<div id=\"gallery-2\" class=\"gallery galleryid-506339 gallery-columns-2 gallery-size-large\">\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><\/div>\n<\/figure><\/div>\n<p>O presidente da Sulcanas (Associa\u00e7\u00e3o Sul-mato-grossense de Cana), Marcio Verrunes, ressaltou a parceria com parceiros do setor industrial.<\/p>\n<p>Ainda segundo os organizadores, a expectativa \u00e9 receber mais de 8 mil pessoas por dia. A feira conta com mais de 120 expositores em um espa\u00e7o de 180 mil metros quadrados, com campos demonstrativos de variedades de cana-de-a\u00e7\u00facar, al\u00e9m de outras culturas como milho, soja e sorgo, al\u00e9m de m\u00e1quinas agr\u00edcolas, equipamentos com tecnologia de ponta e produtos inovadores para produtividade e manejo agr\u00edcola.<\/p>\n<p>Em 2024, a feira movimentou cerca de R$ 70 milh\u00f5es em novos neg\u00f3cios e a expectativa dos organizadores \u00e9 superar esta marca.<\/p>\n<p>O maior evento de bioenergia do Estado \u00e9 organizado pela Sulcanas, com apoio da Biosul e do Governo do Estado. A terceira edi\u00e7\u00e3o da Expocanas come\u00e7ou ontem (25), em Nova Alvorada do Sul, e se estende at\u00e9 a pr\u00f3xima quinta-feira (27).<\/p>\n<p><strong>Setor sucroenerg\u00e9tico<\/strong><\/p>\n<p>A ind\u00fastria sucroenerg\u00e9tica de Mato Grosso do Sul \u00e9 formada por 22 unidades em opera\u00e7\u00e3o. Destas, todas produzem etanol hidratado, 12 produzem etanol anidro, 12 produzem a\u00e7\u00facar [VHP, cristal ou refinado], todas geram bioeletricidade e 13 exportam o excedente dessa energia para a rede nacional.<\/p>\n<p>O setor sucroenerg\u00e9tico participa com 17% no PIB industrial do Estado, e possui atualmente 800 mil hectares de cana-de-a\u00e7\u00facar plantada em 42 munic\u00edpios.<\/p>\n<p>Nova Alvorada do Sul, sede da Expocanas, \u00e9 um dos maiores polos de cultivo de cana do Brasil, com mais de 100 mil hectares dedicados \u00e0 produ\u00e7\u00e3o da mat\u00e9ria-prima.<\/p>\n<p>A Expocanas j\u00e1 faz parte do calend\u00e1rio oficial do Estado e traz como proposta reunir em um s\u00f3 lugar o que h\u00e1 de mais novo em tecnologias, inova\u00e7\u00e3o, pesquisas e pr\u00e1ticas sustent\u00e1veis de produ\u00e7\u00e3o adotadas pelo setor bioenerg\u00e9tico.<\/p>\n<p>Em Mato Grosso do Sul, todas as usinas de bioenergia em opera\u00e7\u00e3o est\u00e3o certificadas no RenovaBio, um dos maiores programas de descarboniza\u00e7\u00e3o do mundo. A partir do programa, foi poss\u00edvel mensurar que de 2020 a 2024 a produ\u00e7\u00e3o de etanol evitou a emiss\u00e3o de 13,7 milh\u00f5es de toneladas de CO2 na atmosfera, equivalente a 89 milh\u00f5es de \u00e1rvores plantadas.<\/p>\n<p><em>Alexandre Gonzaga, Comunica\u00e7\u00e3o do Governo de MS<\/em><br \/><em>Fotos: Saul Schramm\/Secom<\/em><\/p>\n<p>&#8212;<br \/><strong>Relacionada:<\/strong><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"yRA0QTURKh\">\n<p>Mato Grosso do Sul tem produ\u00e7\u00e3o recorde de etanol e avan\u00e7a na descarboniza\u00e7\u00e3o do setor bioenerg\u00e9tico<\/p>\n<\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u201cMato Grosso do Sul tem produ\u00e7\u00e3o recorde de etanol e avan\u00e7a na descarboniza\u00e7\u00e3o do setor bioenerg\u00e9tico\u201d \u2014 Ag\u00eancia de Noticias do Governo de Mato Grosso do Sul\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/mato-grosso-do-sul-tem-producao-recorde-de-etanol-e-avanca-na-descarbonizacao-do-setor-bioenergetico\/embed\/#?secret=M6fzT7WPmj#?secret=yRA0QTURKh\" data-secret=\"yRA0QTURKh\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O setor de bioenergia de Mato Grosso do Sul prev\u00ea uma produ\u00e7\u00e3o de etanol pr\u00f3xima a 4,7 bilh\u00f5es de litros, volume 11% maior em rela\u00e7\u00e3o ao ciclo atual (2024\/2025). J\u00e1 a produ\u00e7\u00e3o de a\u00e7\u00facar no Estado ser\u00e1 de 2,6 milh\u00f5es de toneladas, alcan\u00e7ando um crescimento de 30% para o ciclo 2025\/2026. Os dados foram apresentados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-34687","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=34687"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34687\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=34687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=34687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=34687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}