{"id":34910,"date":"2025-03-31T08:40:16","date_gmt":"2025-03-31T11:40:16","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/03\/31\/governo-de-mato-grosso-do-sul-abre-nova-frente-de-cirurgias-ortopedicas-pelo-sus-na-regiao-leste-do-estado\/"},"modified":"2025-03-31T08:40:16","modified_gmt":"2025-03-31T11:40:16","slug":"governo-de-mato-grosso-do-sul-abre-nova-frente-de-cirurgias-ortopedicas-pelo-sus-na-regiao-leste-do-estado","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/03\/31\/governo-de-mato-grosso-do-sul-abre-nova-frente-de-cirurgias-ortopedicas-pelo-sus-na-regiao-leste-do-estado\/","title":{"rendered":"Governo de Mato Grosso do Sul abre nova frente de cirurgias ortop\u00e9dicas pelo SUS na regi\u00e3o leste do Estado"},"content":{"rendered":"<p><\/p>\n<div>\n<p style=\"text-align: center;\"><em>A\u00e7\u00e3o teve in\u00edcio semana passada na Funda\u00e7\u00e3o Hospitalar de Costa Rica com 36 procedimentos realizados em apenas tr\u00eas dias<\/em><\/p>\n<p>Alvo de alta procura e com crescente demanda de judicializa\u00e7\u00e3o, as cirurgias ortop\u00e9dicas realizadas pelo SUS (Sistema \u00danico de Sa\u00fade) ganharam uma nova frente de atendimento nesta semana, com a contratualiza\u00e7\u00e3o da SES (Secretaria Estadual de Sa\u00fade) e a Funda\u00e7\u00e3o Hospitalar de Costa Rica.<\/p>\n<p>Os atendimentos tiveram in\u00edcio na \u00faltima segunda-feira (24), com o in\u00edcio das cirurgias ortop\u00e9dicas para procedimentos de pr\u00f3tese de quadril, joelho e reposi\u00e7\u00e3o de ligamento e menisco. Entre 24 e 27 de mar\u00e7o, foram realizadas 36 cirurgias. As avalia\u00e7\u00f5es est\u00e3o sendo feitas desde o final de fevereiro, atendendo pacientes de Costa Rica e regi\u00e3o.<\/p>\n<p>&#8220;A demanda por cirurgias ortop\u00e9dicas \u00e9 um desafio que temos enfrentado e, para acelerar a realiza\u00e7\u00e3o dos procedimentos, o \u2018MS Sa\u00fade: Mais Saude, Menos Fila\u2019 tem trabalhado na expans\u00e3o da oferta de servi\u00e7os ortop\u00e9dicos ao longo do \u00faltimo ano. A SES tem feito a contratualiza\u00e7\u00e3o com hospitais em diversas regi\u00f5es, garantindo que as cirurgias necess\u00e1rias sejam realizadas mais perto da popula\u00e7\u00e3o\u201d, explica a Superintendente de Gest\u00e3o Estrat\u00e9gica da SES, Maria \u00c2ngela Benetasso.<\/p>\n<p><strong>Regionaliza\u00e7\u00e3o em pr\u00e1tica<\/strong><\/p>\n<div id=\"gallery-1\" class=\"gallery galleryid-506605 gallery-columns-2 gallery-size-large\">\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><\/div>\n<\/figure><\/div>\n<p>Ela detalha que a estrat\u00e9gia atende diretamente ao princ\u00edpio da regionaliza\u00e7\u00e3o, com foco nos cintur\u00f5es de m\u00e9dia complexidade. A proposta \u00e9 que as cidades vizinhas \u00e0s refer\u00eancias de alta complexidade assumam os atendimentos de m\u00e9dia complexidade.<\/p>\n<p>No caso da Costa Rica, que est\u00e1 inserida no cintur\u00e3o da Costa Leste, a cidade absorve casos de m\u00e9dia complexidade, garantindo que procedimentos como as cirurgias ortop\u00e9dicas sejam realizados o mais pr\u00f3ximo poss\u00edvel do paciente.<\/p>\n<p>Desta forma, os atendimentos passam a ser feitos perto da casa do paciente, enquanto os centros maiores, como Tr\u00eas Lagoas, ficam focados nos casos mais graves. \u201cToda a arquitetura constru\u00edda nesse sentido visa proporcionar um atendimento mais \u00e1gil e eficaz, garantindo que a popula\u00e7\u00e3o consiga acesso r\u00e1pido e de qualidade aos cuidados de sa\u00fade&#8221;, conclui.<\/p>\n<p>&#8220;A parceria com o Governo do Estado, por meio da Secretaria Estadual de Sa\u00fade, \u00e9 fundamental para garantirmos atendimentos especializados aos nossos mun\u00edcipes. Por meio do Programa MS Sa\u00fade, esses atendimentos est\u00e3o sendo realizados no pr\u00f3prio munic\u00edpio, evitando o deslocamento dos pacientes para outras cidades e ampliando o acesso aos tratamentos necess\u00e1rios. Al\u00e9m disso, a iniciativa contribui para reduzir a demanda reprimida em nosso munic\u00edpio e ainda beneficia moradores de outras regi\u00f5es do estado\u201d, confirma o secret\u00e1rio municipal de Sa\u00fade de Costa Rica, Daniel Raykson Lemos Santos.<\/p>\n<p><strong>Oftalmol\u00f3gicos<\/strong><\/p>\n<figure id=\"attachment_34486\" aria-describedby=\"caption-attachment-34486\" style=\"width: 519px\" class=\"wp-caption aligncenter\"><figcaption id=\"caption-attachment-34486\" class=\"wp-caption-text\">Costa Rica iniciou, tamb\u00e9m nesta semana pelo Programa \u2018MS Sa\u00fade: Mais Saude, Menos Fila\u2019, atendimentos especializados em retina.<\/figcaption><\/figure>\n<p>Al\u00e9m das cirurgias ortop\u00e9dicas, Costa Rica iniciou, tamb\u00e9m nesta semana pelo Programa \u2018MS Sa\u00fade: Mais Saude, Menos Fila\u2019, atendimentos especializados em retina.\u00a0 O programa oferece acompanhamento oftalmol\u00f3gico cont\u00ednuo, evitando que os pacientes precisem se deslocar para outras cidades.<\/p>\n<p>Nos dias 22 e 23 de mar\u00e7o, 86 pacientes passaram por avalia\u00e7\u00e3o de retina, com 47 realizando aplica\u00e7\u00f5es oculares. O atendimento especializado j\u00e1 \u00e9 feito em Campo Grande, no Hospital S\u00e3o Juli\u00e3o, desde novembro de 2024; e ser\u00e1 disponibilizado em F\u00e1tima do Sul a partir de 4 de abril deste ano.<\/p>\n<p>Os servi\u00e7os oferecidos incluem exames, inje\u00e7\u00f5es intrav\u00edtreas, laser e at\u00e9 procedimentos de vitrectomia, garantindo um tratamento completo para os pacientes.<\/p>\n<p><em>Dan\u00fabia Burema, Comunica\u00e7\u00e3o SES<br \/>Fotos: Sec. Mun. de Sa\u00fade de Costa Rica<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A\u00e7\u00e3o teve in\u00edcio semana passada na Funda\u00e7\u00e3o Hospitalar de Costa Rica com 36 procedimentos realizados em apenas tr\u00eas dias Alvo de alta procura e com crescente demanda de judicializa\u00e7\u00e3o, as cirurgias ortop\u00e9dicas realizadas pelo SUS (Sistema \u00danico de Sa\u00fade) ganharam uma nova frente de atendimento nesta semana, com a contratualiza\u00e7\u00e3o da SES (Secretaria Estadual de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-34910","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=34910"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34910\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=34910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=34910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=34910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}