{"id":39511,"date":"2025-07-07T05:11:05","date_gmt":"2025-07-07T08:11:05","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/07\/07\/agencia-minas-gerais-governo-de-minas-e-cemig-inauguram-usina-de-grande-porte-com-investimento-de-r-460-milhoes-no-norte-de-minas\/"},"modified":"2025-07-07T05:11:05","modified_gmt":"2025-07-07T08:11:05","slug":"agencia-minas-gerais-governo-de-minas-e-cemig-inauguram-usina-de-grande-porte-com-investimento-de-r-460-milhoes-no-norte-de-minas","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/07\/07\/agencia-minas-gerais-governo-de-minas-e-cemig-inauguram-usina-de-grande-porte-com-investimento-de-r-460-milhoes-no-norte-de-minas\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Governo de Minas e Cemig inauguram usina de grande porte com investimento de R$ 460 milh\u00f5es no Norte de Minas"},"content":{"rendered":"<p><\/p>\n<div>\n<section class=\"news-related \/ col-md-4 col-lg-3 \/ margin-md-bottom-2 margin-left-1 \/ pull-right \/ hidden-xs hidden-sm\">\n<header>\n<p class=\"text-title-section \/ margin-bottom-1\">Relacionadas<\/p>\n<\/header>\n<p>\t\t\t\t\t\t\t<main><\/p>\n<hr class=\"row margin-md-bottom-2\"\/>\n<hr class=\"row margin-md-bottom-2\"\/>\n\t\t\t\t\t\t\t<\/main><br \/>\n\t\t\t\t\t\t<\/section>\n<p>O Governo de Minas e a Cemig inauguraram, nesta sexta-feira (4\/7), com a presen\u00e7a do vice-governador Mateus Sim\u00f5es, uma usina solar fotovoltaica (UFV) com grande capacidade de produ\u00e7\u00e3o de energia no Norte de Minas Gerais.<\/p>\n<p>A nova UFV Advogado Eduardo Soares, localizada em Montes Claros, \u00e9 o maior projeto de gera\u00e7\u00e3o fotovoltaica centralizada da companhia e possui capacidade instalada de 85 megawatts (MW) (correspondente a 100,6 megawatts-pico), com energia suficiente para abastecer grande parte do consumo anual dos clientes residenciais da cidade de Montes Claros. O valor do investimento na nova unidade \u00e9 de R$ 460 milh\u00f5es.<\/p>\n<table align=\"center\" border=\"0\" cellpadding=\"1\" cellspacing=\"1\" style=\"width: 70%;\">&#13;<\/p>\n<tbody>&#13;<\/p>\n<tr>&#13;<\/p>\n<td colspan=\"5\" style=\"text-align: center; vertical-align: middle;\">&#13;<\/p>\n<p style=\"text-align:center\">\n<p>&#13;\n\t\t\t<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<\/p>\n<td colspan=\"3\" rowspan=\"3\" style=\"text-align: center; vertical-align: middle;\">&#13;<br \/>\n\t\t\t&#13;\n\t\t\t<\/td>\n<p>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td colspan=\"5\" style=\"text-align: center; vertical-align: middle;\">&#13;<\/p>\n<p style=\"text-align:center\">\n<p>&#13;\n\t\t\t<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<br \/>\n\t<\/tbody>\n<p>&#13;<br \/>\n<\/table>\n<p>O empreendimento \u00e9 uma retomada da Cemig \u00e0 constru\u00e7\u00e3o de usinas de grande porte, sendo que, desde a entrada em opera\u00e7\u00e3o da Usina Hidrel\u00e9trica de Irap\u00e9, em 2006, que possui capacidade instalada de 399 MW, a companhia n\u00e3o havia inaugurado\u00a0uma obra de maior capacidade de gera\u00e7\u00e3o.<\/p>\n<p>\u201cUma usina dentro do munic\u00edpio de Montes Claros, que gerou ISS durante a constru\u00e7\u00e3o, vai gerar ICMS agora que j\u00e1 est\u00e1 pronta. \u00c9 um motivo de satisfa\u00e7\u00e3o e orgulho\u00a0saber que n\u00f3s temos condi\u00e7\u00e3o de continuar crescendo, que a energia de qualidade verde renov\u00e1vel est\u00e1 aqui, sendo produzida na regi\u00e3o\u201d, concluiu o vice-governador.<\/p>\n<p><strong>Energia limpa e renov\u00e1vel<\/strong><\/p>\n<p>O presidente da Cemig, Reynaldo Passanezi Filho, destaca o importante papel da usina no parque gerador da companhia, que \u00e9 100% limpo e renov\u00e1vel. \u201cA UFV Advogado Eduardo Soares representa a retomada do protagonismo da Cemig na constru\u00e7\u00e3o de grandes ativos de gera\u00e7\u00e3o, refor\u00e7a o compromisso da companhia com a transi\u00e7\u00e3o energ\u00e9tica e fortalece a atua\u00e7\u00e3o diversificada da Companhia que vai da gera\u00e7\u00e3o \u00e0 distribui\u00e7\u00e3o&#8221;, afirmou.<\/p>\n<p>De acordo com o vice-presidente de Gera\u00e7\u00e3o e Transmiss\u00e3o da Cemig, Marco Soligo, a UFV Advogado Eduardo Soares demonstra o compromisso da companhia com as melhores pr\u00e1ticas de ESG \u2014 sigla para Environmental, Social and Governance (Ambiental, Social e Governan\u00e7a) \u2014 e com o desenvolvimento do estado.<\/p>\n<p>\u201cEsse projeto refor\u00e7a o papel da Cemig como destaque na transi\u00e7\u00e3o energ\u00e9tica no Brasil, aliando desenvolvimento econ\u00f4mico e sustentabilidade. A implanta\u00e7\u00e3o da UVF Advogado Eduardo Soares est\u00e1 alinhada ao planejamento estrat\u00e9gico da companhia, fortalecendo sua atua\u00e7\u00e3o no segmento de energias renov\u00e1veis e fomentando a economia em toda Minas Gerais\u201d, explicou.<\/p>\n<p><strong>N\u00fameros do empreendimento<\/strong><\/p>\n<p>A nova UFV ocupa uma \u00e1rea de 250 hectares e conta com 153,6 mil pain\u00e9is solares montados sobre 2.560 estruturas m\u00f3veis (trackers), que acompanham o movimento do sol para otimizar a gera\u00e7\u00e3o de energia. Em seguida, a energia gerada pelos pain\u00e9is solares passa por 285 inversores, onde \u00e9 convertida em corrente alternada e injetada na rede el\u00e9trica.<\/p>\n<p>Al\u00e9m do parque de gera\u00e7\u00e3o fotovoltaica, o projeto envolveu a constru\u00e7\u00e3o de duas subesta\u00e7\u00f5es na regi\u00e3o Norte de Minas Gerais que possuem pap\u00e9is fundamentais: uma subesta\u00e7\u00e3o elevadora de 90 mega-volt-amperes (MVA) adequa a tens\u00e3o da energia gerada \u00e0 tens\u00e3o da rede de transmiss\u00e3o, enquanto a subesta\u00e7\u00e3o de integra\u00e7\u00e3o de 138 quilovolts (kV) realiza a conex\u00e3o da usina ao sistema el\u00e9trico, garantindo o fornecimento da energia com qualidade e seguran\u00e7a.<\/p>\n<p>O empreendimento foi constru\u00eddo em Montes Claros devido \u00e0 alta irradi\u00e2ncia solar, tornando o investimento ainda mais estrat\u00e9gico e eficiente para a Cemig.<\/p>\n<p>&#8220;A constru\u00e7\u00e3o da nova usina e das duas subesta\u00e7\u00f5es, al\u00e9m de aumentar a oferta de energia limpa e renov\u00e1vel, beneficiar\u00e1 os clientes da regi\u00e3o, uma vez que o sistema de gera\u00e7\u00e3o e distribui\u00e7\u00e3o de energia ficar\u00e1 ainda mais robusto e est\u00e1vel&#8221;, destacou o gestor de implanta\u00e7\u00e3o de ativos de gera\u00e7\u00e3o da companhia, Tiago Saraiva, respons\u00e1vel t\u00e9cnico pela constru\u00e7\u00e3o do empreendimento.<\/p>\n<p><strong>Outro projeto a caminho<\/strong><\/p>\n<p>Ap\u00f3s a inaugura\u00e7\u00e3o da UFV Advogado Eduardo Soares, em Montes Claros, a Cemig se prepara para entregar, nos pr\u00f3ximos meses, mais um importante projeto de energia solar em Minas Gerais.<\/p>\n<p>Localizada em S\u00e3o Gon\u00e7alo do Abaet\u00e9, na regi\u00e3o Noroeste do estado, a usina solar Jusante recebeu investimentos de aproximadamente R$ 390 milh\u00f5es. Composta por sete unidades de 10 MW cada, a estrutura ter\u00e1 capacidade instalada de 70 MW (cerca de 87 MWp) e energia suficiente para abastecer cerca de 95% do consumo anual dos clientes residenciais de Divin\u00f3polis, por exemplo.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Relacionadas O Governo de Minas e a Cemig inauguraram, nesta sexta-feira (4\/7), com a presen\u00e7a do vice-governador Mateus Sim\u00f5es, uma usina solar fotovoltaica (UFV) com grande capacidade de produ\u00e7\u00e3o de energia no Norte de Minas Gerais. A nova UFV Advogado Eduardo Soares, localizada em Montes Claros, \u00e9 o maior projeto de gera\u00e7\u00e3o fotovoltaica centralizada da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39511","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=39511"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39511\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=39511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=39511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=39511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}