{"id":41625,"date":"2025-08-21T10:55:16","date_gmt":"2025-08-21T13:55:16","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/08\/21\/seinfra-realiza-servicos-de-manutencao-em-mais-de-40-bairros-nesta-quinta-feira\/"},"modified":"2025-08-21T10:55:16","modified_gmt":"2025-08-21T13:55:16","slug":"seinfra-realiza-servicos-de-manutencao-em-mais-de-40-bairros-nesta-quinta-feira","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/08\/21\/seinfra-realiza-servicos-de-manutencao-em-mais-de-40-bairros-nesta-quinta-feira\/","title":{"rendered":"Seinfra realiza servi\u00e7os de manuten\u00e7\u00e3o em mais de 40 bairros nesta quinta-feira"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A Secretaria de Infraestrutura (Seinfra) segue, nesta quinta-feira (21), com servi\u00e7os de manuten\u00e7\u00e3o de ilumina\u00e7\u00e3o p\u00fablica, na rede de drenagem e Opera\u00e7\u00e3o Tapa-Buraco. As a\u00e7\u00f5es acontecem simultaneamente em 43 bairros ao longo de todo o dia.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><\/figure>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<\/figure>\n<p>Haver\u00e1 manuten\u00e7\u00e3o na rede de ilumina\u00e7\u00e3o p\u00fablica nos bairros do Jo\u00e3o Paulo II, Esplanada, Funcion\u00e1rios II, III e IV, Cristo, Rangel, Varj\u00e3o, Mandacaru, Valentina e Geisel.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><\/figure>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<figure class=\"wp-block-image size-full\"><\/figure>\n<\/figure>\n<p>Os servi\u00e7os na rede de drenagem refor\u00e7am a desobstru\u00e7\u00e3o de galerias e abertura de lan\u00e7amentos nas localidades de Centro, Bessa, Mana\u00edra, Tamba\u00fa e Cabo Branco.<\/p>\n<p>A Opera\u00e7\u00e3o Tapa-Buraco far\u00e1 a recupera\u00e7\u00e3o de pavimento nos bairros do Planalto da Boa Esperan\u00e7a, Cui\u00e1, Geisel, Jardim Veneza, Ernani S\u00e1tiro, Gramame, Mu\u00e7umagro, Valentina, Colinas do Sul, Altiplano, Cabo Branco, Mangabeira, Castelo Branco, Torre, Pedro Gondim, Alto do C\u00e9u, Expedicion\u00e1rios, Brisamar, Bairro das Ind\u00fastrias, Alto do Mateus, Bairro dos Estados, Bairro dos Ip\u00eas, Centro, Treze de Maio, Tambauzinho, Oitizeiro, Funcion\u00e1rios, Varj\u00e3o, Mandacaru, Distrito Industrial, Paratibe, Colinas do Sul, Roger, Jardim Cidade Universit\u00e1ria, Banc\u00e1rios, Jardim Oceania, Mana\u00edra, Bessa e Tamba\u00fa.<\/p>\n<p><strong>Atendimento \u2013<\/strong>\u00a0A popula\u00e7\u00e3o pode solicitar os servi\u00e7os de manuten\u00e7\u00e3o da Seinfra, como tapa-buraco, galerias, ilumina\u00e7\u00e3o e terraplanagem por meio do aplicativo Jo\u00e3o Pessoa na Palma da M\u00e3o.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Infraestrutura (Seinfra) segue, nesta quinta-feira (21), com servi\u00e7os de manuten\u00e7\u00e3o de ilumina\u00e7\u00e3o p\u00fablica, na rede de drenagem e Opera\u00e7\u00e3o Tapa-Buraco. As a\u00e7\u00f5es acontecem simultaneamente em 43 bairros ao longo de todo o dia. Haver\u00e1 manuten\u00e7\u00e3o na rede de ilumina\u00e7\u00e3o p\u00fablica nos bairros do Jo\u00e3o Paulo II, Esplanada, Funcion\u00e1rios II, III e IV, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-41625","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41625"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41625\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}