{"id":42121,"date":"2025-09-01T22:29:22","date_gmt":"2025-09-02T01:29:22","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/09\/01\/prefeitura-de-sorocaba-realiza-concurso-publico-para-vagas-em-diversas-areas-agencia-de-noticias\/"},"modified":"2025-09-01T22:29:22","modified_gmt":"2025-09-02T01:29:22","slug":"prefeitura-de-sorocaba-realiza-concurso-publico-para-vagas-em-diversas-areas-agencia-de-noticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/09\/01\/prefeitura-de-sorocaba-realiza-concurso-publico-para-vagas-em-diversas-areas-agencia-de-noticias\/","title":{"rendered":"Prefeitura de Sorocaba realiza concurso p\u00fablico para vagas em diversas \u00e1reas \u2013 Ag\u00eancia de Not\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<div class=\"col\">\n<p class=\"mt-0\">\n                        <strong><br \/>\n                            <span class=\"far fa-calendar mr-1 mt-2\"\/><br \/>\n                            1 de setembro de 2025<br \/>\n                            <span class=\"far fa-clock ml-3 mt-2\"\/><br \/>\n                            20:26<br \/>\n                        <\/strong>\n                    <\/p>\n<p class=\"mb-0\">Por: <strong>Michelle Alves<\/strong><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<blockquote>\n<\/blockquote>\n<p>A Prefeitura de Sorocaba, por meio da Secretaria de Recursos Humanos (Serh), divulga, nesta segunda-feira (1\u00ba de setembro), no Jornal Munic\u00edpio de Sorocaba (https:\/\/noticias.sorocaba.sp.gov.br\/jornal-do-municipio\/), o edital do concurso p\u00fablico n\u00ba 01\/2025 para cargos em diversas \u00e1reas. As inscri\u00e7\u00f5es dever\u00e3o ser realizadas, de 8 de setembro a 13 de outubro deste ano, no site da Funda\u00e7\u00e3o Vunesp (https:\/\/www.vunesp.com.br\/), organizadora do certame, mediante o pagamento da taxa de inscri\u00e7\u00e3o.<\/p>\n<p>\u00a0<\/p>\n<p>Ser\u00e3o, no total, 89 vagas, para os seguintes cargos: Agente de Servi\u00e7o Cemiterial (3 vagas), Ajudantes Geral (2 vagas), Encanador (1 vaga), Jardineiro (1 vaga), Inspetor de Alunos (2 vagas), Pintor (2 vagas), Auxiliar de Educa\u00e7\u00e3o (20 vagas), Secret\u00e1rio de Escola (1 vaga), Enfermeiro (2 vagas), Fonoaudi\u00f3logo (1 vaga), M\u00e9dico I (Cl\u00ednico Geral \u2013 2 vagas), M\u00e9dico I (Ginecologista \u2013 27 vagas), M\u00e9dico I (Pediatra \u2013 24 vagas) e\u00a0 M\u00e9dico II (Cl\u00ednico Geral \u2013 1 vaga). Os cargos, que exigem Ensino M\u00e9dio e\/ou Ensino Superior, t\u00eam vencimentos a partir de R$ 2.325,92.<\/p>\n<p>\u00a0<\/p>\n<p>A aplica\u00e7\u00e3o da prova objetiva, feita pela Funda\u00e7\u00e3o Vunesp, est\u00e1 marcada para o dia 30 de novembro deste ano, devendo os candidatos se atentar aos hor\u00e1rios de realiza\u00e7\u00e3o das provas, que ser\u00e3o aplicadas nos per\u00edodos da manh\u00e3 e da tarde.<\/p>\n<p>\u00a0<\/p>\n<p>Os interessados em solicitar a isen\u00e7\u00e3o do pagamento da taxa de inscri\u00e7\u00e3o devem enviar a solicita\u00e7\u00e3o e os documentos comprobat\u00f3rios nos dias 8 e 9 de setembro, conforme estabelecido no edital. O Edital apresenta, ainda, todos os procedimentos a serem adotados pelos candidatos com defici\u00eancia e \u00e0queles que necessitarem de condi\u00e7\u00f5es especiais para a realiza\u00e7\u00e3o da prova.<\/p>\n<p>\u00a0<\/p>\n<p>A Secretaria de Recursos Humanos orienta que todos leiam atentamente o edital e cumpram rigorosamente as regras e os prazos estabelecidos, al\u00e9m de preencherem corretamente o formul\u00e1rio de inscri\u00e7\u00e3o e o envio de eventuais documenta\u00e7\u00f5es diretamente no site da Funda\u00e7\u00e3o Vunesp.<\/p>\n<p>\u00a0<\/p>\n<p>D\u00favidas relacionadas ao certame podem ser esclarecidas diretamente com a Funda\u00e7\u00e3o Vunesp, pelo site: https:\/\/www.vunesp.com.br\/, na \u00c1rea do Candidato, ou entrando em contato com o Disque Vunesp, pelo telefone: (11) 3874-6300.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>1 de setembro de 2025 20:26 Por: Michelle Alves A Prefeitura de Sorocaba, por meio da Secretaria de Recursos Humanos (Serh), divulga, nesta segunda-feira (1\u00ba de setembro), no Jornal Munic\u00edpio de Sorocaba (https:\/\/noticias.sorocaba.sp.gov.br\/jornal-do-municipio\/), o edital do concurso p\u00fablico n\u00ba 01\/2025 para cargos em diversas \u00e1reas. As inscri\u00e7\u00f5es dever\u00e3o ser realizadas, de 8 de setembro a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-42121","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=42121"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42121\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=42121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=42121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=42121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}