{"id":43514,"date":"2025-10-06T08:20:43","date_gmt":"2025-10-06T11:20:43","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/10\/06\/audiencia-publica-no-stf-debate-pejotizacao-nas-relacoes-de-trabalho\/"},"modified":"2025-10-06T08:20:43","modified_gmt":"2025-10-06T11:20:43","slug":"audiencia-publica-no-stf-debate-pejotizacao-nas-relacoes-de-trabalho","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/10\/06\/audiencia-publica-no-stf-debate-pejotizacao-nas-relacoes-de-trabalho\/","title":{"rendered":"Audi\u00eancia p\u00fablica no STF debate pejotiza\u00e7\u00e3o nas rela\u00e7\u00f5es de trabalho"},"content":{"rendered":"<p> Por MRNews<br \/>\n<\/p>\n<div wp_automatic_readability=\"53.666374781086\">\n<p><strong>O Supremo Tribunal Federal (STF) promove nesta segunda-feira (6) uma audi\u00eancia p\u00fablica para debater a pejotiza\u00e7\u00e3o nas rela\u00e7\u00f5es de trabalho.<\/strong> O fen\u00f4meno ocorre quando empresas contratam prestadores de servi\u00e7o como pessoa jur\u00eddica para fugir do v\u00ednculo trabalhista.<\/p>\n<p><strong>Os debates ser\u00e3o abertos \u00e0s 8h, pelo ministro Gilmar Mendes, relator das a\u00e7\u00f5es que tratam da quest\u00e3o, e contar\u00e3o com a presen\u00e7a de especialistas em direito trabalhista, representantes de sindicatos, do Minist\u00e9rio do Trabalho e Emprego, Minist\u00e9rio P\u00fablico do Trabalho (MPT) e dos setores empresariais.<\/strong><\/p>\n<p>Em abril deste ano, o ministro suspendeu todas as a\u00e7\u00f5es sobre o tema que est\u00e3o em tramita\u00e7\u00e3o no pa\u00eds e convocou a audi\u00eancia p\u00fablica. Os processos s\u00f3 voltar\u00e3o a tramitar ap\u00f3s a decis\u00e3o da Corte sobre a legalidade da pejotiza\u00e7\u00e3o. A data do julgamento n\u00e3o foi definida.<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2025\/10\/06\/caminhos-da-reportagem-aborda-educacao-para-pessoas-com-deficiencia\/\">Caminhos da Reportagem aborda educa\u00e7\u00e3o para pessoas com defici\u00eancia<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/segunda-edicao-do-cnu-atrai-servidores-em-busca-de-cargos-melhores\/\">Segunda edi\u00e7\u00e3o do CNU atrai servidores em busca de cargos melhores<\/a><\/strong><\/p>\n<p><strong>Ao determinar a audi\u00eancia p\u00fablica, Gilmar Mendes disse que os debates v\u00e3o ajudar no exame da quest\u00e3o e definir balizas para contrata\u00e7\u00e3o de aut\u00f4nomos e pessoas jur\u00eddicas.<\/strong><\/p>\n<p>Ap\u00f3s a decis\u00e3o do ministro, entidades que representam magistrados do trabalho e a seccional da Ordem dos Advogados do Brasil em S\u00e3o Paulo (OAB-SP) defenderam a compet\u00eancia da Justi\u00e7a do Trabalho para julgar casos envolvendo a pejotiza\u00e7\u00e3o.<\/p>\n<p><strong>Pejotiza\u00e7\u00e3o \u00e9 um termo usado para caracterizar contrata\u00e7\u00f5es de trabalhadores como pessoas jur\u00eddicas pelas empresas.<\/strong> Os PJ, como s\u00e3o chamados, n\u00e3o t\u00eam carteira de trabalho assinada. Essa modalidade ganhou for\u00e7a com a reforma trabalhista, de 2017, que permitiu a terceiriza\u00e7\u00e3o do trabalho para atividades-fim da empresa.<\/p>\n<p>Desde ent\u00e3o, milhares de processos chegaram \u00e0s varas da Justi\u00e7a do Trabalho, e trabalhadores contratados como PJ passaram a buscar o reconhecimento de v\u00ednculo empregat\u00edcio.\u00a0<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/virada-e-derrota-rubro-negra-levam-palmeiras-a-ponta-do-brasileirao\/\">Virada e derrota rubro-negra levam Palmeiras \u00e0 ponta do Brasileir\u00e3o<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/ministra-diz-que-medidas-de-seguranca-no-cnu-2-foram-eficazes\/\">Ministra diz que medidas de seguran\u00e7a no CNU 2 foram eficazes<\/a><\/strong><\/p>\n<p>De acordo com o Minist\u00e9rio P\u00fablico do Trabalho (MPT), de 2020 a mar\u00e7o de 2025, foram ajuizadas 1,2 milh\u00e3o de reclama\u00e7\u00f5es trabalhistas por causa da terceiriza\u00e7\u00e3o.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por MRNews O Supremo Tribunal Federal (STF) promove nesta segunda-feira (6) uma audi\u00eancia p\u00fablica para debater a pejotiza\u00e7\u00e3o nas rela\u00e7\u00f5es de trabalho. O fen\u00f4meno ocorre quando empresas contratam prestadores de servi\u00e7o como pessoa jur\u00eddica para fugir do v\u00ednculo trabalhista. Os debates ser\u00e3o abertos \u00e0s 8h, pelo ministro Gilmar Mendes, relator das a\u00e7\u00f5es que tratam da [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-43514","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=43514"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43514\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=43514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=43514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=43514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}