{"id":43740,"date":"2025-10-10T21:54:37","date_gmt":"2025-10-11T00:54:37","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/10\/10\/agencia-minas-gerais-minas-gerais-destaca-inovacao-negocios-e-protagonismo-feminino-no-segundo-dia-da-abav-expo-2025\/"},"modified":"2025-10-10T21:54:37","modified_gmt":"2025-10-11T00:54:37","slug":"agencia-minas-gerais-minas-gerais-destaca-inovacao-negocios-e-protagonismo-feminino-no-segundo-dia-da-abav-expo-2025","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/10\/10\/agencia-minas-gerais-minas-gerais-destaca-inovacao-negocios-e-protagonismo-feminino-no-segundo-dia-da-abav-expo-2025\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Minas Gerais destaca inova\u00e7\u00e3o, neg\u00f3cios e protagonismo feminino no segundo dia da Abav Expo 2025"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Minas Gerais consolidou sua participa\u00e7\u00e3o na Abav Expo 2025 como um dos destaques da feira sediada no Rio de Janeiro. A programa\u00e7\u00e3o no estande do estado reuniu cozinha mineira, novos roteiros tur\u00edsticos, premia\u00e7\u00f5es e parcerias estrat\u00e9gicas, evidenciando o potencial do estado para atra\u00e7\u00e3o de investimentos a partir da sua diversidade cultural e tur\u00edstica.<\/p>\n<p>Com dezenas de reuni\u00f5es de neg\u00f3cios e o reconhecimento nacional do destino, Minas Gerais encerrou o segundo dia do evento, na \u00faltima quinta-feira (9\/10) reafirmando sua for\u00e7a como estado plural, acolhedor e inovador, onde tradi\u00e7\u00e3o e futuro caminham lado a lado.<\/p>\n<p>Na ocasi\u00e3o, Belo Horizonte recebeu o Pr\u00eamio Excel\u00eancia Tur\u00edstica na categoria Destino Digital &#8211; A\u00e9reo Internacional. \u201cEsse pr\u00eamio \u00e9 reflexo do trabalho conjunto entre o poder p\u00fablico e o setor privado. Minas e sua capital est\u00e3o preparadas para competir em um mercado global, unindo tradi\u00e7\u00e3o, inova\u00e7\u00e3o e uma hospitalidade que \u00e9 nossa marca registrada\u201d, avalia a subsecret\u00e1ria de Turismo de Minas Gerais, Patr\u00edcia Moreira.\u00a0<\/p>\n<p><strong>Produ\u00e7\u00e3o artesanal<\/strong><\/p>\n<p>O lan\u00e7amento da Rota do Queijo em Itamonte refor\u00e7ou a import\u00e2ncia da produ\u00e7\u00e3o artesanal e das certifica\u00e7\u00f5es de origem como diferencial competitivo do turismo regional. A chef Fabi Rodrigues, de Una\u00ed, apresentou o prato Canjiquinha da D\u2019Nhanna com costelinha su\u00edna e ora-pro-n\u00f3bis, representando o projeto Prepara Gastronomia, do Sebrae-MG, que promove o desenvolvimento local e a identidade alimentar mineira.<\/p>\n<p>A tarde seguiu com o lan\u00e7amento do Semin\u00e1rio de Turismo de S\u00e3o Jo\u00e3o del-Rei, que acontecer\u00e1 nos dias 16 e 17\/10, no Teatro Municipal da cidade. O evento reunir\u00e1 gestores, empreendedores e comunidade para debater o papel da f\u00e9, da cultura e da hist\u00f3ria na constru\u00e7\u00e3o de destinos tur\u00edsticos integrados.<\/p>\n<p>Na sequ\u00eancia, a chef Mariana Gontijo comandou a degusta\u00e7\u00e3o Queijos Mineiros, com produtos da Canastra, do Vale do Mucuri, da Serra da Mantiqueira e da Serra do Salitre. A Mesa Mineira, em parceria com o Instituto Mundu, apresentou novas degusta\u00e7\u00f5es de produtos regionais, e o bartender Leo Gomes encerrou a programa\u00e7\u00e3o com drinks inspirados em ingredientes t\u00edpicos do estado.<\/p>\n<p>Profissionais e visitantes refor\u00e7aram o impacto positivo da presen\u00e7a mineira na feira. Leandro C\u00e9sar Ferraz, t\u00e9cnico de turismo da Prefeitura de Barretos (SP), destacou: \u201cMinas \u00e9 um estado de fartura e acolhimento. Esse estande mostra a for\u00e7a da gastronomia e abre novas portas para parcerias regionais.\u201d J\u00e1 Ivair Duarte, gerente comercial do Dayrell Hotel e Centro de Conven\u00e7\u00f5es, ressaltou a import\u00e2ncia da presen\u00e7a institucional: \u201cA atua\u00e7\u00e3o da Secult amplia a visibilidade dos empreendedores e posiciona Minas como refer\u00eancia em turismo diversificado e de qualidade\u201d.<\/p>\n<p>A mestre quitandeira V\u00e2nia Lima Macedo Borges, de Paracatu, abriu a programa\u00e7\u00e3o da Cozinha Viva com as tradicionais empadinhas de frango de Paracatu, ressaltando o papel das mulheres na gastronomia mineira. \u201cRepresentar Paracatu aqui \u00e9 carregar as hist\u00f3rias das mulheres e fam\u00edlias que mant\u00eam vivo o legado das nossas quitandas. \u00c9 uma experi\u00eancia m\u00e1gica, de aprendizado e de orgulho\u201d, contou.<\/p>\n<p>A subsecret\u00e1ria de Turismo de Minas Gerais, Patr\u00edcia Moreira, destacou o protagonismo feminino e o modo \u00fanico de receber que definem a identidade cultural e gastron\u00f4mica do estado. \u201cA ideia \u00e9 trazer o que Minas tem de melhor. N\u00e3o \u00e9 s\u00f3 a cozinha, mas o nosso jeito de receber, o sotaque e o calor humano. Nossa gastronomia \u00e9 forjada pela mistura de povos &#8211; portugueses, negros, ind\u00edgenas e comunidades tradicionais &#8211; e tem alma feminina. As mulheres s\u00e3o guardi\u00e3s das receitas, da hospitalidade e da mem\u00f3ria afetiva que fazem da mesa mineira um verdadeiro patrim\u00f4nio. E \u00e9 essa a ess\u00eancia que queremos mostrar aqui: o mineiro acolhe de verdade quando convida para a cozinha\u201d, afirmou.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Minas Gerais consolidou sua participa\u00e7\u00e3o na Abav Expo 2025 como um dos destaques da feira sediada no Rio de Janeiro. A programa\u00e7\u00e3o no estande do estado reuniu cozinha mineira, novos roteiros tur\u00edsticos, premia\u00e7\u00f5es e parcerias estrat\u00e9gicas, evidenciando o potencial do estado para atra\u00e7\u00e3o de investimentos a partir da sua diversidade cultural e tur\u00edstica. Com dezenas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-43740","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=43740"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43740\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=43740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=43740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=43740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}