{"id":44980,"date":"2025-11-16T08:25:52","date_gmt":"2025-11-16T11:25:52","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2025\/11\/16\/agencia-minas-gerais-governo-de-minas-confere-andamento-das-obras-da-nova-sede-da-delegacia-regional-de-policia-civil-em-araxa\/"},"modified":"2025-11-16T08:25:52","modified_gmt":"2025-11-16T11:25:52","slug":"agencia-minas-gerais-governo-de-minas-confere-andamento-das-obras-da-nova-sede-da-delegacia-regional-de-policia-civil-em-araxa","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2025\/11\/16\/agencia-minas-gerais-governo-de-minas-confere-andamento-das-obras-da-nova-sede-da-delegacia-regional-de-policia-civil-em-araxa\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Governo de Minas confere andamento das obras da nova sede da Delegacia Regional de Pol\u00edcia Civil em Arax\u00e1"},"content":{"rendered":"<p><\/p>\n<div>\n<section class=\"news-related \/ col-md-4 col-lg-3 \/ margin-md-bottom-2 margin-left-1 \/ pull-right \/ hidden-xs hidden-sm\">\n<header>\n<p class=\"text-title-section \/ margin-bottom-1\">Relacionadas<\/p>\n<\/header>\n<p>\t\t\t\t\t\t\t<main><\/p>\n<hr class=\"row margin-md-bottom-2\"\/>\n\t\t\t\t\t\t\t<\/main><br \/>\n\t\t\t\t\t\t<\/section>\n<p>O governador Romeu Zema acompanhou, nesta sexta-feira (14\/11), a evolu\u00e7\u00e3o das interven\u00e7\u00f5es realizadas no novo im\u00f3vel da nova sede da Delegacia Regional de Arax\u00e1, no Alto Parana\u00edba. A unidade ir\u00e1 funcionar de forma integrada \u00e0s outras delegacias especializadas, aprimorando o trabalho da Pol\u00edcia Civil em toda a regi\u00e3o.<\/p>\n<p>O pr\u00e9dio localizado na Avenida Tancredo Neves, no bairro Vila Silv\u00e9ria, vai reunir, em um \u00fanico local, a Delegacia Especializada de Atendimento \u00e0 Mulher, a Delegacia Especializada de Repress\u00e3o a Crimes Rurais e o plant\u00e3o.<\/p>\n<p>No local, tamb\u00e9m v\u00e3o trabalhar as equipes de investiga\u00e7\u00e3o de furtos e roubos, crimes contra a vida, delitos ambientais, fraudes, tr\u00e2nsito e combate ao tr\u00e1fico, bem como do setor de intelig\u00eancia.<br \/>&#13;<br \/>\n\u00a0<\/p>\n<table align=\"center\" border=\"0\" cellpadding=\"1\" cellspacing=\"1\" style=\"width: 70%;\">&#13;<\/p>\n<tbody>&#13;<\/p>\n<tr>&#13;<\/p>\n<td colspan=\"5\" style=\"text-align: center; vertical-align: middle;\">&#13;<\/p>\n<p style=\"text-align:center\">\n<p>&#13;\n\t\t\t<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<\/p>\n<td colspan=\"3\" rowspan=\"3\" style=\"text-align: center; vertical-align: middle;\">&#13;<br \/>\n\t\t\t&#13;\n\t\t\t<\/td>\n<p>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<\/p>\n<td style=\"text-align: center; vertical-align: middle;\">\u00a0<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<\/p>\n<tr>&#13;<\/p>\n<td colspan=\"5\" style=\"text-align: center; vertical-align: middle;\">&#13;<\/p>\n<p style=\"text-align:center\">\n<p>&#13;\n\t\t\t<\/td>\n<p>&#13;<br \/>\n\t\t<\/tr>\n<p>&#13;<br \/>\n\t<\/tbody>\n<p>&#13;<br \/>\n<\/table>\n<p>&#13;<br \/>\nPara atender \u00e0s necessidades das equipes da Pol\u00edcia Civil, est\u00e3o sendo realizadas interven\u00e7\u00f5es estruturais, como adequa\u00e7\u00e3o de salas para os trabalhos policiais, incluindo as atividades de registro de ocorr\u00eancias, oitivas e investiga\u00e7\u00f5es, e reformas no setor de compartimento para presos.<\/p>\n<p>A previs\u00e3o \u00e9 que as obras e interven\u00e7\u00f5es sejam finalizadas no primeiro trimestre de 2026.<\/p>\n<p><strong>Estrutura<\/strong><\/p>\n<p>As unidades que comp\u00f5em a DRPC atendem diretamente as cidades de Arax\u00e1 e Tapira, e tamb\u00e9m d\u00e3o apoio operacional \u00e0s Delegacias de Pol\u00edcia Civil respons\u00e1veis por outros 10 munic\u00edpios da regi\u00e3o, incluindo Ibi\u00e1, Pratinha, Campos Altos, Santa Rosa da Serra, Nova Ponte, Santa Juliana, Pedrin\u00f3polis, Perdizes, Sacramento e Conquista.<\/p>\n<p><strong>Projeto Sedes Novas<\/strong><\/p>\n<p>A Delegacia Regional em Arax\u00e1 integra o projeto da PCMG Sedes Novas, que tem como objetivo investir na constru\u00e7\u00e3o de novas estruturas, reformas e manuten\u00e7\u00f5es prediais, proporcionando condi\u00e7\u00f5es adequadas de trabalho para os servidores e melhor atendimento \u00e0 popula\u00e7\u00e3o. Desde 2019, j\u00e1 foram contempladas mais de 200 unidades policiais no estado.<\/p>\n<p>O investimento no pr\u00e9dio da DRPC em Arax\u00e1 \u00e9 de aproximadamente R$ 1,1 milh\u00e3o, considerando recursos provenientes de emendas parlamentares em \u00e2mbito estadual e federal, assim como repasse do Executivo municipal.<\/p>\n<p>\u00a0<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Relacionadas O governador Romeu Zema acompanhou, nesta sexta-feira (14\/11), a evolu\u00e7\u00e3o das interven\u00e7\u00f5es realizadas no novo im\u00f3vel da nova sede da Delegacia Regional de Arax\u00e1, no Alto Parana\u00edba. A unidade ir\u00e1 funcionar de forma integrada \u00e0s outras delegacias especializadas, aprimorando o trabalho da Pol\u00edcia Civil em toda a regi\u00e3o. O pr\u00e9dio localizado na Avenida Tancredo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-44980","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=44980"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44980\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=44980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=44980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=44980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}