{"id":46545,"date":"2026-02-24T18:24:33","date_gmt":"2026-02-24T21:24:33","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/02\/24\/defesa-civil-reforca-monitoramento-diante-da-previsao-de-chuvas-intensas-prefeitura-estancia-turistica-guaratingueta\/"},"modified":"2026-02-24T18:24:33","modified_gmt":"2026-02-24T21:24:33","slug":"defesa-civil-reforca-monitoramento-diante-da-previsao-de-chuvas-intensas-prefeitura-estancia-turistica-guaratingueta","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/02\/24\/defesa-civil-reforca-monitoramento-diante-da-previsao-de-chuvas-intensas-prefeitura-estancia-turistica-guaratingueta\/","title":{"rendered":"Defesa Civil refor\u00e7a monitoramento diante da previs\u00e3o de chuvas intensas \u2013 Prefeitura Est\u00e2ncia Tur\u00edstica Guaratinguet\u00e1"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A Defesa Civil de Guaratinguet\u00e1 participou, na tarde desta ter\u00e7a-feira (24), de uma reuni\u00e3o on-line com coordenadores das Defesas Civis de todo o Estado de S\u00e3o Paulo, al\u00e9m de representantes da Centro Nacional de Gerenciamento de Riscos e Desastres (CENAD) e do Centro Nacional de Monitoramento e Alertas de Desastres Naturais (CEMADEN).<\/p>\n<p>Durante o encontro, foram apresentadas atualiza\u00e7\u00f5es meteorol\u00f3gicas que indicam previs\u00e3o de pancadas de chuva forte para a regi\u00e3o entre os dias 24 a 27 de fevereiro, com possibilidade de acumulados significativos.<\/p>\n<p>Diante desse cen\u00e1rio, h\u00e1 risco de alagamentos pontuais, eleva\u00e7\u00e3o de n\u00edvel de rios e ribeir\u00f5es, al\u00e9m de ocorr\u00eancias como queda de barreiras e de \u00e1rvores, podendo causar transtornos em diferentes pontos do munic\u00edpio.<\/p>\n<p>Como parte do sistema estadual de monitoramento e alerta, a Defesa Civil de Guaratinguet\u00e1 permanece acompanhando as condi\u00e7\u00f5es clim\u00e1ticas e orienta a popula\u00e7\u00e3o, especialmente moradores de \u00e1reas consideradas de risco, a redobrar a aten\u00e7\u00e3o.<\/p>\n<p>Em caso de emerg\u00eancia, a Defesa Civil atende 24 horas pelo telefone (12) 3122-5130. Para situa\u00e7\u00f5es de resgate, o Corpo de Bombeiros pode ser acionado pelo telefone 193.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Defesa Civil de Guaratinguet\u00e1 participou, na tarde desta ter\u00e7a-feira (24), de uma reuni\u00e3o on-line com coordenadores das Defesas Civis de todo o Estado de S\u00e3o Paulo, al\u00e9m de representantes da Centro Nacional de Gerenciamento de Riscos e Desastres (CENAD) e do Centro Nacional de Monitoramento e Alertas de Desastres Naturais (CEMADEN). Durante o encontro, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-46545","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=46545"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46545\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=46545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=46545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=46545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}