{"id":46738,"date":"2026-02-28T09:48:44","date_gmt":"2026-02-28T12:48:44","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/02\/28\/confira-a-agenda-do-consultorio-movel-neste-mes-de-marco-cgnoticias\/"},"modified":"2026-02-28T09:48:44","modified_gmt":"2026-02-28T12:48:44","slug":"confira-a-agenda-do-consultorio-movel-neste-mes-de-marco-cgnoticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/02\/28\/confira-a-agenda-do-consultorio-movel-neste-mes-de-marco-cgnoticias\/","title":{"rendered":"Confira a agenda do Consult\u00f3rio M\u00f3vel neste m\u00eas de mar\u00e7o\u00a0 \u2013 CGNot\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A\u00a0Prefeitura de Campo Grande, atrav\u00e9s da\u00a0Superintend\u00eancia do Bem-Estar Animal (SUBEA),\u00a0divulga\u00a0a\u00a0agenda de mar\u00e7o do Consult\u00f3rio M\u00f3vel, que levar\u00e1 servi\u00e7os gratuitos de bem-estar animal a diferentes bairros de Campo Grande ao longo do m\u00eas.\u00a0<\/p>\n<p>A a\u00e7\u00e3o tem como objetivo ampliar o acesso da popula\u00e7\u00e3o aos servi\u00e7os veterin\u00e1rios b\u00e1sicos, com foco no controle populacional e na sa\u00fade de c\u00e3es e gatos. Os atendimentos ocorrem de segunda-feira a sexta-feira, das 8h \u00e0s 13h e ser\u00e3o distribu\u00eddas 15 senhas para castra\u00e7\u00e3o e 15 senhas para consulta cl\u00ednica, vacina\u00e7\u00e3o antirr\u00e1bica e vermifuga\u00e7\u00e3o, com atendimento por ordem de chegada.\u00a0<\/p>\n<p><strong>Confira a programa\u00e7\u00e3o completa:<\/strong>\u00a0<\/p>\n<ul class=\"wp-block-list\">\n<li><strong>CRAS Jardim Canguru<\/strong>\u00a0<br \/>02\/03 a 06\/03\u00a0<br \/>Das 8h \u00e0s 13h\u00a0<br \/>Rua dos Top\u00f3grafos, 1175 \u2013 Jardim Canguru\u00a0<\/li>\n<\/ul>\n<ul class=\"wp-block-list\">\n<li><strong>Associa\u00e7\u00e3o de Moradores Vila Jacy<\/strong>\u00a0<br \/>09\/03 a 13\/03\u00a0<br \/>Das 8h \u00e0s 13h\u00a0<br \/>Rua Brigadeiro, 1271 \u2013 Vila\u00a0Taquarussu\u00a0<\/li>\n<\/ul>\n<ul class=\"wp-block-list\">\n<li><strong>Par\u00f3quia S\u00e3o Jo\u00e3o Calabria<\/strong>\u00a0<br \/>16\/03 a 20\/03\u00a0<br \/>Das 8h \u00e0s 13h\u00a0<br \/>Rua Oliv\u00e9rio Rodrigues da Luz, 247 \u2013 Jardim\u00a0Macaubas\u00a0<\/li>\n<\/ul>\n<ul class=\"wp-block-list\">\n<li><strong>CEU das Artes \u2013 Parque do Lageado<\/strong>\u00a0<br \/>23\/03 a 27\/03\u00a0<br \/>Das 8h \u00e0s 13h\u00a0<br \/>Rua Marai Del Honor Samper, 981 \u2013 Parque do Lageado\u00a0<\/li>\n<\/ul>\n<ul class=\"wp-block-list\">\n<li><strong>Associa\u00e7\u00e3o de Moradores do Bairro Serravile<\/strong>\u00a0<br \/>30\/03 a 02\/04\u00a0<br \/>Das 8h \u00e0s 13h\u00a0<br \/>Rua\u00a0Capanari, 303 (em frente ao campo de futebol)\u00a0<\/li>\n<\/ul>\n<p>Documentos obrigat\u00f3rios para todos os servi\u00e7os:\u00a0<\/p>\n<ul class=\"wp-block-list\">\n<li>Cadastro no\u00a0Cad\u00danico\u00a0atualizado e impresso (indispens\u00e1vel);\u00a0<\/li>\n<li>Documento oficial com foto;<\/li>\n<li>Comprovante de resid\u00eancia.<\/li>\n<\/ul>\n<p><em>#ParaTodosVerem: A imagem mostra um c\u00e3o preto e marrom sendo atendido por um veterin\u00e1rio dentro do consult\u00f3rio m\u00f3vel<\/em><\/p>\n<\/div>\n<p><script async defer async defer src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=1#xfbml=1&amp;version=v3.2\" id=\"prefeitura-campogrande-script-facebook-sdk-js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0Prefeitura de Campo Grande, atrav\u00e9s da\u00a0Superintend\u00eancia do Bem-Estar Animal (SUBEA),\u00a0divulga\u00a0a\u00a0agenda de mar\u00e7o do Consult\u00f3rio M\u00f3vel, que levar\u00e1 servi\u00e7os gratuitos de bem-estar animal a diferentes bairros de Campo Grande ao longo do m\u00eas.\u00a0 A a\u00e7\u00e3o tem como objetivo ampliar o acesso da popula\u00e7\u00e3o aos servi\u00e7os veterin\u00e1rios b\u00e1sicos, com foco no controle populacional e na sa\u00fade de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-46738","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=46738"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46738\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=46738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=46738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=46738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}