{"id":46873,"date":"2026-03-03T14:06:41","date_gmt":"2026-03-03T17:06:41","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/03\/03\/eleicao-do-conselho-municipal-de-saude-acontece-em-marco-prefeitura-municipal-de-bonito\/"},"modified":"2026-03-03T14:06:41","modified_gmt":"2026-03-03T17:06:41","slug":"eleicao-do-conselho-municipal-de-saude-acontece-em-marco-prefeitura-municipal-de-bonito","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/03\/03\/eleicao-do-conselho-municipal-de-saude-acontece-em-marco-prefeitura-municipal-de-bonito\/","title":{"rendered":"Elei\u00e7\u00e3o do Conselho Municipal de Sa\u00fade acontece em mar\u00e7o &#8211; Prefeitura Municipal de Bonito"},"content":{"rendered":"<p><\/p>\n<div>\n<div class=\"td-post-featured-image\"><\/div>\n<p>O Conselho Municipal de Sa\u00fade de Bonito publicou edital de convoca\u00e7\u00e3o para a elei\u00e7\u00e3o da nova composi\u00e7\u00e3o do colegiado, referente ao bi\u00eanio 2026\/2028. O processo contempla representantes dos usu\u00e1rios do SUS, trabalhadores da sa\u00fade e gestores ou prestadores de servi\u00e7os.<\/p>\n<p>As reuni\u00f5es dos f\u00f3runs setoriais acontecem nos dias 5 e 12 de mar\u00e7o, e a elei\u00e7\u00e3o dos conselheiros titulares e suplentes est\u00e1 marcada para o dia 17 de mar\u00e7o, com posse da Mesa Diretora na mesma data.<\/p>\n<p>As atividades ser\u00e3o realizadas na sede do Conselho, em Bonito, na Rua Dr. Conrado, n\u00ba 854, Vila Don\u00e1ria. A participa\u00e7\u00e3o \u00e9 aberta aos segmentos previstos em legisla\u00e7\u00e3o e regimento interno.<\/p>\n<p>Confira o edital na \u00edntegra.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Municipal de Sa\u00fade de Bonito publicou edital de convoca\u00e7\u00e3o para a elei\u00e7\u00e3o da nova composi\u00e7\u00e3o do colegiado, referente ao bi\u00eanio 2026\/2028. O processo contempla representantes dos usu\u00e1rios do SUS, trabalhadores da sa\u00fade e gestores ou prestadores de servi\u00e7os. As reuni\u00f5es dos f\u00f3runs setoriais acontecem nos dias 5 e 12 de mar\u00e7o, e a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-46873","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=46873"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46873\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=46873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=46873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=46873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}