{"id":47618,"date":"2026-03-20T00:06:36","date_gmt":"2026-03-20T03:06:36","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/03\/20\/elevado-das-bandeiras-e-tuneis-serao-fechados-para-manutencao-nesta-quinta-feira-prefeitura-da-cidade-do-rio-de-janeiro\/"},"modified":"2026-03-20T00:06:36","modified_gmt":"2026-03-20T03:06:36","slug":"elevado-das-bandeiras-e-tuneis-serao-fechados-para-manutencao-nesta-quinta-feira-prefeitura-da-cidade-do-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/03\/20\/elevado-das-bandeiras-e-tuneis-serao-fechados-para-manutencao-nesta-quinta-feira-prefeitura-da-cidade-do-rio-de-janeiro\/","title":{"rendered":"Elevado das Bandeiras e t\u00faneis ser\u00e3o fechados para manuten\u00e7\u00e3o nesta quinta-feira &#8211; Prefeitura da Cidade do Rio de Janeiro"},"content":{"rendered":"<p><\/p>\n<div id=\"main\">\n<div class=\"wrapper-breadcrumbs\" wp_automatic_readability=\"34.875956504229\">\n<div class=\"image-post\" wp_automatic_readability=\"33\">\n                     O tablado inferior do Elevado das Bandeiras ser\u00e1 fechado  no sentido S\u00e3o Conrado &#8211; Foto: Prefeitura do Rio                  <\/div>\n<p>O tablado inferior do Elevado das Bandeiras ser\u00e1 fechado no sentido S\u00e3o Conrado, das 23h desta quinta-feira (19\/3) \u00e0s 4h30 de sexta-feira (20\/3), para manuten\u00e7\u00e3o. A liga\u00e7\u00e3o Barra da Tijuca-S\u00e3o Conrado ser\u00e1 feita pelo tablado superior.<\/p>\n<p>O T\u00fanel Rebou\u00e7as ser\u00e1 fechado, a partir das 23h30 desta quinta-feira (19\/3) \u00e0s 5h de sexta-feira (20\/3), no sentido Lagoa, para manuten\u00e7\u00e3o. Durante o fechamento, o tr\u00e2nsito de ve\u00edculos seguir\u00e1 por uma faixa revers\u00edvel \u00e0 esquerda no sentido Centro, operando em dire\u00e7\u00e3o a Zona Sul. As outras duas faixas funcionar\u00e3o no sentido Centro.<\/p>\n<p>Os t\u00faneis Zuzu Angel e Ac\u00fastico Rafael Mascarenhas ser\u00e3o fechados no sentido S\u00e3o Conrado, das 23h30 desta quinta-feira (19\/3) \u00e0s 5h de sexta-feira (20\/3), para servi\u00e7os de manuten\u00e7\u00e3o. A principal op\u00e7\u00e3o para desvio \u00e9 a Avenida Niemeyer.<\/p>\n<p>O T\u00fanel Vice-Presidente da Rep\u00fablica Jos\u00e9 Alencar ser\u00e1 interditado, nesta quinta-feira (19\/3), no sentido Barra da Tijuca, das 23h \u00e0s 4h de sexta-feira (20\/3), para manuten\u00e7\u00e3o. Os ve\u00edculos que seguem em dire\u00e7\u00e3o a Barra ser\u00e3o desviados pela Serra da Grota Funda (Avenida Artur Xex\u00e9o). Os \u00f4nibus do BRT que seguem para Barra dever\u00e3o trafegar pela calha da galeria oposta. J\u00e1 os \u00f4nibus que circulam originalmente pela calha no sentido Santa Cruz seguir\u00e3o pela pista comum a todos os ve\u00edculos.<\/p>\n<p>Sinaliza\u00e7\u00e3o especifica ser\u00e1 instalada para orientar e alertar os motoristas. Operadores da CET-Rio v\u00e3o monitorar as condi\u00e7\u00f5es do tr\u00e2nsito e atuar, se necess\u00e1rio. Al\u00e9m disso, os tempos semaf\u00f3ricos ser\u00e3o ajustados para melhorar a fluidez na rota de desvio e nos principais corredores das regi\u00f5es.<\/p>\n<p>             <!-- Compartilhe ---><\/p>\n<p>\t\t\t <!-- TAGS --><\/p>\n<section class=\"category-tags\">\n<div class=\"marcacao-category\">\n<article class=\"category-post\">\n<p>Categoria: <\/p>\n<\/article>\n<li>19 de mar\u00e7o de 2026<\/li><\/div>\n<article class=\"tags\">\n\t\t\t\t\tMarca\u00e7\u00f5es: CET-Rio Elevado das Bandeiras interdi\u00e7\u00f5es manuten\u00e7\u00e3o tr\u00e2nsito t\u00faneis<br \/><\/article>\n<\/section>\n<p>            <!-- Mais Not&iacute;cias --><\/p>\n<p>\t\t<!-- Conte&uacute;do SIDEBAR --><\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O tablado inferior do Elevado das Bandeiras ser\u00e1 fechado no sentido S\u00e3o Conrado &#8211; Foto: Prefeitura do Rio O tablado inferior do Elevado das Bandeiras ser\u00e1 fechado no sentido S\u00e3o Conrado, das 23h desta quinta-feira (19\/3) \u00e0s 4h30 de sexta-feira (20\/3), para manuten\u00e7\u00e3o. A liga\u00e7\u00e3o Barra da Tijuca-S\u00e3o Conrado ser\u00e1 feita pelo tablado superior. O [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-47618","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=47618"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47618\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=47618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=47618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=47618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}