{"id":47649,"date":"2026-03-20T14:48:42","date_gmt":"2026-03-20T17:48:42","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/03\/20\/prazo-ja-comecou-prefeitura-estancia-turistica-guaratingueta\/"},"modified":"2026-03-20T14:48:42","modified_gmt":"2026-03-20T17:48:42","slug":"prazo-ja-comecou-prefeitura-estancia-turistica-guaratingueta","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/03\/20\/prazo-ja-comecou-prefeitura-estancia-turistica-guaratingueta\/","title":{"rendered":"prazo j\u00e1 come\u00e7ou \u2013 Prefeitura Est\u00e2ncia Tur\u00edstica Guaratinguet\u00e1"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Est\u00e1 aberto o per\u00edodo para o alistamento militar obrigat\u00f3rio.<\/p>\n<p>Jovens nascidos em 2008 devem realizar o alistamento at\u00e9 o dia 30 de junho de 2026.<\/p>\n<p>O procedimento \u00e9 r\u00e1pido, gratuito e pode ser feito pela internet, por meio do site \ud83d\udc49 alistamento.eb.mil.br ou pelo aplicativo do Ex\u00e9rcito Brasileiro.<\/p>\n<p>Ficar atento ao prazo \u00e9 fundamental para evitar pend\u00eancias com a Justi\u00e7a Militar e garantir o acesso a documentos e servi\u00e7os importantes.<\/p>\n<p>Em caso de d\u00favidas, procure a Junta de Servi\u00e7o Militar de Guaratinguet\u00e1, localizada na Rua Prudente de Moraes, 64 \u2013 Centro.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 aberto o per\u00edodo para o alistamento militar obrigat\u00f3rio. Jovens nascidos em 2008 devem realizar o alistamento at\u00e9 o dia 30 de junho de 2026. O procedimento \u00e9 r\u00e1pido, gratuito e pode ser feito pela internet, por meio do site \ud83d\udc49 alistamento.eb.mil.br ou pelo aplicativo do Ex\u00e9rcito Brasileiro. Ficar atento ao prazo \u00e9 fundamental para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-47649","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=47649"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47649\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=47649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=47649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=47649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}