{"id":47809,"date":"2026-03-24T10:30:37","date_gmt":"2026-03-24T13:30:37","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/03\/24\/indice-de-alfabetizacao-cresce-e-garante-selo-ouro-pela-2a-vez-a-capital-cgnoticias\/"},"modified":"2026-03-24T10:30:37","modified_gmt":"2026-03-24T13:30:37","slug":"indice-de-alfabetizacao-cresce-e-garante-selo-ouro-pela-2a-vez-a-capital-cgnoticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/03\/24\/indice-de-alfabetizacao-cresce-e-garante-selo-ouro-pela-2a-vez-a-capital-cgnoticias\/","title":{"rendered":"\u00cdndice de alfabetiza\u00e7\u00e3o cresce e garante Selo Ouro pela 2\u00aa vez \u00e0 Capital \u2013 CGNot\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Campo Grande conquistou, pela segunda vez consecutiva, o Selo Ouro Nacional do Compromisso com a Alfabetiza\u00e7\u00e3o, concedido pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC). A premia\u00e7\u00e3o foi entregue nesta segunda-feira (23), em Bras\u00edlia, e reconhece munic\u00edpios que desenvolvem pol\u00edticas p\u00fablicas eficazes para garantir que as crian\u00e7as sejam alfabetizadas na idade adequada.<\/p>\n<p>O reconhecimento integra o programa Compromisso Nacional Crian\u00e7a Alfabetizada, que incentiva estados e munic\u00edpios a adotarem a\u00e7\u00f5es estruturadas para fortalecer a alfabetiza\u00e7\u00e3o nos primeiros anos da educa\u00e7\u00e3o b\u00e1sica. Representando o munic\u00edpio, o secret\u00e1rio municipal de Educa\u00e7\u00e3o, Lucas Henrique Bitencourt, esteve na capital federal para receber o pr\u00eamio.<\/p>\n<p>A conquista reflete os avan\u00e7os da Rede Municipal de Ensino de Campo Grande nos \u00faltimos anos. O munic\u00edpio apresentou crescimento significativo nos indicadores de alfabetiza\u00e7\u00e3o, saindo de 41% para 61% de crian\u00e7as alfabetizadas. Esse resultado \u00e9 fruto de pol\u00edticas voltadas ao acompanhamento pedag\u00f3gico, \u00e0 forma\u00e7\u00e3o continuada de professores e ao fortalecimento das pr\u00e1ticas de ensino nas escolas.<\/p>\n<p>Segundo o secret\u00e1rio, o reconhecimento nacional refor\u00e7a o compromisso da gest\u00e3o com a qualidade da educa\u00e7\u00e3o p\u00fablica. Ele destacou que o avan\u00e7o nos \u00edndices demonstra que o trabalho desenvolvido por professores, gestores e equipes pedag\u00f3gicas tem gerado resultados concretos na aprendizagem das crian\u00e7as.<\/p>\n<p>O Selo Ouro \u00e9 concedido a munic\u00edpios que apresentam a\u00e7\u00f5es efetivas e resultados consistentes na garantia da alfabetiza\u00e7\u00e3o na idade certa, valorizando iniciativas que fortalecem o processo de ensino nos anos iniciais do ensino fundamental.<\/p>\n<p>A premia\u00e7\u00e3o reafirma o compromisso da Prefeitura de Campo Grande com o avan\u00e7o da educa\u00e7\u00e3o p\u00fablica, por meio de investimentos em pol\u00edticas educacionais que assegurem o desenvolvimento e o futuro dos alunos da rede municipal.<\/p>\n<p><em>#ParaTodosVerem: A imagem de capa mostra os representantes da Semed segurando a bandeira da cidade e o selo de ouro<\/em><\/p>\n<\/div>\n<p><script async defer async defer src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=1#xfbml=1&amp;version=v3.2\" id=\"prefeitura-campogrande-script-facebook-sdk-js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campo Grande conquistou, pela segunda vez consecutiva, o Selo Ouro Nacional do Compromisso com a Alfabetiza\u00e7\u00e3o, concedido pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC). A premia\u00e7\u00e3o foi entregue nesta segunda-feira (23), em Bras\u00edlia, e reconhece munic\u00edpios que desenvolvem pol\u00edticas p\u00fablicas eficazes para garantir que as crian\u00e7as sejam alfabetizadas na idade adequada. O reconhecimento integra o programa Compromisso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-47809","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=47809"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47809\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=47809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=47809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=47809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}