{"id":48300,"date":"2026-04-04T07:39:50","date_gmt":"2026-04-04T10:39:50","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/04\/04\/confira-a-interdicao-deste-sabado-4-cgnoticias\/"},"modified":"2026-04-04T07:39:50","modified_gmt":"2026-04-04T10:39:50","slug":"confira-a-interdicao-deste-sabado-4-cgnoticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/04\/04\/confira-a-interdicao-deste-sabado-4-cgnoticias\/","title":{"rendered":"Confira a interdi\u00e7\u00e3o deste s\u00e1bado (4) \u2013 CGNot\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Motoristas que passam pelo bairro Amamba\u00ed devem ficar atentos neste s\u00e1bado (4), devido a altera\u00e7\u00f5es no tr\u00e2nsito por conta da programa\u00e7\u00e3o da Semana Santa em Campo Grande.<\/p>\n<p>A Ag\u00eancia Municipal de Transporte e Tr\u00e2nsito (Agetran) informa que haver\u00e1 interdi\u00e7\u00e3o para a realiza\u00e7\u00e3o de um evento religioso na Igreja Assembleia de Deus Miss\u00f5es.<\/p>\n<p><strong>Data:<\/strong> 04\/04\/2026<br \/><strong>Hor\u00e1rio:<\/strong> 08h \u00e0s 23h<br \/><strong>Local:<\/strong> Rua Brilhante, n\u00ba 1408, entre as ruas Apor\u00e9 e Iguassu \u2013 bairro Amamba\u00ed<\/p>\n<p>A orienta\u00e7\u00e3o \u00e9 respeitar a sinaliza\u00e7\u00e3o e buscar rotas alternativas.<\/p>\n<p><em>#ParaTodosVerem: Na imagem em destaque mostra uma via interditada <\/em><\/p>\n<\/div>\n<p><script async defer async defer src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=1#xfbml=1&amp;version=v3.2\" id=\"prefeitura-campogrande-script-facebook-sdk-js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Motoristas que passam pelo bairro Amamba\u00ed devem ficar atentos neste s\u00e1bado (4), devido a altera\u00e7\u00f5es no tr\u00e2nsito por conta da programa\u00e7\u00e3o da Semana Santa em Campo Grande. A Ag\u00eancia Municipal de Transporte e Tr\u00e2nsito (Agetran) informa que haver\u00e1 interdi\u00e7\u00e3o para a realiza\u00e7\u00e3o de um evento religioso na Igreja Assembleia de Deus Miss\u00f5es. Data: 04\/04\/2026Hor\u00e1rio: 08h [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-48300","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=48300"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48300\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=48300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=48300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=48300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}