{"id":48305,"date":"2026-04-04T11:10:50","date_gmt":"2026-04-04T14:10:50","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/04\/04\/agencia-minas-gerais-presidio-de-janauba-promove-acao-de-limpeza-em-espacos-publicos-do-municipio-com-mao-de-obra-de-custodiados-2\/"},"modified":"2026-04-04T11:10:50","modified_gmt":"2026-04-04T14:10:50","slug":"agencia-minas-gerais-presidio-de-janauba-promove-acao-de-limpeza-em-espacos-publicos-do-municipio-com-mao-de-obra-de-custodiados-2","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/04\/04\/agencia-minas-gerais-presidio-de-janauba-promove-acao-de-limpeza-em-espacos-publicos-do-municipio-com-mao-de-obra-de-custodiados-2\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Pres\u00eddio de Jana\u00faba promove a\u00e7\u00e3o de limpeza em espa\u00e7os p\u00fablicos do munic\u00edpio com m\u00e3o de obra de custodiados"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A Pol\u00edcia Penal de Minas Gerais (PPMG), por meio do Pres\u00eddio de Jana\u00faba, no Norte do estado,\u00a0 iniciou nesta semana uma a\u00e7\u00e3o de apoio \u00e0 comunidade local com a participa\u00e7\u00e3o de custodiados da unidade na realiza\u00e7\u00e3o de servi\u00e7os de limpeza e capina em \u00e1rea de uma escola municipal.<\/p>\n<p>O projeto tem como objetivo contribuir para a conserva\u00e7\u00e3o dos espa\u00e7os p\u00fablicos da regi\u00e3o e contempla a limpeza das escolas p\u00fablicas, do Hospital Regional e do Cemit\u00e9rio de Jana\u00faba. Al\u00e9m disso, a a\u00e7\u00e3o fortalece o processo de reintegra\u00e7\u00e3o das pessoas privadas de liberdade por meio do trabalho, que incentiva disciplina e responsabilidade.<\/p>\n<p>Segundo o diretor-geral do Pres\u00eddio de Jana\u00faba, Clayton Davidson Gomes de Souza, a iniciativa vai al\u00e9m da manuten\u00e7\u00e3o de espa\u00e7os p\u00fablicos, sendo um exemplo dentre os projetos de ressocializa\u00e7\u00e3o no sistema prisional.<\/p>\n<p>\u201cEssas atividades favorecem a reintegra\u00e7\u00e3o social, ao permitir que os detentos participem de a\u00e7\u00f5es que beneficiam diretamente a sociedade. Dessa forma, a Pol\u00edcia Penal\u00a0reafirma um compromisso, n\u00e3o s\u00f3 com a seguran\u00e7a mas tamb\u00e9m com a promo\u00e7\u00e3o de pol\u00edticas p\u00fablicas voltadas \u00e0 humaniza\u00e7\u00e3o e ressocializa\u00e7\u00e3o\u201d.<\/p>\n<p>Todas as atividades s\u00e3o realizadas sob supervis\u00e3o e em conformidade com as normas de seguran\u00e7a vigentes, com acompanhamento e escolta da Pol\u00edcia Penal, garantindo a integridade do processo e de todos os envolvidos, de acordo com os processos de ressocializa\u00e7\u00e3o por trabalho desenvolvidos dentro do Departamento Penitenci\u00e1rio de Minas Gerais (Depen-MG).\u00a0<\/p>\n<p>\u201cEstamos desenvolvendo a\u00e7\u00f5es de relevante interesse social em parceria com a comunidade local, utilizando a m\u00e3o de obra de custodiados. Essas atividades contribuem para a melhoria dos espa\u00e7os p\u00fablicos e promovem disciplina, responsabilidade e valoriza\u00e7\u00e3o do trabalho dos presos\u201d, finalizou o diretor.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Penal de Minas Gerais (PPMG), por meio do Pres\u00eddio de Jana\u00faba, no Norte do estado,\u00a0 iniciou nesta semana uma a\u00e7\u00e3o de apoio \u00e0 comunidade local com a participa\u00e7\u00e3o de custodiados da unidade na realiza\u00e7\u00e3o de servi\u00e7os de limpeza e capina em \u00e1rea de uma escola municipal. O projeto tem como objetivo contribuir para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-48305","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=48305"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48305\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=48305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=48305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=48305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}