{"id":49777,"date":"2026-05-08T20:54:40","date_gmt":"2026-05-08T23:54:40","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/08\/corrida-do-consumidor-acontece-na-tarde-deste-sabado-no-busto-de-tamandare\/"},"modified":"2026-05-08T20:54:40","modified_gmt":"2026-05-08T23:54:40","slug":"corrida-do-consumidor-acontece-na-tarde-deste-sabado-no-busto-de-tamandare","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/08\/corrida-do-consumidor-acontece-na-tarde-deste-sabado-no-busto-de-tamandare\/","title":{"rendered":"Corrida do Consumidor acontece na tarde deste s\u00e1bado, no Busto de Tamandar\u00e9"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Ap\u00f3s a entrega dos kits, que termina neste s\u00e1bado (9), \u00e0s 12h, \u00e9 hora dos participantes vestirem a camisa do evento e se dirigirem \u00e0 Corrida do Consumidor 2026 da Secretaria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Jo\u00e3o Pessoa (Procon-JP) no Busto de Tamandar\u00e9, a partir das 16h. O pagode de Gil Junior vai animar os atletas e o p\u00fablico em geral a partir das 17h, em arena montada no local.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><\/figure>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<\/figure>\n<p>O secret\u00e1rio do Procon-JP, Junior Pires, j\u00e1 comemora o sucesso da Corrida do Consumidor 2026 e lembra que, ap\u00f3s a corrida, os atletas far\u00e3o uma grande confraterniza\u00e7\u00e3o ao som do pagode de Gil Junior. \u201cEsperamos muita alegria e disposi\u00e7\u00e3o de todos os presentes. E quem tiver na Orla no fim da tarde, tamb\u00e9m pode vir comemorar com a gente\u201d, afirmou.<\/p>\n<p>A terceira vers\u00e3o da Corrida do Consumidor de Jo\u00e3o Pessoa ter\u00e1 o percurso de 5km e 10km, divididos nas categorias de p\u00fablico em geral; PCD cadeirante ou n\u00e3o cadeirante. \u201cVamos todos nos encontrar no Busto de Tamandar\u00e9 a partir das 16h para a Corrida do Consumidor e para o show de pagode que ocorrer\u00e1 logo em seguida\u201d, refor\u00e7a Junior Pires.<\/p>\n<p><strong>Percursos<\/strong> \u2013 A largada da Corrida do Consumidor acontecer\u00e1, \u00e0s 16h, do Busto de Tamandar\u00e9, seguindo pela Avenida Cabo Branco at\u00e9 a Funda\u00e7\u00e3o Casa de Jos\u00e9 Am\u00e9rico, onde ocorrer\u00e1 o retorno para quem far\u00e1 o percurso de 5 km, fazendo o trajeto inverso. Os corredores inscritos para percorrer os 10 km far\u00e3o duas voltas, tamb\u00e9m at\u00e9 a Funda\u00e7\u00e3o Casa de Jos\u00e9 Am\u00e9rico, para encerramento do evento esportivo, no Busto de Tamandar\u00e9.<\/p>\n<p><strong>Gil Junio<\/strong><strong>r<\/strong> \u2013 O m\u00fasico Gil Junior come\u00e7a a festa musical a partir das 17h, com o show se estendendo at\u00e9 as 22h. Entusiasta dos ritmos pagode e samba, Gil Junior j\u00e1 \u00e9 conhecido do p\u00fablico pessoense, que o acompanha nos eventos do g\u00eanero.<\/p>\n<p><strong>Se<\/strong><strong>rvi\u00e7o:<\/strong><\/p>\n<p><strong>Evento:<\/strong> Corrida do Consumidor 2026<\/p>\n<p><strong>Data:<\/strong> s\u00e1bado (9)<\/p>\n<p><strong>Hor\u00e1rio: <\/strong>largada da corrida \u00e0s 16h e in\u00edcio do show \u00e0s 17h<\/p>\n<p><strong>Local<\/strong>: Busto de Tamandar\u00e9<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a entrega dos kits, que termina neste s\u00e1bado (9), \u00e0s 12h, \u00e9 hora dos participantes vestirem a camisa do evento e se dirigirem \u00e0 Corrida do Consumidor 2026 da Secretaria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Jo\u00e3o Pessoa (Procon-JP) no Busto de Tamandar\u00e9, a partir das 16h. O pagode de Gil Junior [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-49777","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=49777"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49777\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=49777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=49777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=49777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}