{"id":49801,"date":"2026-05-09T11:33:44","date_gmt":"2026-05-09T14:33:44","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/09\/galeria-de-vidro-recebe-exposicao-entre-portais-e-passos-cgnoticias\/"},"modified":"2026-05-09T11:33:44","modified_gmt":"2026-05-09T14:33:44","slug":"galeria-de-vidro-recebe-exposicao-entre-portais-e-passos-cgnoticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/09\/galeria-de-vidro-recebe-exposicao-entre-portais-e-passos-cgnoticias\/","title":{"rendered":"Galeria de Vidro recebe exposi\u00e7\u00e3o \u201cEntre Portais e Passos\u201d \u2013 CGNot\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A Galeria de Vidro, em Campo Grande, recebe a exposi\u00e7\u00e3o \u201cEntre Portais e Passos\u201d, da artista Ana Maria Maluf Rabacow. A mostra prop\u00f5e ao p\u00fablico uma experi\u00eancia sens\u00edvel que une arte, mem\u00f3ria e movimento em uma narrativa visual marcada pela delicadeza. A exposi\u00e7\u00e3o vai ficar at\u00e9 o dia  23 de maio de 2026<\/p>\n<p>O evento re\u00fane obras que estabelecem um di\u00e1logo entre elementos da arquitetura especialmente os portais antigos, carregados de simbolismo e a leveza das bailarinas em movimento. A proposta \u00e9 explorar contrastes entre o permanente e o ef\u00eamero, convidando o visitante a refletir sobre o tempo, as transforma\u00e7\u00f5es e os caminhos percorridos ao longo da vida.<\/p>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<p>Com tra\u00e7os que transitam entre o concreto e o et\u00e9reo, cada obra conduz o espectador por uma travessia simb\u00f3lica, onde gesto e espa\u00e7o se encontram. A artista constr\u00f3i, assim, um percurso contemplativo que desperta sensa\u00e7\u00f5es e interpreta\u00e7\u00f5es individuais, valorizando a subjetividade de quem observa.<\/p>\n<p>Instalada no complexo da Plataforma Cultural, na Esplanada Ferrovi\u00e1ria, a Galeria de Vidro abre espa\u00e7o para uma experi\u00eancia art\u00edstica que alia sensibilidade est\u00e9tica e profundidade simb\u00f3lica, refor\u00e7ando a import\u00e2ncia da arte como meio de express\u00e3o e reflex\u00e3o.<\/p>\n<p>A abertura oficial come\u00e7ou ontem dia 8 de maio, \u00e0s 19h30. A visita\u00e7\u00e3o \u00e9 gratuita e pode ser feita de segunda a sexta-feira, das 8h \u00e0s 20h, e aos s\u00e1bados, das 8h \u00e0s 12h.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><\/figure>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<\/figure>\n<\/div>\n<p><script async defer async defer src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=1#xfbml=1&amp;version=v3.2\" id=\"prefeitura-campogrande-script-facebook-sdk-js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Galeria de Vidro, em Campo Grande, recebe a exposi\u00e7\u00e3o \u201cEntre Portais e Passos\u201d, da artista Ana Maria Maluf Rabacow. A mostra prop\u00f5e ao p\u00fablico uma experi\u00eancia sens\u00edvel que une arte, mem\u00f3ria e movimento em uma narrativa visual marcada pela delicadeza. A exposi\u00e7\u00e3o vai ficar at\u00e9 o dia 23 de maio de 2026 O evento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-49801","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=49801"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49801\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=49801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=49801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=49801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}