{"id":49812,"date":"2026-05-09T17:12:53","date_gmt":"2026-05-09T20:12:53","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/09\/prefeitura-amplia-a-area-de-atuacao-da-divisao-de-elite-da-gm-rio-forca-municipal-para-botafogo-prefeitura-da-cidade-do-rio-de-janeiro\/"},"modified":"2026-05-09T17:12:53","modified_gmt":"2026-05-09T20:12:53","slug":"prefeitura-amplia-a-area-de-atuacao-da-divisao-de-elite-da-gm-rio-forca-municipal-para-botafogo-prefeitura-da-cidade-do-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/09\/prefeitura-amplia-a-area-de-atuacao-da-divisao-de-elite-da-gm-rio-forca-municipal-para-botafogo-prefeitura-da-cidade-do-rio-de-janeiro\/","title":{"rendered":"Prefeitura amplia a \u00e1rea de atua\u00e7\u00e3o da Divis\u00e3o de Elite da GM-Rio &#8211; For\u00e7a Municipal para Botafogo &#8211; Prefeitura da Cidade do Rio de Janeiro"},"content":{"rendered":"<p><\/p>\n<div id=\"main\">\n<div class=\"wrapper-breadcrumbs\" wp_automatic_readability=\"57.700419856755\">\n<div class=\"image-post\" wp_automatic_readability=\"33\">\n                     Policiamento come\u00e7a neste domingo (10) com atua\u00e7\u00e3o em tr\u00eas per\u00edmetros do bairro. Foto: Marco Antonio Lima\n                  <\/div>\n<p>A Divis\u00e3o de Elite da GM-Rio \u2013 For\u00e7a Municipal inicia neste domingo (10\/05) o policiamento em Botafogo, com atua\u00e7\u00e3o em tr\u00eas per\u00edmetros do bairro. O planejamento operacional e o balan\u00e7o das a\u00e7\u00f5es desde o in\u00edcio da atua\u00e7\u00e3o nas ruas, em 15 de mar\u00e7o, foram apresentados neste s\u00e1bado (09\/05) pelo prefeito do Rio, Eduardo Cavaliere, e pelo secret\u00e1rio de Seguran\u00e7a Urbana, Brenno Carnevale, a empres\u00e1rios, comerciantes e representantes locais. O encontro contou tamb\u00e9m com a participa\u00e7\u00e3o da Diretora-Geral da For\u00e7a Municipal, Aim\u00e9e de La Torre.<\/p>\n<blockquote wp_automatic_readability=\"13\">\n<p>\u2013 Hoje completamos 60 dias de atua\u00e7\u00e3o da For\u00e7a Municipal com mais de 400 pris\u00f5es efetuadas, milhares de abordagens, com os crimes sendo reduzidos nas \u00e1reas onde a For\u00e7a Municipal atua. E, o mais importante, com a confian\u00e7a da popula\u00e7\u00e3o de que esse conjunto de agentes da Divis\u00e3o de Elite est\u00e1 pronta para seguir a sua miss\u00e3o. Estamos fazendo o trabalho da Fo\u00e7a Municipal naquilo que \u00e9 a nossa responsabilidade: enfrentar e reduzir os roubos e furtos nas \u00e1reas de maior ocorr\u00eancia desses crimes na cidade, onde est\u00e3o as manchas criminais \u2013 destacou o prefeito do Rio.<\/p>\n<\/blockquote>\n<p>O secret\u00e1rio de Seguran\u00e7a Urbana apresentou o balan\u00e7o desses primeiros dias de atua\u00e7\u00e3o da For\u00e7a Municipal, entre 15 de mar\u00e7o a 4 de maio, com destaque para as 449 pris\u00f5es e deten\u00e7\u00f5es efetuadas. Foram 2,3 mil abordagens e 273 ve\u00edculos tiveram seus registros verificados. Uma arma de fogo foi apreendida, mais outras quatro r\u00e9plicas e dez armas brancas. Foram recuperados 74 celulares, 12 cord\u00f5es recuperados, 10 bicicletas e 52 motos foram recuperadas ou apreendidas.<\/p>\n<p>E em Botafogo, o policiamento ser\u00e1 realizado em tr\u00eas per\u00edmetros:\u00a0 Rua Lauro M\u00fcller x Rua General Severiano x Av. Venceslau Br\u00e1s; do entorno do Metr\u00f4 Botafogo, incluindo a Rua S\u00e3o Clemente, a Rua Volunt\u00e1rios da P\u00e1tria e transversais; al\u00e9m do eixo da Praia de Botafogo x Rua Marqu\u00eas de Abrantes, e algumas ruas do bairro do Flamengo.<\/p>\n<blockquote wp_automatic_readability=\"14\">\n<p>\u2013 Vamos atuar em tr\u00eas conjuntos de eixos de v\u00e1rias ruas que concentram furtos e roubos. Vamos pegar desde a Praia de Botafogo passando pelo metr\u00f4, Volunt\u00e1rios da P\u00e1tria, S\u00e3o Clemente, tamb\u00e9m Lauro Muller e Venceslau Br\u00e1s, v\u00e1rias ruas que de acordo com os dados consolidados, concentram esse tipo de crime. Vai ser um policiamento ostensivo, com a popula\u00e7\u00e3o percebendo os agentes da For\u00e7a Municipal nas ruas \u2013 explicou Brenno Carnevale.<\/p>\n<\/blockquote>\n<p>A expans\u00e3o para o bairro marca a segunda fase da atua\u00e7\u00e3o da For\u00e7a Municipal na Zona Sul da cidade, iniciada em 15 de mar\u00e7o, na regi\u00e3o do Jardim de Alah, no Leblon. Com isso, Botafogo se junta aos outros cinco per\u00edmetros j\u00e1 implementados ao planejamento da For\u00e7a Municipal: Rodovi\u00e1ria do Rio X Terminal Gentileza X Esta\u00e7\u00e3o Leopoldina; Jardim de Alah; Avenida Presidente Vargas X Campo de Santana X Central do Brasil X Cinel\u00e2ndia; Campo Grande \u2013 esta\u00e7\u00e3o de trem X cal\u00e7ad\u00e3o; Tijuca \u2013 S\u00e3o Francisco Xavier X Afonso Pena.<\/p>\n<p>Ao todo, 22 regi\u00f5es com alta incid\u00eancia de roubos e furtos foram mapeadas na cidade. A expans\u00e3o do policiamento ocorre de forma gradual, com base na an\u00e1lise de manchas criminais, sendo previamente apresentada nas reuni\u00f5es do CompStat Rio.<\/p>\n<p>             <!-- Compartilhe ---><\/p>\n<p>\t\t\t <!-- TAGS --><\/p>\n<section class=\"category-tags\">\n<div class=\"marcacao-category\">\n<article class=\"category-post\">\n<p>Categoria: <\/p>\n<\/article>\n<li>9 de maio de 2026<\/li><\/div>\n<article class=\"tags\">\n\t\t\t\t\tMarca\u00e7\u00f5es: balan\u00e7o Botafogo mancha criminal Secretaria de Seguran\u00e7a Urbana<br \/><\/article>\n<\/section>\n<p>            <!-- Mais Not&iacute;cias --><\/p>\n<p>\t\t<!-- Conte&uacute;do SIDEBAR --><\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Policiamento come\u00e7a neste domingo (10) com atua\u00e7\u00e3o em tr\u00eas per\u00edmetros do bairro. Foto: Marco Antonio Lima A Divis\u00e3o de Elite da GM-Rio \u2013 For\u00e7a Municipal inicia neste domingo (10\/05) o policiamento em Botafogo, com atua\u00e7\u00e3o em tr\u00eas per\u00edmetros do bairro. O planejamento operacional e o balan\u00e7o das a\u00e7\u00f5es desde o in\u00edcio da atua\u00e7\u00e3o nas ruas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-49812","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=49812"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49812\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=49812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=49812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=49812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}