{"id":49820,"date":"2026-05-09T22:06:43","date_gmt":"2026-05-10T01:06:43","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/09\/agencia-minas-gerais-vale-do-litio-completa-tres-anos-marcados-por-avanco-no-pib-de-municipios-do-jequitinhonha-2\/"},"modified":"2026-05-09T22:06:43","modified_gmt":"2026-05-10T01:06:43","slug":"agencia-minas-gerais-vale-do-litio-completa-tres-anos-marcados-por-avanco-no-pib-de-municipios-do-jequitinhonha-2","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/09\/agencia-minas-gerais-vale-do-litio-completa-tres-anos-marcados-por-avanco-no-pib-de-municipios-do-jequitinhonha-2\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Vale do L\u00edtio completa tr\u00eas anos marcados por avan\u00e7o no PIB de munic\u00edpios do Jequitinhonha"},"content":{"rendered":"<p><\/p>\n<div>\n<section class=\"news-related \/ col-md-4 col-lg-3 \/ margin-md-bottom-2 margin-left-1 \/ pull-right \/ hidden-xs hidden-sm\">\n<header>\n<p class=\"text-title-section \/ margin-bottom-1\">Relacionadas<\/p>\n<\/header>\n<p>\t\t\t\t\t\t\t<main><\/p>\n<hr class=\"row margin-md-bottom-2\"\/>\n\t\t\t\t\t\t\t<\/main><br \/>\n\t\t\t\t\t\t<\/section>\n<p>Neste s\u00e1bado (9\/5), o projeto\u00a0<u>Vale do L\u00edtio<\/u>, iniciativa do\u00a0<u>Governo de Minas<\/u>\u00a0para estabelecer o estado como protagonista na cadeia de valor do l\u00edtio, completa tr\u00eas anos. Desde o lan\u00e7amento na Nasdaq, maior bolsa de valores do mundo, em Nova Iorque, nos Estados Unidos, a a\u00e7\u00e3o tamb\u00e9m promoveu o avan\u00e7o econ\u00f4mico de munic\u00edpios da regi\u00e3o em diversas frentes.<\/p>\n<p>O Produto Interno Bruto (PIB) do Vale do Jequitinhonha alcan\u00e7ou R$ 12,56 bilh\u00f5es em 2023, segundo os \u00faltimos dados divulgados pelo IBGE. Entre as cidades com atividades miner\u00e1rias ligadas ao l\u00edtio, Ara\u00e7ua\u00ed e Itinga, o PIB dobrou ap\u00f3s o lan\u00e7amento do projeto, com aumento de 108,1% e 91,3% entre 2021 e 2023, respectivamente.<\/p>\n<p>No mesmo per\u00edodo, o PIB per capita de Ara\u00e7ua\u00ed cresceu 122,7% e Itinga 109,5%. Al\u00e9m disso, em n\u00fameros absolutos, Ara\u00e7ua\u00ed apresentou o maior PIB per capita da regi\u00e3o (R$ 31,5 mil), superando at\u00e9 mesmo munic\u00edpios como T\u00e9ofilo Otoni, que possui uma popula\u00e7\u00e3o quatro vezes maior.<\/p>\n<p>Ainda, os Vales do Jequitinhonha e Mucuri mant\u00eam destaque na abertura de empresas, tendo apresentado o maior crescimento proporcional\u00a0em 2023 e 2025, e a segunda com melhor desempenho em 2024.<\/p>\n<p>\u201cMinas Gerais tem convertido o potencial do l\u00edtio em resultados diretos para a popula\u00e7\u00e3o do Jequitinhonha, com mais empregos, rendas e oportunidades. Observamos tamb\u00e9m uma diversifica\u00e7\u00e3o na economia, uma vez que, a partir dos investimentos atra\u00eddos, outros setores, como servi\u00e7os e com\u00e9rcio, tamb\u00e9m se tornam janelas de oportunidades para empreendedores da regi\u00e3o\u201d, afirma a secret\u00e1ria de\u00a0<u>Estado de Desenvolvimento Econ\u00f4mico<\/u>, Mila Corr\u00eaa da Costa.<\/p>\n<p><strong>Cientistas transformam rejeitos em fertilizantes<\/strong><\/p>\n<p>A partir do projeto Vale do L\u00edtio, o Governo de Minas, por meio da\u00a0<u>Funda\u00e7\u00e3o de Amparo \u00e0 Pesquisa do Estado de Minas Gerais (Fapemig)<\/u>, j\u00e1 destinou mais de R$ 13,2 milh\u00f5es em projetos ligados ao mineral cr\u00edtico.\u00a0<\/p>\n<p>Grande parte das pesquisas s\u00e3o desenvolvidas pela Universidade Federal dos Vales do Jequitinhonha e Mucuri (UFVJM) na pr\u00f3pria regi\u00e3o. Uma delas \u00e9 conduzida pelo professor do curso de Engenharia H\u00eddrica, Alexandre Sylvio da Costa, cujo objetivo \u00e9 reaproveitar o rejeito da minera\u00e7\u00e3o do l\u00edtio para produzir fertilizantes.\u00a0<\/p>\n<p>\u201cEnt\u00e3o, muitas vezes, aquele rejeito que para a empresa n\u00e3o tem valor, para outros processos, principalmente agricultura, pode ter um grande valor agregado. Estamos partindo para a etapa de campo, que vai ser desenvolvida l\u00e1 na regi\u00e3o com os produtores que produzem eucalipto para fornecer para a pr\u00f3pria opera\u00e7\u00e3o do l\u00edtio&#8221;, explica Alexandre.<\/p>\n<p>Al\u00e9m disso, pesquisadores da universidade tamb\u00e9m trabalham em um projeto voltado para a cria\u00e7\u00e3o de baterias de l\u00edtio, uma das principais utiliza\u00e7\u00f5es do min\u00e9rio na ind\u00fastria de tecnologia atualmente.\u00a0<\/p>\n<p>\u201cA nossa ideia \u00e9 justamente criar tecnologias nacionais que possam entrar para a cadeia final\u00edstica desses produtos. Ter pessoas bem formadas nessa \u00e1rea \u00e9 importante para que a gente n\u00e3o perca esse \u2018trem\u2019\u201d, afirma o professor do Instituto de Ci\u00eancia, Engenharia e Tecnologia da UFVJM, Douglas Santos Monteiro.\u00a0<\/p>\n<p><strong>Investimentos verdes na cadeia do l\u00edtio\u00a0<\/strong><\/p>\n<p>Desde a implementa\u00e7\u00e3o do Vale do L\u00edtio, em 2023, foram atra\u00eddos R$ 6,9 bilh\u00f5es em investimentos privados, com previs\u00e3o de cerca de 6 mil empregos gerados. Dentre os aportes recentes est\u00e1\u00a0 o\u00a0<u>investimento de R$ 220 milh\u00f5es da empresa indiana Altman na Companhia Brasileira de L\u00edtio (CBL)<\/u>\u00a0para a amplia\u00e7\u00e3o das opera\u00e7\u00f5es da planta de refinaria da empresa localizada em Divisa Alegre, no Norte de Minas.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Relacionadas Neste s\u00e1bado (9\/5), o projeto\u00a0Vale do L\u00edtio, iniciativa do\u00a0Governo de Minas\u00a0para estabelecer o estado como protagonista na cadeia de valor do l\u00edtio, completa tr\u00eas anos. Desde o lan\u00e7amento na Nasdaq, maior bolsa de valores do mundo, em Nova Iorque, nos Estados Unidos, a a\u00e7\u00e3o tamb\u00e9m promoveu o avan\u00e7o econ\u00f4mico de munic\u00edpios da regi\u00e3o em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-49820","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=49820"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49820\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=49820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=49820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=49820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}