{"id":49832,"date":"2026-05-10T07:54:39","date_gmt":"2026-05-10T10:54:39","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/10\/prefeitura-de-joao-pessoa-ganha-premio-selo-de-merito-na-area-de-habitacao-social-pelo-4o-ano-consecutivo\/"},"modified":"2026-05-10T07:54:39","modified_gmt":"2026-05-10T10:54:39","slug":"prefeitura-de-joao-pessoa-ganha-premio-selo-de-merito-na-area-de-habitacao-social-pelo-4o-ano-consecutivo","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/10\/prefeitura-de-joao-pessoa-ganha-premio-selo-de-merito-na-area-de-habitacao-social-pelo-4o-ano-consecutivo\/","title":{"rendered":"Prefeitura de Jo\u00e3o Pessoa ganha pr\u00eamio \u2018Selo de M\u00e9rito\u2019 na \u00e1rea de habita\u00e7\u00e3o social pelo 4\u00ba ano consecutivo"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A Prefeitura de Jo\u00e3o Pessoa ganhou, pelo quarto ano consecutivo, o pr\u00eamio nacional \u2018Selo de M\u00e9rito\u2019 na \u00e1rea de habita\u00e7\u00e3o social, concedido pela Associa\u00e7\u00e3o Brasileira de Cohabs e Agentes P\u00fablicos de Habita\u00e7\u00e3o (ABC) e pelo F\u00f3rum Nacional de Secretarias de Habita\u00e7\u00e3o e Desenvolvimento Urbano (FNSHDU). Neste ano, o reconhecimento foi concedido ao programa \u2018Construindo Inclus\u00e3o\u2019, desenvolvido pela gest\u00e3o municipal com foco na promo\u00e7\u00e3o da habita\u00e7\u00e3o de interesse social e inclus\u00e3o das fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><\/figure>\n<figure class=\"wp-block-image size-full\"><\/figure>\n<\/figure>\n<p>Segundo a secret\u00e1ria de Habita\u00e7\u00e3o Social de Jo\u00e3o Pessoa, Socorro Gadelha, o programa habitacional da Prefeitura vai al\u00e9m da constru\u00e7\u00e3o de moradias, atuando tamb\u00e9m na inclus\u00e3o social, regulariza\u00e7\u00e3o fundi\u00e1ria, recupera\u00e7\u00e3o de im\u00f3veis e qualifica\u00e7\u00e3o profissional das fam\u00edlias atendidas. Ela destacou que, nos \u00faltimos quatro anos, a Semhab acumulou sete premia\u00e7\u00f5es com projetos como \u2018Cuidar do Lar\u2019, o Residencial H\u00e9lio Miguel da Silva, o Residencial Dubai e iniciativas de regulariza\u00e7\u00e3o fundi\u00e1ria.<\/p>\n<p>\u201cCom mais esse pr\u00eamio n\u00f3s somos tetracampe\u00f5es e \u00e9 um reconhecimento ao programa habitacional que desenvolvemos aqui em Jo\u00e3o Pessoa, que \u00e9 voltado para a inclus\u00e3o social. Ele \u00e9 amplo e n\u00e3o se restringe a obras de \u2018pedra e cal\u2019, mas \u00e9 um instrumento de transforma\u00e7\u00e3o na vida das fam\u00edlias atendidas, oferecendo uma nova perspectiva e uma qualidade de vida melhor atrav\u00e9s da inclus\u00e3o social\u201d, destacou a secret\u00e1ria.<\/p>\n<p>A premia\u00e7\u00e3o ser\u00e1 entregue durante a 73\u00aa edi\u00e7\u00e3o do F\u00f3rum Nacional de Habita\u00e7\u00e3o de Interesse Social, que acontece entre os dias 13 e 15 de maio, no Recife (PE). O evento re\u00fane representantes de estados, munic\u00edpios, Governo Federal, especialistas e entidades ligadas ao setor habitacional para discutir pol\u00edticas p\u00fablicas e solu\u00e7\u00f5es voltadas \u00e0 moradia digna no Brasil.<\/p>\n<p>\u201cO pr\u00eamio tamb\u00e9m \u00e9 um incentivo para seguirmos avan\u00e7ando na constru\u00e7\u00e3o de novas unidades habitacionais, na recupera\u00e7\u00e3o de im\u00f3veis e na garantia da posse legal das moradias. Al\u00e9m disso, desenvolvemos a\u00e7\u00f5es sociais, cursos de capacita\u00e7\u00e3o e qualifica\u00e7\u00e3o profissional, promovendo gera\u00e7\u00e3o de emprego e renda para as fam\u00edlias beneficiadas. Essa \u00e9 a recomenda\u00e7\u00e3o do prefeito Leo Bezerra, que entende que a moradia \u00e9 o porto seguro de uma fam\u00edlia e que a fun\u00e7\u00e3o da gest\u00e3o p\u00fablica \u00e9 proporcionar a essas pessoas os meios necess\u00e1rios para que elas tenham um futuro melhor\u201d, ressaltou Socorro Gadelha.<\/p>\n<p>O secret\u00e1rio executivo de Habita\u00e7\u00e3o Social de Jo\u00e3o Pessoa, Beto Pirulito, afirmou que o reconhecimento nacional demonstra a prioridade dada ao setor habitacional pela gest\u00e3o municipal. \u201cReceber o Selo de M\u00e9rito pelo quarto ano seguido comprova a seriedade e o compromisso da Prefeitura de Jo\u00e3o Pessoa com a habita\u00e7\u00e3o social. Desenvolvemos um programa amplo, que atua desde a constru\u00e7\u00e3o de novas moradias at\u00e9 a\u00e7\u00f5es sociais e de regulariza\u00e7\u00e3o fundi\u00e1ria e promo\u00e7\u00e3o de cursos profissionalizantes, sempre com o objetivo de promover inclus\u00e3o social e mais qualidade de vida para a popula\u00e7\u00e3o\u201d, afirmou.<\/p>\n<p><strong>F\u00f3rum Nacional de Habita\u00e7\u00e3o de Interesse Social 2026<\/strong> \u2013 A 73\u00aa edi\u00e7\u00e3o do f\u00f3rum, realizado pela ABC e pelo FNSHDU, vai acontecer no Audit\u00f3rio Cais do Sert\u00e3o \u2013 Armaz\u00e9m 10, no Recife Antigo, pr\u00f3ximo ao Marco Zero, no per\u00edodo de 13 a 15 de maio. O evento vai ter a presen\u00e7a de especialistas da sociedade civil e representantes de estados e munic\u00edpios e do Governo Federal, atrav\u00e9s do Minist\u00e9rio das Cidades e da Caixa Econ\u00f4mica Federal.<\/p>\n<p>O f\u00f3rum tem como p\u00fablico-alvo gestores p\u00fablicos e equipes t\u00e9cnicas das \u00e1reas de habita\u00e7\u00e3o e regulariza\u00e7\u00e3o fundi\u00e1ria de todos os estados brasileiros e dos munic\u00edpios com popula\u00e7\u00e3o de mais de 100 mil habitantes, t\u00e9cnicos e dirigentes dos \u00f3rg\u00e3os afins do Governo Federal e tamb\u00e9m empres\u00e1rios e membros da sociedade civil e demais pessoas interessadas no tema.<\/p>\n<p>O principal objetivo \u00e9 promover o debate sobre os rumos da pol\u00edtica habitacional no Brasil, compartilhando informa\u00e7\u00f5es sobre planos e programas governamentais. Tamb\u00e9m deve fortalecer a interlocu\u00e7\u00e3o entre os agentes p\u00fablicos de Estados, Munic\u00edpios, do Governo Federal e do setor produtivo. Al\u00e9m da troca de experi\u00eancias sobre as pr\u00e1ticas do setor, bem como debater sobre os desafios, papeis e possibilidades de atua\u00e7\u00e3o de cada ente federado, para o fortalecimento da habita\u00e7\u00e3o de interesse social no Brasil.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Jo\u00e3o Pessoa ganhou, pelo quarto ano consecutivo, o pr\u00eamio nacional \u2018Selo de M\u00e9rito\u2019 na \u00e1rea de habita\u00e7\u00e3o social, concedido pela Associa\u00e7\u00e3o Brasileira de Cohabs e Agentes P\u00fablicos de Habita\u00e7\u00e3o (ABC) e pelo F\u00f3rum Nacional de Secretarias de Habita\u00e7\u00e3o e Desenvolvimento Urbano (FNSHDU). Neste ano, o reconhecimento foi concedido ao programa \u2018Construindo Inclus\u00e3o\u2019, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-49832","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=49832"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49832\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=49832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=49832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=49832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}