{"id":49906,"date":"2026-05-12T01:54:52","date_gmt":"2026-05-12T04:54:52","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/12\/procon-jp-notifica-empresas-com-debito-oriundo-de-multa-administrativa-para-oportunidade-de-regularizacao\/"},"modified":"2026-05-12T01:54:52","modified_gmt":"2026-05-12T04:54:52","slug":"procon-jp-notifica-empresas-com-debito-oriundo-de-multa-administrativa-para-oportunidade-de-regularizacao","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/12\/procon-jp-notifica-empresas-com-debito-oriundo-de-multa-administrativa-para-oportunidade-de-regularizacao\/","title":{"rendered":"Procon-JP notifica empresas com d\u00e9bito oriundo de multa administrativa para oportunidade de regulariza\u00e7\u00e3o"},"content":{"rendered":"<p><\/p>\n<div>\n<p>O Procon de Jo\u00e3o Pessoa est\u00e1 notificando as empresas com d\u00e9bitos oriundos de multas administrativas para oportunidade de regulariza\u00e7\u00e3o das d\u00edvidas pendentes no sistema de controle da Secretaria e cujos boletos encontram-se com o prazo de vencimento expirado.<\/p>\n<p>O secret\u00e1rio de Prote\u00e7\u00e3o e Defesa do Consumidor, Junior Pires, adianta que a notifica\u00e7\u00e3o \u00e0s empresas tem por objetivo conceder uma \u00faltima oportunidade para a regulariza\u00e7\u00e3o volunt\u00e1ria das pend\u00eancias financeiras antes que os respectivos processos administrativos sejam encaminhados \u00e0 Procuradoria Geral do Munic\u00edpio para fins de inscri\u00e7\u00e3o em d\u00edvida ativa.<\/p>\n<p>O titular do Procon-JP explica que a inscri\u00e7\u00e3o em d\u00edvida ativa ensejar\u00e1 em cobran\u00e7a judicial atrav\u00e9s de execu\u00e7\u00e3o fiscal e com incid\u00eancia de encargos legais, custas processuais e honor\u00e1rios advocat\u00edcios, al\u00e9m de poss\u00edveis restri\u00e7\u00f5es junto aos \u00f3rg\u00e3os de prote\u00e7\u00e3o ao cr\u00e9dito.<\/p>\n<p><strong>Quinze dias<\/strong> \u2013 As empresas notificadas t\u00eam um prazo de 15 dias para uma resposta ap\u00f3s o recebimento do documento. Junior Pires informa que a viabiliza\u00e7\u00e3o da quita\u00e7\u00e3o dos d\u00e9bitos ser\u00e1 facilitada atrav\u00e9s de benef\u00edcios, como desconto de 10%. \u201cAs empresas que procederem \u00e0 regulariza\u00e7\u00e3o dos d\u00e9bitos poder\u00e3o fazer jus ao desconto de 10% sobre o valor da multa administrativa, nos termos da Lei Municipal no 12.963\/2015\u201d.<\/p>\n<p>Outro benef\u00edcio citado pelo secret\u00e1rio fala das condi\u00e7\u00f5es de pagamento: \u201cAlternativamente, o interessado poder\u00e1 pleitear outras condi\u00e7\u00f5es de pagamento, observando-se os crit\u00e9rios e requisitos estabelecidos na Lei Municipal no 15.044\/2023\u201d.<\/p>\n<p><strong>Novas guias<\/strong> \u2013 Para a emiss\u00e3o de novas guias de pagamento ou para o protocolo de pedidos de parcelamento, a empresa dever\u00e1 entrar em contato com o setor financeiro do Procon\/JP ou comparecer \u00e0 sede administrativa, situada na Avenida Dom Pedro I, 382, Centro.<\/p>\n<p><strong>Atendimentos do Procon-JP<\/strong><\/p>\n<p>Sede:Avenida Pedro I,n\u00ba 382, Tambi\u00e1, das 8h \u00e0s 17h (distribui\u00e7\u00e3o de fichas entre 8h e 16h30)<\/p>\n<p>Telefone: 0800 083 2015;<\/p>\n<p>Whats Geral: (83) 98665-0179;<\/p>\n<p>WhatsApp Transporte p\u00fablico:(83) 98873-9976;<\/p>\n<p>Instagram: @procon_jp;<\/p>\n<p>Site: procon.joaopessoa.pb.gov.br.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Procon de Jo\u00e3o Pessoa est\u00e1 notificando as empresas com d\u00e9bitos oriundos de multas administrativas para oportunidade de regulariza\u00e7\u00e3o das d\u00edvidas pendentes no sistema de controle da Secretaria e cujos boletos encontram-se com o prazo de vencimento expirado. O secret\u00e1rio de Prote\u00e7\u00e3o e Defesa do Consumidor, Junior Pires, adianta que a notifica\u00e7\u00e3o \u00e0s empresas tem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-49906","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=49906"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49906\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=49906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=49906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=49906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}