{"id":49946,"date":"2026-05-12T20:49:36","date_gmt":"2026-05-12T23:49:36","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/12\/joao-pessoa-sera-a-capital-nacional-da-vela-ao-receber-o-campeonato-brasileiro-de-hobie-cat\/"},"modified":"2026-05-12T20:49:36","modified_gmt":"2026-05-12T23:49:36","slug":"joao-pessoa-sera-a-capital-nacional-da-vela-ao-receber-o-campeonato-brasileiro-de-hobie-cat","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/05\/12\/joao-pessoa-sera-a-capital-nacional-da-vela-ao-receber-o-campeonato-brasileiro-de-hobie-cat\/","title":{"rendered":"Jo\u00e3o Pessoa ser\u00e1 a capital nacional da vela ao receber o Campeonato Brasileiro de Hobie Cat"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Entre os dias 11 e 17 de outubro deste ano, Jo\u00e3o Pessoa se transformar\u00e1 na capital nacional da vela, com a realiza\u00e7\u00e3o do Campeonato Brasileiro de Hobie Cat (Brascat) 2026, na praia do Cabo Branco. A competi\u00e7\u00e3o atrair\u00e1 um p\u00fablico estimado de mais de 100 velejadores e 50 embarca\u00e7\u00f5es, mais de 200 participantes entre competidores e familiares, al\u00e9m de turistas que acompanham competi\u00e7\u00f5es esportivas promovidas na cidade.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><\/figure>\n<\/figure>\n<p>Nesta ter\u00e7a-feira (12), os organizadores do campeonato fizeram uma visita ao secret\u00e1rio de Turismo da Capital, Daniel Rodrigues, para contextualizar a import\u00e2ncia da competi\u00e7\u00e3o, afirmando que a op\u00e7\u00e3o pela cidade como sede da prova reafirma o protagonismo crescente de Jo\u00e3o Pessoa no cen\u00e1rio n\u00e1utico brasileiro. \u201cReceber um campeonato desse porte fortalece ainda mais a relev\u00e2ncia da regi\u00e3o, colocando Jo\u00e3o Pessoa em evid\u00eancia no calend\u00e1rio nacional\u201d, ressaltou o secret\u00e1rio.<\/p>\n<p>Para Daniel Rodrigues, Jo\u00e3o Pessoa vem se tornando uma das cidades mais procuradas para a realiza\u00e7\u00e3o de competi\u00e7\u00f5es ao ar livre, pelas condi\u00e7\u00f5es clim\u00e1ticas, mas, sobretudo, pela estrutura da orla mar\u00edtima, destacando a acessibilidade, mobilidade e seguran\u00e7a. \u201cJo\u00e3o Pessoa j\u00e1 se destaca no calend\u00e1rio nacional de corridas de rua, ciclismo, nata\u00e7\u00e3o e, agora, no mar, fruto da pol\u00edtica p\u00fablica que coloca no cen\u00e1rio nacional uma cidade esportiva, onde se pode praticar qualquer tipo de esporte ao ar livre\u201d, enfatizou.\u00ad<\/p>\n<p>De acordo com os organizadores, o evento atrair\u00e1 atletas de diversos estados, movimentando o turismo esportivo, a economia local e promovendo um interc\u00e2mbio entre velejadores experientes e novos talentos que despontam no Pa\u00eds. O Hobie Cat \u00e9 um tipo popular de catamar\u00e3 de praia (barco \u00e0 vela com dois cascos) pequeno, leve e veloz, amplamente utilizado para recrea\u00e7\u00e3o, turismo e regatas.<\/p>\n<p>Conforme a organiza\u00e7\u00e3o da competi\u00e7\u00e3o, a Para\u00edba \u00e9 um dos melhores destinos do Brasil para a pr\u00e1tica da vela e do Hobie Cat, por ter ventos constantes, mar calmo e \u00e1guas cristalinas. \u201cA escolha da Praia de Cabo Branco como sede do Brascat 2026 n\u00e3o \u00e9 por acaso \u2013 \u00e9 uma decis\u00e3o estrat\u00e9gica que une condi\u00e7\u00f5es ideais de regata, visibilidade e experi\u00eancia\u201d, explicou Igor Guimar\u00e3es, diretor de Vela do Iate Clube da Para\u00edba.<\/p>\n<p>Ainda participaram do encontro o secret\u00e1rio de Juventude, Esporte e Recrea\u00e7\u00e3o da Capital (Sejer), Jo\u00e3ozinho Neto; o secret\u00e1rio executivo Juliano Sucupira; Nara Rocha, capit\u00e3 de flotilha de Hobie Cat; Milton Pessoa, capit\u00e3o de flotilha de Hobie Cat 16; e os velejadores Savigny Cunha Lima e Juli\u00e3o Ferreira Filho, membros da Comiss\u00e3o Organizadora do Brascat 2026.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entre os dias 11 e 17 de outubro deste ano, Jo\u00e3o Pessoa se transformar\u00e1 na capital nacional da vela, com a realiza\u00e7\u00e3o do Campeonato Brasileiro de Hobie Cat (Brascat) 2026, na praia do Cabo Branco. A competi\u00e7\u00e3o atrair\u00e1 um p\u00fablico estimado de mais de 100 velejadores e 50 embarca\u00e7\u00f5es, mais de 200 participantes entre competidores [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-49946","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=49946"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49946\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=49946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=49946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=49946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}