{"id":52643,"date":"2026-07-15T12:31:39","date_gmt":"2026-07-15T15:31:39","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/07\/15\/fumace-percorre-cinco-bairros-nesta-quarta-feira-15-cgnoticias\/"},"modified":"2026-07-15T12:31:39","modified_gmt":"2026-07-15T15:31:39","slug":"fumace-percorre-cinco-bairros-nesta-quarta-feira-15-cgnoticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/07\/15\/fumace-percorre-cinco-bairros-nesta-quarta-feira-15-cgnoticias\/","title":{"rendered":"Fumac\u00ea percorre cinco bairros nesta quarta-feira (15) \u2013 CGNot\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>O combate ao mosquito <em>Aedes aegypti<\/em>, transmissor de arboviroses como Dengue, Zika e Chikungunya, ser\u00e1 refor\u00e7ado nesta quarta-feira (15), em cinco bairros de Campo Grande: Amambai, Lageado, Los Angeles, S\u00e3o Conrado e Tarum\u00e3.<\/p>\n<p>As equipes da Coordenadoria de Controle de Endemias Vetoriais (CCEV) da Secretaria Municipal de Sa\u00fade (Sesau) circular\u00e3o das 16h \u00e0s 22h, com o uso do servi\u00e7o de borrifa\u00e7\u00e3o ultra baixo volume (UBV), conhecido como fumac\u00ea.<\/p>\n<p>Para uma maior efic\u00e1cia do inseticida, \u00e9 necess\u00e1rio que o morador abra portas e janelas, permitindo que o produto alcance os locais onde h\u00e1 maior probabilidade de estarem os mosquitos.<\/p>\n<p>Os servi\u00e7os podem ser adiados ou at\u00e9 mesmo cancelados em caso de chuva, ventos fortes ou neblina, condi\u00e7\u00f5es clim\u00e1ticas que comprometem a aplica\u00e7\u00e3o do inseticida.<\/p>\n<p>O inseticida age principalmente sobre os mosquitos adultos, especialmente as f\u00eameas, respons\u00e1veis pela transmiss\u00e3o das doen\u00e7as. Ainda assim, outras esp\u00e9cies podem ser atingidas, por isso a aplica\u00e7\u00e3o \u00e9 realizada de forma criteriosa.<\/p>\n<p><strong>Confira o itiner\u00e1rio:<\/strong><\/p>\n<figure class=\"wp-block-image size-full\"><\/figure>\n<p><em>#ParaTodosVerem: A imagem em destaque mostra uma equipe do fumac\u00ea circulando, dentro das mat\u00e9ria h\u00e1 uma tabela com o itiner\u00e1rio das equipes desta quarta-feira (15)<\/em><\/p>\n<\/div>\n<p><script async defer async defer src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=1#xfbml=1&amp;version=v3.2\" id=\"prefeitura-campogrande-script-facebook-sdk-js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O combate ao mosquito Aedes aegypti, transmissor de arboviroses como Dengue, Zika e Chikungunya, ser\u00e1 refor\u00e7ado nesta quarta-feira (15), em cinco bairros de Campo Grande: Amambai, Lageado, Los Angeles, S\u00e3o Conrado e Tarum\u00e3. As equipes da Coordenadoria de Controle de Endemias Vetoriais (CCEV) da Secretaria Municipal de Sa\u00fade (Sesau) circular\u00e3o das 16h \u00e0s 22h, com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-52643","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52643"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52643\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}