{"id":52644,"date":"2026-07-15T12:33:39","date_gmt":"2026-07-15T15:33:39","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/07\/15\/botafogo-x-santos-altera-transito-no-entorno-do-nilton-santos-nesta-quinta-feira-prefeitura-da-cidade-do-rio-de-janeiro\/"},"modified":"2026-07-15T12:33:39","modified_gmt":"2026-07-15T15:33:39","slug":"botafogo-x-santos-altera-transito-no-entorno-do-nilton-santos-nesta-quinta-feira-prefeitura-da-cidade-do-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/07\/15\/botafogo-x-santos-altera-transito-no-entorno-do-nilton-santos-nesta-quinta-feira-prefeitura-da-cidade-do-rio-de-janeiro\/","title":{"rendered":"Botafogo x Santos altera tr\u00e2nsito no entorno do Nilton Santos nesta quinta-feira &#8211; Prefeitura da Cidade do Rio de Janeiro"},"content":{"rendered":"<p><\/p>\n<div>\n                     CET-Rio inicia bloqueios de vias no Engenho de Dentro a partir das 16h30 para partida do Brasileir\u00e3o                  <\/div>\n<div>\n<p>A CET-Rio ir\u00e1 implantar uma opera\u00e7\u00e3o de tr\u00e2nsito nesta quinta-feira (16\/07) para o jogo entre Botafogo e Santos, pelo Campeonato Brasileiro. A partida acontece \u00e0s 19h30 no Est\u00e1dio Nilton Santos, em Engenho de Dentro. A partir das 16h30, haver\u00e1 interdi\u00e7\u00f5es ao tr\u00e2nsito de ve\u00edculos na regi\u00e3o. A opera\u00e7\u00e3o contar\u00e1 com agentes da CET-Rio, apoiadores de tr\u00e1fego, ve\u00edculos operacionais e motocicletas. O efetivo atuar\u00e1 na seguran\u00e7a vi\u00e1ria, na fluidez do tr\u00e2nsito e na manuten\u00e7\u00e3o dos cruzamentos livres, bem como na orienta\u00e7\u00e3o a pedestres, torcedores e motoristas. T\u00e9cnicos da CET-Rio, situados no Centro de Opera\u00e7\u00f5es e Resili\u00eancia (COR-Rio), ir\u00e3o monitorar toda a movimenta\u00e7\u00e3o por meio de c\u00e2meras. Se necess\u00e1rio, ser\u00e3o feitos ajustes na programa\u00e7\u00e3o semaf\u00f3rica com o objetivo de garantir boas condi\u00e7\u00f5es vi\u00e1rias.<\/p>\n<\/div>\n<div>\n<p dir=\"ltr\"><strong>Interdi\u00e7\u00f5es<\/strong><\/p>\n<p dir=\"ltr\"><strong>Das 16h30 \u00e0s 23h30:<\/strong><\/p>\n<p dir=\"ltr\">\u2013\u00a0 Rua Dr. Padilha, entre a rua Arquias Cordeiro e a rua Piau\u00ed.<\/p>\n<p><strong>Das 21h \u00e0s 23h30:<\/strong><\/p>\n<p dir=\"ltr\">\u2013 Rua Dr. Padilha, entre a rua Piau\u00ed e a rua das Oficinas;<\/p>\n<p dir=\"ltr\">\u2013 Rua Jos\u00e9 dos Reis entre a rua das Oficinas e a Rua Bento Gon\u00e7alves;<\/p>\n<p dir=\"ltr\">\u2013 Rua da Aboli\u00e7\u00e3o, entre a Rua Afonso Ferreira e a Rua Jos\u00e9 dos Reis;<\/p>\n<p dir=\"ltr\">\u2013 Rua Afonso Ferreira, sentido rua Jos\u00e9 dos Reis, entre a rua Ben\u00edcio de Abreu e a rua da Aboli\u00e7\u00e3o.<\/p>\n<p dir=\"ltr\"><strong>Acesso \u00e0 Linha Amarela, sentido Avenida Brasil<\/strong><\/p>\n<p dir=\"ltr\"><strong>Das 16h30 at\u00e9 0h30 do dia seguinte (17\/07):<\/strong><\/p>\n<p dir=\"ltr\">O acesso \u00e0 Linha Amarela, sentido Avenida Brasil\/Fund\u00e3o, poder\u00e1 ser realizado pela rua das Oficinas, a partir do cruzamento com a rua Jos\u00e9 dos Reis, sob o viaduto Jornalista Armando Nogueira.<\/p>\n<p dir=\"ltr\"><strong>Moradores do entorno<\/strong><\/p>\n<p dir=\"ltr\">\u00a0O acesso dos ve\u00edculos de moradores das imedia\u00e7\u00f5es do est\u00e1dio ser\u00e1 feito mediante apresenta\u00e7\u00e3o do comprovante de resid\u00eancia.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CET-Rio inicia bloqueios de vias no Engenho de Dentro a partir das 16h30 para partida do Brasileir\u00e3o A CET-Rio ir\u00e1 implantar uma opera\u00e7\u00e3o de tr\u00e2nsito nesta quinta-feira (16\/07) para o jogo entre Botafogo e Santos, pelo Campeonato Brasileiro. A partida acontece \u00e0s 19h30 no Est\u00e1dio Nilton Santos, em Engenho de Dentro. A partir das 16h30, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52644","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52644"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52644\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}